{"id":12071,"date":"2019-10-11T17:00:25","date_gmt":"2019-10-11T17:00:25","guid":{"rendered":"http:\/\/www.iri.edu.ar\/?p=12071"},"modified":"2023-09-06T13:32:49","modified_gmt":"2023-09-06T16:32:49","slug":"moreno-y-la-incertidumbre","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2019\/10\/11\/moreno-y-la-incertidumbre\/","title":{"rendered":"Moreno y la incertidumbre"},"content":{"rendered":"<p><span style=\"color: #000000;\">La incertidumbre de lo que est\u00e1 aconteciendo en Ecuador bien se podr\u00eda resumir en la entrevista que realiz\u00f3 el presidente Lenin Moreno el 9 de octubre de 2019 en la cadena multinacional CNN. Las preguntas formuladas por el entrevistador no generaban una respuesta clara del mandatario, \u00e9l afirmaba que se estaban realizando conversaciones con la dirigencia ind\u00edgena -a pesar que la CONAIE negaba tal hecho-, que las marchas eran pac\u00edficas y que el vandalismo causado era ocasionado por bandas criminales que respond\u00edan al ex presidente, <strong>Rafael Correa<\/strong>.<\/span><\/p>\n<p><span style=\"color: #000000;\">La parsimonia de Moreno en todas sus intervenciones no refleja lo que acontece en el pa\u00eds. El cambio de sede administrativa de Quito a Guayaquil no es poca cosa, que el centro de Quito es un campo de batalla tampoco. De hecho, si utilizamos el concepto de estado fallido, Ecuador en estos momentos es un estado fallido o por lo menos fr\u00e1gil. \u00bfPor qu\u00e9? Por las siguientes caracter\u00edsticas:<\/span><\/p>\n<p><span style=\"color: #000000;\">El gobierno no controla todo el territorio, provincias enteras con mayor\u00eda poblacional ind\u00edgena est\u00e1n siendo ocupadas, tal es el caso de la provincia de Chimborazo.<\/span><\/p>\n<p><span style=\"color: #000000;\">La ciudad de Ambato, un centro industrial del pa\u00eds, est\u00e1 declarado en emergencia por falta de agua y otros insumos b\u00e1sicos producto de las protestas. El estado es incapaz de suministrar insumos b\u00e1sicos a todo el territorio.<\/span><\/p>\n<p><span style=\"color: #000000;\">Producto del caos, se presentan altos \u00edndices de criminalidad, reflejado en los grandes saqueos que se han realizado en las ciudades del pa\u00eds.<\/span><\/p>\n<p><span style=\"color: #000000;\">El gobierno popularmente es d\u00e9bil y su autoridad la ejerce por la fuerza. De hecho, si el monopolio de la fuerza no se mantuviera en manos del gobierno nacional, estar\u00edamos comparando la situaci\u00f3n ecuatoriana con otros pa\u00edses menos afortunados como Libia o Siria. Las fuerzas armadas y la polic\u00eda en estos momentos son la garant\u00eda que legitima al gobierno, al igual que los grupos empresariales que est\u00e1n a favor de las medidas econ\u00f3micas, no en vano el cambio de sede de Quito a Guayaquil, ciudad que se caracteriza por ser el centro financiero y donde se localizan los principales grupos econ\u00f3micos del Ecuador. Desde luego, hay que destacar la participaci\u00f3n y el apoyo al r\u00e9gimen de ciertos sectores de la sociedad que se han definido como \u201cclase media\u201d, una clase que no quiere a Moreno pero que lo defiende por la \u201cdemocracia\u201d y porque cree que el corre\u00edsmo est\u00e1 organizando todo el caos.<\/span><\/p>\n<p><span style=\"color: #000000;\">Despu\u00e9s de presentar estos argumentos formularia la siguiente pregunta: \u00bfPor qu\u00e9 est\u00e1 sucediendo esto? La respuesta es muy larga, pero se tratar\u00e1 de resumir de la mejor manera posible.<\/span><\/p>\n<p><span style=\"color: #000000;\">La posesi\u00f3n de <strong>Moreno<\/strong> tras ganar las elecciones no fue normal, los sectores de la sociedad que se han definido como \u201cclase media\u201d, que ahora abogan por \u201cla democracia\u201d, realizaron marchas por un presunto fraude, pero la tensi\u00f3n fue aminorando con el pasar de los d\u00edas.<\/span><\/p>\n<p><span style=\"color: #000000;\">A pesar del apoyo inicial del antiguo r\u00e9gimen, meses despu\u00e9s el gobierno rompi\u00f3 lazos con el corre\u00edsmo, m\u00e1s a\u00fan cuando el ex vicepresidente <strong>Jorge Glas<\/strong> fue encarcelado por delitos de corrupci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Sin una base pol\u00edtica, <strong>Moreno<\/strong> busc\u00f3 nuevos aliados, el gabinete que conform\u00f3 estaba compuesto por los miembros del partido pol\u00edtico Alianza Pa\u00eds -quienes decidieron permanecer junto al r\u00e9gimen, los dem\u00e1s formar\u00edan el movimiento Revoluci\u00f3n Ciudadana de tendencia correista-. Otros personajes de la pol\u00edtica tambi\u00e9n integraron el r\u00e9gimen, algunos relacionados con un partido pol\u00edtico que es fuerte en la regi\u00f3n Costa.<\/span><\/p>\n<p><span style=\"color: #000000;\">A favor de Moreno se podr\u00eda mencionar que encontr\u00f3 un Estado sobre endeudado, con d\u00e9ficit financiero y con pocas l\u00edneas de cr\u00e9dito por el alto riesgo pa\u00eds. La \u201cmesa servida\u201d que proclam\u00f3 <strong>Correa<\/strong> en su \u00faltimo discurso como presidente, haciendo referencia a la econom\u00eda del pa\u00eds, no se compaginaba con los datos de la hacienda p\u00fablica. El gobierno actual emprendi\u00f3 reformas econ\u00f3micas, como despidos masivos (10.000 trabajadores p\u00fablicos perdieron sus puestos de trabajo), reducci\u00f3n del gasto p\u00fablico con la intenci\u00f3n de mantener un super\u00e1vit primario, entre otras cosas. Las reformas no bastaron para equilibrar el d\u00e9ficit y la cuenta corriente, por tal motivo el gobierno decidi\u00f3 acudir al FMI.<\/span><\/p>\n<p><span style=\"color: #000000;\">Las peticiones que realiza el FMI al pa\u00eds endeudado son poco claras frente a la opini\u00f3n p\u00fablica. No se puede determinar si este organismo exigi\u00f3 la eliminaci\u00f3n de los subsidios de los combustibles en Ecuador, que representa aproximadamente 1.400 millones de d\u00f3lares anuales. Pero el gobierno ecuatoriano lleg\u00f3 a un acuerdo con el FMI para obtener cr\u00e9ditos por m\u00e1s de 4.200 millones de d\u00f3lares, a cambio de reducir el d\u00e9ficit fiscal. Por tal motivo en una cadena nacional el gobierno oficializ\u00f3 las siguientes reformas: un aporte especial de las empresas con ingresos de m\u00e1s de 10 millones de d\u00f3lares al a\u00f1o; un ajuste en el sector p\u00fablico con una baja salarial de hasta un 20% en contratos temporales; una reducci\u00f3n de vacaciones a la mitad, adem\u00e1s, de un aporte con un d\u00eda de salario al mes para los trabajadores p\u00fablicos; y finalmente el fin de los subsidios a los combustibles, un subsidio que se hab\u00eda mantenido por cuatro d\u00e9cadas. El gal\u00f3n de gasolina extra, utilizado por autom\u00f3viles y otros veh\u00edculos medianos, pas\u00f3 de 1.85 d\u00f3lares a 2.30 d\u00f3lares; y el gal\u00f3n de di\u00e9sel, utilizado por maquinaria y transporte pesado, paso de 1.08 d\u00f3lares a 2.27 d\u00f3lares, una subida de m\u00e1s del 120% en las estaciones de servicio.<\/span><\/p>\n<p><span style=\"color: #000000;\">La reacci\u00f3n popular fue m\u00e1s en\u00e9rgica de lo previsto. En un inicio los transportistas, algunos dirigentes vinculados con el corre\u00edsmo, abanderaron la protesta social pero despu\u00e9s de un ataque informativo, donde se se\u00f1alaba la presunta corrupci\u00f3n de algunos sindicalistas, acabaron por mermar este movimiento. Entonces el sector ind\u00edgena, el que tanto hab\u00eda atacado al antiguo gobierno de <strong>Rafael Correa<\/strong>, lider\u00f3 las protestas. Un sector aparentemente \u201cdormido\u201d a causa del corre\u00edsmo renaci\u00f3 de una manera poco esperada. Desde las regiones m\u00e1s olvidadas del pa\u00eds, miles de ind\u00edgenas cerraron las principales v\u00edas de conexi\u00f3n del pa\u00eds, adem\u00e1s otros miles viajaron a la ciudad de Quito. Con apoyo de otros movimientos sociales ligados a la izquierda revolucionaria y el anarquismo rodearon la ciudad capital, obligando al gobierno a trasladar la sede administrativa a Guayaquil. Las grandes manifestaciones no solo llegaron a Quito, otras manifestaciones tambi\u00e9n se instalaron en otras ciudades, incluso se tomaron gobernaciones.<\/span><\/p>\n<p><span style=\"color: #000000;\">Fruto del caos, se produjeron saqueos y destrucci\u00f3n de infraestructura p\u00fablica y privada. El gobierno acus\u00f3 a los dirigentes correistas de propiciar estos hechos vand\u00e1licos. Es un discurso que fue acogido por algunos sectores de la sociedad e incluso se instal\u00f3 en el exterior la consigna de que las personas que apoyan a <strong>Rafael Correa<\/strong> est\u00e1n desestabilizando la democracia. Por tal motivo, m\u00e1s all\u00e1 de las fronteras se puede creer que el antiguo r\u00e9gimen tiene un poder omnipresente, este \u201cenemigo\u201d ha sido sobredimensionado por el gobierno, e incluso ha sido aprovechado por el acusado, es decir, por <strong>Rafael Correa<\/strong>, que en medios internacionales ha culpado al gobierno de acabar con la democracia, enalteci\u00e9ndose como figura pol\u00edtica. La participaci\u00f3n del corre\u00edsmo en las manifestaciones es una realidad, pero es m\u00ednima, incluso si en las protestas ind\u00edgenas y de los otros movimientos sociales un representante del corre\u00edsmo es descubierto, como ya ha ocurrido, es golpeado y retirado a palos.<\/span><\/p>\n<p><span style=\"color: #000000;\">La soluci\u00f3n no radica en enfrentar al antiguo r\u00e9gimen, sino en un futuro di\u00e1logo con los grandes actores de las manifestaciones. Un di\u00e1logo ver\u00eddico y no originado por una mera declaraci\u00f3n. Los efectos de la crisis son desastrosos para la econom\u00eda nacional y principalmente para los seres humanos que participan en las manifestaciones. La violencia, originada por el uso excesivo de la fuerza por parte de la polic\u00eda y los militares, ya ha generado decenas de fallecidos.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Tras siete d\u00edas de las manifestaciones toda la poblaci\u00f3n se adapta a la crisis, por ejemplo, en la ciudad de Quito hay zonas donde existe una libre circulaci\u00f3n, hay transporte, hay locales funcionando y las personas est\u00e1n realizando sus labores de acuerdo a sus posibilidades. En pocas palabras, podes tomar un caf\u00e9 a unas diez cuadras de las manifestaciones, podes ver el humo de las llantas y los disparos de gases lacrim\u00f3genos, como ver en primera fila una revoluci\u00f3n. Pero a pesar de ello la incertidumbre persiste, no se sabe si la normalidad vendr\u00e1 ma\u00f1ana o durar\u00e1 unas semanas m\u00e1s.<\/span><\/p>\n<p><span style=\"color: #000000;\">Para concluir, una solidaridad con el pueblo ind\u00edgena. Un pueblo que ha sufrido de maltratos, de explotaci\u00f3n, de marginalidad y de racismo desde la era colonial. Un pueblo que a pesar de sus adversidades act\u00faa y lucha contra medidas antipopulares que tambi\u00e9n afectan al ciudadano com\u00fan, al ciudadano que por lo general vive con un salario precario y que siente a diario la crisis econ\u00f3mica.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong><em><span style=\"color: #000000;\">Galo Gonzalez Orna <\/span><\/em><\/strong><\/span><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><br \/>\n<span style=\"font-size: 14pt;\"><span style=\"color: #000000; font-size: 12pt;\">Miembro<\/span><\/span><br \/>\n<span style=\"color: #000000;\">Departamento de Am\u00e9rica Latina y el Caribe<\/span><br \/>\n<span style=\"color: #000000;\">IRI &#8211; UNLP<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> <span style=\"color: #000000;\">Mag\u00edster en Relaciones Internacionales de la UNLP.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La incertidumbre de lo que est\u00e1 aconteciendo en Ecuador bien se podr\u00eda resumir en la entrevista que realiz\u00f3 el presidente Lenin Moreno el 9 de octubre de 2019 en la cadena multinacional CNN. Las preguntas formuladas por el entrevistador no generaban una respuesta clara del mandatario, \u00e9l afirmaba que se estaban realizando conversaciones con la [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":11993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[34],"tags":[89,1142],"class_list":["post-12071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones-iri","tag-ecuador","tag-opalatina","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat-150x150.jpg",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat-300x80.jpg",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",600,160,false],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat-272x182.jpg",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",375,100,false],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",720,192,false],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2019\/10\/opiniones_feat.jpg",750,200,false]},"uagb_author_info":{"display_name":"Candela","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/candela\/"},"uagb_comment_info":0,"uagb_excerpt":"La incertidumbre de lo que est\u00e1 aconteciendo en Ecuador bien se podr\u00eda resumir en la entrevista que realiz\u00f3 el presidente Lenin Moreno el 9 de octubre de 2019 en la cadena multinacional CNN. Las preguntas formuladas por el entrevistador no generaban una respuesta clara del mandatario, \u00e9l afirmaba que se estaban realizando conversaciones con la&hellip;","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/12071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=12071"}],"version-history":[{"count":4,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/12071\/revisions"}],"predecessor-version":[{"id":12083,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/12071\/revisions\/12083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/11993"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=12071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=12071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=12071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}