{"id":12827,"date":"2020-01-05T15:44:22","date_gmt":"2020-01-05T15:44:22","guid":{"rendered":"http:\/\/www.iri.edu.ar\/?p=12827"},"modified":"2020-01-05T15:46:13","modified_gmt":"2020-01-05T15:46:13","slug":"a-proposito-de-la-ejecucion-del-general-qasem-soleimani","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2020\/01\/05\/a-proposito-de-la-ejecucion-del-general-qasem-soleimani\/","title":{"rendered":"A prop\u00f3sito de la ejecuci\u00f3n del general Qasem Soleimani"},"content":{"rendered":"<p class=\"ydpa0ceaed5yiv8962314967ydpc95ec6b7MsoNormal\">La ejecuci\u00f3n del general iran\u00ed\u00a0<b>Qasem Soleimani<\/b>\u00a0por parte de las FFAA de los EEUU tiene que ser comprendida como un paso m\u00e1s en la escalada de la tensi\u00f3n entre los Estados Unidos e Ir\u00e1n, desde que en 2015 Washington rompiera unilateralmente el acuerdo nuclear al que Occidente, la ONU y Teher\u00e1n arribaron tras arduas negociaciones.<\/p>\n<p class=\"ydpa0ceaed5yiv8962314967ydpc95ec6b7MsoNormal\">El general\u00a0<b>Soleimani<\/b>\u00a0era la cara visible de la creciente influencia de la Revoluci\u00f3n Isl\u00e1mica en la regi\u00f3n y una pieza clave en la pol\u00edtica exterior iran\u00ed. Este escenario desat\u00f3 una nueva Guerra Fr\u00eda entre Teher\u00e1n y Riad, en la cual Ir\u00e1n (con el activo acompa\u00f1amiento ruso) tiene a muchos pa\u00edses de la regi\u00f3n aline\u00e1ndose a sus intereses: Irak, Siria, L\u00edbano, Yemen, enfrent\u00e1ndose a Arabia Saud\u00ed, Emiratos \u00c1rabes, Qatar (\u00bfnuevamente en su eje tradicional?) e Israel. Una manera brutal de disminuir esa creciente influencia ha sido, por lo tanto, la ejecuci\u00f3n del general\u00a0<b>Soleimani<\/b>.<\/p>\n<p class=\"ydpa0ceaed5yiv8962314967ydpc95ec6b7MsoNormal\">Por otro lado, cabe recordar que el 2020 es a\u00f1o electoral en Estados Unidos. El presidente\u00a0<b>Donald Trump<\/b>\u00a0acaba de llevar a cabo una acci\u00f3n del manual republicano de cara a las elecciones: endurecer las posiciones frente a un enemigo al cual, desde 1979, Washington recurre de manera sistem\u00e1tica. No est\u00e1 de m\u00e1s recordar que junto a Irak y Corea del Norte, Ir\u00e1n es protagonista recurrente del \u201cEje del Mal\u201d.<\/p>\n<p class=\"ydpa0ceaed5yiv8962314967ydpc95ec6b7MsoNormal\">Es ingenuo catalogar a esta ejecuci\u00f3n como una aventura irresponsable de Washington. No lo es. Es una acci\u00f3n meditada y llevada a cabo con frialdad. Una decisi\u00f3n t\u00e1ctica consistente con la estrategia de enfrentar a Ir\u00e1n para borrar su influencia en una regi\u00f3n caliente desde siempre, para la estabilidad global. De all\u00ed que la escalada del precio del petr\u00f3leo, por ejemplo, beneficie a las explotaciones no convencionales en los Estados Unidos y perjudique sensiblemente a China (principal consumidor de lo producido en la regi\u00f3n) y agrave las consecuencias de las sanciones econ\u00f3micas impuestas a Teher\u00e1n, donde en el frente interno el moderado\u00a0<b>Hasan Rohani<\/b>, enfrenta sus propias movilizaciones populares hace m\u00e1s de un mes por el encarecimiento del combustible.<\/p>\n<p class=\"ydpa0ceaed5yiv8962314967ydpc95ec6b7MsoNormal\">Las consecuencias aparecen como dif\u00edciles de mensurar\u00a0en este escenario, donde nuestro pa\u00eds permanece marginado de las decisiones adoptadas por los principales actores de la realidad internacional, pero sabiendo que nuestra respuesta ante la escalada en la crisis desatada condiciona indisimulablemente nuestro futuro inmediato.<\/p>\n<p class=\"ydpa0ceaed5yiv8962314967ydpc95ec6b7MsoNormal\">M\u00e1s all\u00e1 de las especulaciones cortoplacistas, no podemos menos que condenar el acto de fuerza llevado a cabo por los Estados Unidos. Las acciones de Washington encajan (sin forzar en absoluto ninguno de los tipos) en lo que el Derecho Internacional define como \u201cagresi\u00f3n\u201d (resoluci\u00f3n 3314 de 1974), con el agravante de que se llev\u00f3 a cabo en un tercer pa\u00eds (Irak) sin conocimiento del mismo. Estas ejecuciones no son nuevas y a ellas han echado mano en reiteradas ocasiones muchos de los actores: EE.UU. (sin distinciones partidarias, tanto dem\u00f3cratas como republicanos), Reino Unido, Rusia, Turqu\u00eda, Israel, Arabia Saudita, entre otros. Pero hay que llamar a las cosas por su nombre: su repetici\u00f3n no disminuye la gravedad de la violaci\u00f3n de los Derechos Humanos b\u00e1sicos que ellas implican.<\/p>\n<p class=\"ydpa0ceaed5yiv8962314967ydpc95ec6b7MsoNormal\"><b>Las repercusiones son imprevisibles,\u00a0<\/b>aunque dif\u00edcilmente impliquen reacciones sim\u00e9tricas por parte del r\u00e9gimen de los ayatolas (mucho m\u00e1s racional de lo que Occidente lo presenta), pero llegar\u00e1n. Est\u00e1n a la vuelta de la esquina.<b><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ejecuci\u00f3n del general iran\u00ed\u00a0Qasem Soleimani\u00a0por parte de las FFAA de los EEUU tiene que ser comprendida como un paso m\u00e1s en la escalada de la tensi\u00f3n entre los Estados Unidos e Ir\u00e1n, desde que en 2015 Washington rompiera unilateralmente el acuerdo nuclear al que Occidente, la ONU y Teher\u00e1n arribaron tras arduas negociaciones. El [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[35],"tags":[143,135,141,138,137,136,142,140,139],"class_list":["post-12827","post","type-post","status-publish","format-standard","hentry","category-iri-opina","tag-agresion","tag-eeuu","tag-eje-del-mal","tag-guerra","tag-irak","tag-iran","tag-medio-oriente","tag-soleimani","tag-war","entry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"ocean-thumb-m":false,"ocean-thumb-ml":false,"ocean-thumb-l":false,"sow-carousel-default":false,"sow-blog-portfolio":false,"sow-blog-grid":false,"sow-blog-alternate":false},"uagb_author_info":{"display_name":"Juana Alvarez Eiras","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/juana-alvarez-eiras\/"},"uagb_comment_info":0,"uagb_excerpt":"La ejecuci\u00f3n del general iran\u00ed\u00a0Qasem Soleimani\u00a0por parte de las FFAA de los EEUU tiene que ser comprendida como un paso m\u00e1s en la escalada de la tensi\u00f3n entre los Estados Unidos e Ir\u00e1n, desde que en 2015 Washington rompiera unilateralmente el acuerdo nuclear al que Occidente, la ONU y Teher\u00e1n arribaron tras arduas negociaciones. El&hellip;","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/12827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=12827"}],"version-history":[{"count":2,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/12827\/revisions"}],"predecessor-version":[{"id":12829,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/12827\/revisions\/12829"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=12827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=12827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=12827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}