{"id":17857,"date":"2021-03-08T14:20:08","date_gmt":"2021-03-08T14:20:08","guid":{"rendered":"http:\/\/www.iri.edu.ar\/?p=17857"},"modified":"2023-09-06T12:34:21","modified_gmt":"2023-09-06T15:34:21","slug":"8m-dia-internacional-de-las-mujeres","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2021\/03\/08\/8m-dia-internacional-de-las-mujeres\/","title":{"rendered":"8M, D\u00eda Internacional de las mujeres"},"content":{"rendered":"<p style=\"text-align: right;\"><em><span style=\"font-size: 12pt;\">\u201cDejarse dominar por el miedo a sentir y a trabajar al l\u00edmite de la propia capacidad es un lujo que solo pueden permitirse quienes carecen de objetivos, quienes no desean guiar sus propios destinos\u201d<\/span><\/em><\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 12pt;\"><strong>Audre Lorde<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Por nuestras ancestras. Por nuestras abuelas, madres y hermanas. Por todas aquellas que dieron sus vidas para disfrutar de las nuestras. Por todas las que nos faltan. Por las generaciones venideras. Hoy conmemoramos nuestra lucha hist\u00f3rica por la consecuci\u00f3n de los derechos y libertades de nosotras, las mujeres, por el deseo de vivir libres, felices y sin miedo.<\/p>\n<p>Sin lugar a dudas, las resonancias de la lucha y resistencia femenina emprendida desde hace ya m\u00e1s de tres siglos, se han visto reflejadas en la ampliaci\u00f3n de nuestra burbuja de derechos; sin embargo, no podemos dejar de ver que a\u00fan faltan muchos revestimientos del patriarcado por quebrantar en este sistema tan opresivo y represivo hacia las mujeres.<\/p>\n<p>Desde el Abya Yala, diferentes luchas tanto feministas como de mujeres se siguen organizando contra el sistema capitalista heteropatriarcal, racista y clasista en defensa de los derechos sexuales y reproductivos, de las mejores oportunidades laborales y educativas, del derecho a la vida, de los derechos de las comunidades originarias y LGBTIQ+, del medio ambiente, entre muchos otros. Estos movimientos de resistencia nos han dejado en claro que no podemos encomendar nuestros derechos a demagogias; sino, al contrario, debemos seguir organiz\u00e1ndonos, tomando las calles, tejiendo lazos de rebeld\u00eda, resistencia y sororidad, exigiendo justicia por todas las mujeres v\u00edctimas de un sistema que nos violenta en todo momento.<\/p>\n<p>En este sentido, no pueden dejar de mencionarse algunos aspectos fundamentales sobre el 8M. Lo primero es el impacto y trascendencia que tiene dicha conmemoraci\u00f3n en la sociedad. Cada a\u00f1o, el activismo feminista logra poner en manifiesto las condiciones de desigualdad que persisten en la humanidad, dejando entrever aquello en lo que debemos trabajar como sociedad, principalmente en lo relacionado con las brechas de g\u00e9nero, las cuales afligen tanto a varones como a mujeres, y que por lo tanto, impide la redenci\u00f3n hacia dicho sistema.<\/p>\n<p>Lo segundo es que debemos eludir los intentos de cooptaci\u00f3n y capitalizaci\u00f3n del 8M como movimiento, es decir, no es un d\u00eda que merezca ser aprovechado de manera lucrativa y ventajosa no solo por el hecho de que se pierden los prop\u00f3sitos de la conmemoraci\u00f3n, sino que tambi\u00e9n se desdibujan lo fundamentos para la instauraci\u00f3n de dicho d\u00eda, que son las condiciones de tremenda desigualdad, exclusi\u00f3n e hiperviolencia hacia las mujeres por parte del sistema. De otro modo, \u00bfqu\u00e9 sentido o prop\u00f3sito tendr\u00eda el \u201cfestejar\u201d un \u201cd\u00eda de la mujer\u201d?<\/p>\n<p>Lo tercero es que cada 8M nos permite recordar el largo camino que hemos recorrido con el activismo feminista y de mujeres a trav\u00e9s de la lucha y resistencia para la consecuci\u00f3n de nuestros derechos y libertades. El ver que muchos imposibles se convirtieron en posibles, nos hace tener una mirada m\u00e1s esperanzadora hacia el futuro.<\/p>\n<p>Finalmente, quisiera resaltar la importancia que adquiere la conmemoraci\u00f3n del 8M en la actualidad, y me refiero al contexto por el que estamos atravesando como humanidad. Es muy bien sabido que las medidas precautorias aplicadas durante la pandemia han vulnerado de manera considerable a muchas mujeres en el mundo, o -mejor dicho-, la pandemia no ha hecho m\u00e1s que agravar las brechas de g\u00e9nero preexistentes en la sociedad.<\/p>\n<p>El aislamiento social, por ejemplo, ha provocado la vulnerabilidad de las mujeres, por el hecho de que muchas fueron despedidas de sus empleos y obligadas a regresar a los trabajos no remunerados o trabajos de cuidados en los hogares. Adem\u00e1s, muchas han tenido que convivir con sus principales agresores, convirti\u00e9ndolas en v\u00edctimas potenciales ante la violencia dom\u00e9stica y feminicidio.<\/p>\n<p>As\u00ed mismo, cabe destacar que no todas las mujeres han tenido la posibilidad de acatar dicho aislamiento, por lo que deben salir a trabajar para poder y vivir, volvi\u00e9ndose cada vez m\u00e1s vulnerables ante el contagio del virus, sin olvidar -por supuesto- al personal m\u00e9dico femenino en la atenci\u00f3n de enfermos por Covid, las cuales representan una gran mayor\u00eda en dicho sector y quienes tambi\u00e9n se encuentran en una situaci\u00f3n de alta vulnerabilidad por las condiciones de precariedad en las que se encuentran laborando.<\/p>\n<p>Por supuesto que todas las condiciones de vulnerabilidad y violencia hacia las mujeres anteriormente descritas, y tambi\u00e9n las no mencionadas, resultan altamente preocupantes para los movimientos de mujeres. Debemos no solamente visibilizar estas problem\u00e1ticas, sino tambi\u00e9n crear mecanismos que nos permitan disuadir el impacto que est\u00e1 teniendo esta pandemia sobre las mujeres.<\/p>\n<p>En los \u00faltimos meses, los gobiernos han estado preocupados por el dise\u00f1o de estrategias para el control del COVID 19; sin embargo, la violencia contra las mujeres, siendo una pandemia mucho m\u00e1s antigua que la actual, sigue esperando el mismo empe\u00f1o por ser erradicada. La historia nos ha ense\u00f1ado que en la peor de las circunstancias o momentos de crisis es cuando el capital explota de manera voraz los cuerpos de las mujeres y eso es algo por lo que debemos permanecer alertas fuertes y sin miedo.<\/p>\n<p>Este 8M sigamos conscientes, solidarias y llenas de esperanza. Manteng\u00e1monos con el \u00e1nimo de llevar la historia hacia un mejor rumbo, de construir un mejor mundo \u00a0para las generaciones venideras. Sigamos haciendo historia.<\/p>\n<p><strong><br \/>\n<\/strong><strong><em>Frida Karin Alvarado Rodr\u00edguez<\/em><br \/>\n<\/strong>Integrante<br \/>\nCentro de Estudios en G\u00e9nero(s) y Relaciones Internacionales<br \/>\nIRI &#8211; UNLP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cDejarse dominar por el miedo a sentir y a trabajar al l\u00edmite de la propia capacidad es un lujo que solo pueden permitirse quienes carecen de objetivos, quienes no desean guiar sus propios destinos\u201d Audre Lorde &nbsp; Por nuestras ancestras. Por nuestras abuelas, madres y hermanas. Por todas aquellas que dieron sus vidas para disfrutar [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":16658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[34],"tags":[430,431,1147],"class_list":["post-17857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones-iri","tag-8m","tag-dia-internacional-delas-mujeres","tag-opcegri","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",600,160,false],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",375,100,false],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",720,192,false],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false]},"uagb_author_info":{"display_name":"Candela","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/candela\/"},"uagb_comment_info":0,"uagb_excerpt":"\u201cDejarse dominar por el miedo a sentir y a trabajar al l\u00edmite de la propia capacidad es un lujo que solo pueden permitirse quienes carecen de objetivos, quienes no desean guiar sus propios destinos\u201d Audre Lorde &nbsp; Por nuestras ancestras. Por nuestras abuelas, madres y hermanas. Por todas aquellas que dieron sus vidas para disfrutar&hellip;","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/17857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=17857"}],"version-history":[{"count":1,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/17857\/revisions"}],"predecessor-version":[{"id":17858,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/17857\/revisions\/17858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/16658"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=17857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=17857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=17857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}