{"id":19504,"date":"2021-08-27T14:30:38","date_gmt":"2021-08-27T14:30:38","guid":{"rendered":"http:\/\/www.iri.edu.ar\/?p=19504"},"modified":"2021-08-27T14:30:58","modified_gmt":"2021-08-27T14:30:58","slug":"programa-dra-lorenza-sebesta","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2021\/08\/27\/programa-dra-lorenza-sebesta\/","title":{"rendered":"Programa 2021 Dra. Lorenza Sebesta"},"content":{"rendered":"<h5>Europa y su integraci\u00f3n<\/h5>\n<p>Profesor <strong>Lorenza Sebesta<\/strong><\/p>\n<p><strong>Email<\/strong><a href=\"mailto:Lorenza.Sebesta@unitn.it\">Lorenza.Sebesta@unitn.it<\/a><\/p>\n<h6>Objetivo del curso<\/h6>\n<p>El curso ofrece un acercamiento a la integraci\u00f3n europea entendida como un sistema pol\u00edtico original y, al mismo tiempo, como el \u00e9xito de circunstancias hist\u00f3ricas excepcionales vividas por \u00a0sus estados partes y por el sistema internacional. Sus objetivos pueden resumirse en brindar algunas nociones b\u00e1sicas, de car\u00e1cter hist\u00f3rico\u00a0 y conceptual, para\u00a0 comprender la naturaleza de la Uni\u00f3n Europea y sus din\u00e1micas de funcionamiento.<\/p>\n<h6>Contenido del programa<\/h6>\n<ol>\n<li><strong>El contexto hist\u00f3rico de la primera integraci\u00f3n europea (1945-1968)<\/strong><br \/>\n-aspectos comunes de la construcci\u00f3n pol\u00edtica y econ\u00f3mica de los pa\u00edses de Europa Occidental (partidos pol\u00edticos, Constituciones, rasgos estructurales de los pa\u00edses europeos y sus pol\u00edticas econ\u00f3micas entre liberalismo y estatalismo)<br \/>\n-bipolarismo y multilateralismo post b\u00e9lico (la relaci\u00f3n entre atlantismo, multilateralismo y\u00a0 europe\u00edsmo, formaci\u00f3n de los bloques y cuesti\u00f3n alemana)<br \/>\n-descolonizaci\u00f3n y \u201cTercer Mundo\u201d<\/li>\n<li><strong>Naturaleza y actores de un sistema pol\u00edtico original <\/strong><br \/>\n-la Uni\u00f3n Europea (UE): ni estado, ni organizaci\u00f3n internacional<br \/>\n-el funcionamiento\u00a0 de la gobernanza europea:\u00a0 la UE como sistema complejo, flujos de entrada (<em>inputs<\/em>) y salida (<em>outputs<\/em>)\u00a0 y retroalimentaci\u00f3n (<em>feedbacks<\/em>) (David Easton)\u00a0 y clivajes pol\u00edticos\u00a0 (Stein Rokkan)<br \/>\n-instituciones y actores del sistema europeo<\/li>\n<li><strong>Din\u00e1micas de cambio <\/strong><br \/>\n-tipos de cambios: expansi\u00f3n territorial, modificaciones institucionales, ampliaci\u00f3n de competencias<br \/>\n-modalidades de cambio: nuevos tratados, fallos del Tribunal de Justicia de la Uni\u00f3n Europea, competencia subsidiaria (art 352 TFUE)<br \/>\n-motivaciones de los cambios: desaf\u00edos estructurales, pedidos externos, activismo de las instituciones,\u00a0 coaliciones de interes<br \/>\n-hip\u00f3tesis interpretativas sobre las din\u00e1micas de cambio \u2013 el concepto \u00a0<em>spill-over<\/em> en\u00a0 Ernst Haas y los planteos de Albert Hirschman sobre la participaci\u00f3n y\u00a0 defecci\u00f3n de los actores como respuesta al deterioro de empresas, organizaciones y estados.<\/li>\n<li><strong>Pautas de comprensi\u00f3n de la integraci\u00f3n como espacio econ\u00f3mico<\/strong><br \/>\n-definiciones de capitalismo<br \/>\n-carb\u00f3n y acero en las bases de la primera integraci\u00f3n<br \/>\n-de la zona de libre mercado a la uni\u00f3n econ\u00f3mica y monetaria<br \/>\n-cambios estructurales de los a\u00f1os Setenta e\u00a0 inserci\u00f3n de Europa en el nuevo capitalismo global<br \/>\n-algunos rasgos definitorios de la crisis actual de Europa: din\u00e1micas econ\u00f3micas (financiarizaci\u00f3n <em>versus<\/em> industrializaci\u00f3n, acreedores <em>versus<\/em> deudores), racionalidad del sistema (agentes del mercado <em>versus<\/em> estados), cultura pol\u00edtica (tecnocracia <em>versus<\/em> democracia, intereses individuales <em>versus <\/em>bien com\u00fan, meritocracia <em>versus<\/em> igualdad, reconocimiento mutuo <em>versus <\/em>reglamentaci\u00f3n com\u00fan).<\/li>\n<li><\/li>\n<\/ol>\n<h6>Bibliograf\u00eda<\/h6>\n<p>AGUILAR,\u00a0 Salvador, \u201cLa teor\u00eda de los clivajes y el conflicto social moderno\u201d, Universidad de Barcelona, 2009 (Versi\u00f3n ampliada de la ponencia presentada en noviembre de 2008 al Congreso de Ciencia Pol\u00edtica Cr\u00edtica organizado por la UPV en Bilbao) file:\/\/\/C:\/Users\/Utente\/Documents\/Aguilar_sobre_clivajes_2009.pdf<br \/>\nALDECOA, Francisco: <em>La integraci\u00f3n europea. An\u00e1lisis hist\u00f3rico-institucional con textos y documentos,<\/em> Vol. 2. <em>G\u00e9nesis y desarrollo de la Uni\u00f3n Europea (1979-2002)<\/em>, \u00a0Madrid, Tecnos, 2002.<br \/>\nAMBROSIUS, Gerold, <em>El espacio econ\u00f3mico europeo. El final de las econom\u00edas nacionales<\/em>, Madrid, Siglo Veintiuno,\u00a0 2001 (ed. orig. 1996).<br \/>\nEASTON, David, \u201cAn approach to the analysis of political system\u201d, in <em>World Politics<\/em>, vol.9, n.3, 1957, p.383-400.<br \/>\nFABBRINI, Sergio, \u201cM\u00e1s all\u00e1 de Lisboa: el enigma constitucional de la integraci\u00f3n europea\u201d, en Revista SAAP, Vol.4, N. 1, mayo 2010, pp. 13-48.<br \/>\nHAAS, Ernst B., <em>Partidos pol\u00edticos y grupos de presi\u00f3n en la integraci\u00f3n <\/em>europea, Buenos Aires, INTAL, 1966 (ed.orig. 1958).<br \/>\nHABERMAS , J\u00fcrgen, \u201c\u00bfDemocracia o capitalismo?\u201d, en <em>Nueva Sociedad<\/em>, n. 246, julio-agosto 2013, <a href=\"http:\/\/nuso.org\/articulo\/democracia-o-capitalismo\/\">http:\/\/nuso.org\/articulo\/democracia-o-capitalismo\/<\/a>\u00a0 [versione italiana J\u00fcrgen Habermas, \u201cDemocrazia o capitalismo? La miseria capitalistica di una societ\u00e0 planetaria integrata economicamente e frantumata in stati nazionali\u201d (traduzione di Walter Previtera), en <em>Reset<\/em>, septiembre 2013, en <a href=\"http:\/\/www.resetdoc.org\/story\/00000022342\">http:\/\/www.resetdoc.org\/story\/00000022342<\/a>]\nHIRSCHMAN, Albert O., <em>Salida, voz y lealtad: Respuestas al deterioro de empresas, organizaciones y estados<\/em>, M\u00e9xico, FCE, 1977 (ed.orig. 1970).<br \/>\nKEYLOR, William, <em>El mundo del siglo XX. II. La Guerra Fr\u00eda entre las superpotencias, <\/em>Buenos Aires, Ed. Docencia, 1998 [ed. orig. 1996].<br \/>\nMAIR, Peter, \u201cLa democracia m\u00e1s all\u00e1 de los partidos\u201d, en B\u00c9RTOA, Fernando Casal y Gerardo SCHERLIS (eds.), <em>Partidos, Sistemas de Partidos y democracia<\/em>.\u00a0 Buenos Aires, Eudeba, 2015, pp. 263-303.<br \/>\nMARTIN DE LA GUARDIA, Ricardo y PEREZ SANCHEZ, Guillermo (eds.) <em>Historia de la Integraci\u00f3n Europea<\/em>, Barcelona, Ariel, 2001.<br \/>\nMORENO JUSTE, Antonio, \u201cEl proceso de construcci\u00f3n europea: de la CEE a la Uni\u00f3n Europea\u201d<em>, <\/em>en PEREIRA, Juan Carlos (coord..),\u00a0 <em>Historia de las relaciones internacionales contempor\u00e1neas<\/em>, Barcelona, Ariel, 2009 (I ed. 2001).<br \/>\nNEGRO, Sandra, <em>Derecho de la Integraci\u00f3n. <\/em><em>Manual<\/em>, Buenos Aires, Editorial B de f, 2010.<br \/>\nROKKAN, Stein, <em>Stato, nazione e democrazia in Europa<\/em>, a cura di Peter Flora, Bologna, Il Mulino, 2002.<br \/>\nSEBESTA, Lorenza, <em>Seis lecciones sobre Europa<\/em>, Roma, Aracne, 2012.<br \/>\nId., \u201cEl mercado: ficci\u00f3n y realidad de una met\u00e1fora europea\u201d, en <em>Eadem Utraque Europa<\/em>, a.XI, n.16, agosto 2015, pp. 245-270.<br \/>\nSTREECK,\u00a0 Wolfgang, \u201cLa integraci\u00f3n europea: un proyecto elitista\u201d, en <em>Nueva Sociedad<\/em>, n. 242, noviembre-diciembre de 2012 [traducci\u00f3n de \u201cDas Ende der Nachkriegsdemokratie\u201d, en Suddeutsche Zeitung, 27 de julio de 2012] en\u00a0 <a href=\"http:\/\/nuso.org\/articulo\/la-integracion-europea-un-proyecto-elitista\/\">http:\/\/nuso.org\/articulo\/la-integracion-europea-un-proyecto-elitista\/<\/a><\/p>\n<h6>Modalidad de evaluaci\u00f3n y requisitos de aprobaci\u00f3n del curso<\/h6>\n<p>El examen final consistir\u00e1 en un trabajo original sobre una de las tem\u00e1ticas tratadas o sea sobre un concepto, un tema, un periodo hist\u00f3rico o una fuente primaria relacionada con la integraci\u00f3n europea. Se requiere un enfoque descriptivo o anal\u00edtico, evitar por lo posible las referencias prescriptivas y las generalidades. El trabajo ser\u00e1 evaluado seg\u00fan la capacidad de elegir un tema original,\u00a0 una bibliograf\u00eda adecuada,\u00a0 organizar con l\u00f3gica los argumentos y seguir las normas formales y de las bellas letras\u00a0 en la redacci\u00f3n del texto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Europa y su integraci\u00f3n Profesor Lorenza Sebesta EmailLorenza.Sebesta@unitn.it Objetivo del curso El curso ofrece un acercamiento a la integraci\u00f3n europea entendida como un sistema pol\u00edtico original y, al mismo tiempo, como el \u00e9xito de circunstancias hist\u00f3ricas excepcionales vividas por \u00a0sus estados partes y por el sistema internacional. Sus objetivos pueden resumirse en brindar algunas nociones [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19504","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","entry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"ocean-thumb-m":false,"ocean-thumb-ml":false,"ocean-thumb-l":false,"sow-carousel-default":false,"sow-blog-portfolio":false,"sow-blog-grid":false,"sow-blog-alternate":false},"uagb_author_info":{"display_name":"Juana Alvarez Eiras","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/juana-alvarez-eiras\/"},"uagb_comment_info":0,"uagb_excerpt":"Europa y su integraci\u00f3n Profesor Lorenza Sebesta EmailLorenza.Sebesta@unitn.it Objetivo del curso El curso ofrece un acercamiento a la integraci\u00f3n europea entendida como un sistema pol\u00edtico original y, al mismo tiempo, como el \u00e9xito de circunstancias hist\u00f3ricas excepcionales vividas por \u00a0sus estados partes y por el sistema internacional. Sus objetivos pueden resumirse en brindar algunas nociones&hellip;","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/19504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=19504"}],"version-history":[{"count":2,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/19504\/revisions"}],"predecessor-version":[{"id":19506,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/19504\/revisions\/19506"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=19504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=19504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=19504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}