{"id":19547,"date":"2021-08-31T03:01:56","date_gmt":"2021-08-31T03:01:56","guid":{"rendered":"http:\/\/www.iri.edu.ar\/?p=19547"},"modified":"2023-09-06T12:20:55","modified_gmt":"2023-09-06T15:20:55","slug":"a-23-anos-del-fallo-akayesu-reflexiones-sobre-la-genesis-de-la-proscripcion-del-genocidio","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2021\/08\/31\/a-23-anos-del-fallo-akayesu-reflexiones-sobre-la-genesis-de-la-proscripcion-del-genocidio\/","title":{"rendered":"A 23 a\u00f1os del fallo Akayesu. Reflexiones sobre la g\u00e9nesis de la proscripci\u00f3n del genocidio"},"content":{"rendered":"<p style=\"text-align: right;\"><em>\u201cOnly man has law. Law must be built.\u201d<br \/>\n<strong>A Man Called Lemkin<\/strong>\u00a0 (Rosenthal, 1988)<\/em><\/p>\n<p>Entre abril y julio de 1994 por lo menos 500.000 personas de la poblaci\u00f3n tutsi y hutu moderada fueron masacradas brutalmente en Ruanda, uno de los per\u00edodos de exterminio masivo m\u00e1s intensos de la historia de la humanidad. El Consejo de Seguridad de las Naciones Unidas (ONU) concluy\u00f3 que la situaci\u00f3n constitu\u00eda una amenaza para la paz y la seguridad internacionales en el sentido del Cap\u00edtulo VII de la Carta de la ONU. Decidido a poner fin a esos cr\u00edmenes y \u00abconvencido de que el enjuiciamiento de las personas responsables de tales actos contribuir\u00eda al proceso de reconciliaci\u00f3n nacional y al restablecimiento y mantenimiento de la paz\u00bb, el Consejo estableci\u00f3 el Tribunal Penal Internacional para Ruanda (TPIR) que tendr\u00eda sede en Arusha, Tanzania, mediante la resoluci\u00f3n 955 del 8 de noviembre de 1994<a href=\"#_ftn1\" name=\"_ftnref1\"><u><sup>[1]<\/sup><\/u><\/a>.<\/p>\n<p>El TPIR fue el primer tribunal internacional que se ocup\u00f3 de procesar a los autores de genocidio, cr\u00edmenes de lesa humanidad y cr\u00edmenes de guerra. Su jurisdicci\u00f3n abarcaba todas las graves violaciones del derecho internacional humanitario en Ruanda y a ciudadanos ruandeses responsables de tales violaciones cometidas en territorio de pa\u00edses vecinos entre el 1 de enero y el 31 de diciembre de 1994<a href=\"#_ftn2\" name=\"_ftnref2\"><u><sup>[2]<\/sup><\/u><\/a>.<\/p>\n<p>El proceso contra Jean-Paul Akayesu fue particularmente \u201cesperado por mucho tiempo por el pueblo de Ruanda\u201d y constituy\u00f3 un important\u00edsimo precedente en \u201cla destrucci\u00f3n de la cultura de la impunidad\u201d en palabras de <strong>Louise Arbour<\/strong>, Fiscal del TPIR<a href=\"#_ftn3\" name=\"_ftnref3\"><u><sup>[3]<\/sup><\/u><\/a>.<\/p>\n<p>Akayesu ocup\u00f3 el cargo de alcalde, figura de m\u00e1ximo poder en la comuna de Taba desde abril de 1993 hasta junio de 1994. Como tal, ten\u00eda el control exclusivo de la polic\u00eda comunal, de los gendarmes puestos a disposici\u00f3n del municipio y era responsable de la ejecuci\u00f3n de leyes, reglamentos y de la administraci\u00f3n de justicia<a href=\"#_ftn4\" name=\"_ftnref4\"><u><sup>[4]<\/sup><\/u><\/a>. La acusaci\u00f3n afirm\u00f3 que mientras Akayesu se encontraba en ejercicio de esas funciones, entre abril y junio de 1994, al menos dos mil tutsis fueron asesinados en Taba. <strong>Jean-Paul Akayesu<\/strong> no s\u00f3lo estaba al tanto de los asesinatos sino que, en muchos casos, presenci\u00f3 su comisi\u00f3n, facilit\u00f3 los medios para dar lugar a la ejecuci\u00f3n de esos cr\u00edmenes y foment\u00f3 ese accionar a trav\u00e9s del uso p\u00fablico de la palabra convocando a la poblaci\u00f3n a unirse para eliminar al \u201cenemigo \u00fanico\u201d, haciendo referencia a la etnia tutsi.<\/p>\n<p>Por esos actos, el 2 de septiembre de 1998 fue declarado culpable de los cargos de genocidio e incitaci\u00f3n directa y p\u00fablica a cometer genocidio<a href=\"#_ftn5\" name=\"_ftnref5\"><u><sup>[5]<\/sup><\/u><\/a>. Es notable adem\u00e1s que el TPIR consider\u00f3 que la violencia sexual puede constituir un acto de genocidio y sostuvo que <em>\u00ab<\/em>la violencia sexual es un paso en el proceso de destrucci\u00f3n del grupo tutsi, en la destrucci\u00f3n del esp\u00edritu, de la voluntad de vivir y de la vida misma<em>\u00ab<\/em><a href=\"#_ftn6\" name=\"_ftnref6\"><u><sup>[6]<\/sup><\/u><\/a>.<\/p>\n<p>Este fue el primer veredicto de culpabilidad por el crimen de genocidio que pronunci\u00f3 el TPIR y, adem\u00e1s, fue la primera sentencia por genocidio emitida por una corte internacional, lo que constituy\u00f3 un hito en la historia del derecho penal internacional. Naciones Unidas celebr\u00f3 la decisi\u00f3n calific\u00e1ndola como la primera concreci\u00f3n pr\u00e1ctica de los principios de la Convenci\u00f3n contra el Genocidio, que han sido rescatados de los estatutos para convertirse 50 a\u00f1os despu\u00e9s de su aprobaci\u00f3n como consecuencia del Holocausto, en un testamento para la renovada determinaci\u00f3n mundial de castigar el genocidio<a href=\"#_ftn7\" name=\"_ftnref7\"><u><sup>[7]<\/sup><\/u><\/a>.<\/p>\n<p>En los or\u00edgenes de estos principios surge el notable esfuerzo del jurista que acu\u00f1\u00f3 el t\u00e9rmino \u201cgenocidio\u201d. El concepto naci\u00f3 cuando Rapha\u00ebl Lemkin, de nacionalidad polaca, lo incorpor\u00f3 en 1944 en su publicaci\u00f3n <em>Axis Rule in Occupied Europe<\/em>, a partir de la conjunci\u00f3n de la palabra de origen griego <em>genos<\/em> -raza o tribu- y la del lat\u00edn <em>cide<\/em> (o su conjugaci\u00f3n <em>caedere<\/em>) -muerte, para hacer referencia a la destrucci\u00f3n de una naci\u00f3n o un grupo \u00e9tnico<a href=\"#_ftn8\" name=\"_ftnref8\"><u><sup>[8]<\/sup><\/u><\/a>.<\/p>\n<p>Unos a\u00f1os antes, en agosto de 1941, cuando transcurr\u00eda la Segunda Guerra Mundial, quien en ese entonces Primer Ministro <strong>Winston Churchill<\/strong>, se dirigi\u00f3 al pueblo de Gran Breta\u00f1a en una emisi\u00f3n de radio, y habl\u00f3 de la \u00abfuria b\u00e1rbara\u00bb de las tropas alemanas que estaban devastando Europa, en referencia al Holocausto. Las \u00faltimas palabras de <strong>Churchill<\/strong> fueron brutales: \u00abEstamos en presencia de un crimen sin nombre\u00bb<a href=\"#_ftn9\" name=\"_ftnref9\"><u><sup>[9]<\/sup><\/u><\/a>. All\u00ed fue cuando Lemkin y un grupo de personas sintieron que estaban asistiendo a una <em>conspiraci\u00f3n de silencio<\/em><a href=\"#_ftn10\" name=\"_ftnref10\"><u><sup>[10]<\/sup><\/u><\/a>.<\/p>\n<p><strong>Lemkin<\/strong> comprend\u00eda que el problema de los asesinatos en masa no era nuevo, pero cre\u00eda que la comunidad carec\u00eda tanto de leyes como de un lenguaje que les permitiera prevenir futuras atrocidades<a href=\"#_ftn11\" name=\"_ftnref11\"><u><sup>[11]<\/sup><\/u><\/a>. Al decidir acu\u00f1ar una nueva palabra para referir a la violencia destructiva de un grupo espec\u00edfico, <strong>Lemkin<\/strong> finalmente dispuso <em>genocidio<\/em>, una palabra que denotaba un plan coordinado de acciones encaminadas a la destrucci\u00f3n de los fundamentos esenciales de la vida de grupos nacionales, con el objetivo de aniquilar a los propios grupos<a href=\"#_ftn12\" name=\"_ftnref12\"><u><sup>[12]<\/sup><\/u><\/a>.<\/p>\n<p>As\u00ed, gracias a sus gestiones ante los incipientes sistemas de derecho internacional de la ONU, <strong>Lemkin<\/strong> actu\u00f3 como asesor de <strong>Robert H. Jackson<\/strong>, Fiscal principal estadounidense para los Juicios de Nuremberg<a href=\"#_ftn13\" name=\"_ftnref13\"><u><sup>[13]<\/sup><\/u><\/a>. Tambi\u00e9n trabaj\u00f3 tras bambalinas para asegurarse de que el delito de genocidio se incluyera en los cargos contra los l\u00edderes nazis, esfuerzo que result\u00f3 plasmado en el tercer cargo de la acusaci\u00f3n, que enumeraba los cr\u00edmenes de guerra, y se\u00f1al\u00f3 que los imputados hab\u00edan<\/p>\n<p style=\"padding-left: 90px;\"><span style=\"font-size: 10pt;\"><em>\u00ab<\/em>llevado a cabo un genocidio deliberado y sistem\u00e1tico, es decir, el exterminio de grupos raciales y nacionales, contra las poblaciones civiles de ciertos territorios ocupados con el fin de destruir determinadas razas y clases de personas y grupos nacionales, raciales o religiosos, en particular jud\u00edos, polacos y gitanos y otros<em>\u00ab<\/em>.<a href=\"#_ftn14\" name=\"_ftnref14\"><u><sup>[14]<\/sup><\/u><\/a>\u00a0<\/span><\/p>\n<p>Sin embargo, las sentencias de los Juicios de Nuremberg no fueron sentencias por el crimen de genocidio, sino por cr\u00edmenes de guerra y contra la humanidad.<\/p>\n<p>Al a\u00f1o siguiente, en cuanto concluyeron los Juicios de Nuremberg y con la reci\u00e9n creada Organizaci\u00f3n de Naciones Unidas, Lemkin dedic\u00f3 sus esfuerzos para convencer a los Estados miembros de la Asamblea General de que uno de sus primeros mandatos fuera la adopci\u00f3n de una Convenci\u00f3n Internacional sobre Genocidio, logrando que la resoluci\u00f3n 96 de la Asamblea General del 11 de diciembre de 1946 determinara que el genocidio \u201ces la negaci\u00f3n del derecho a la existencia a grupos humanos enteros, que tal negaci\u00f3n del derecho a la existencia conmueve la conciencia humana, causa grandes p\u00e9rdidas a la humanidad a partir de las contribuciones culturales y de otros tipos que representan esos grupos humanos y es contraria a la ley moral, al esp\u00edritu y a los objetivos de las Naciones Unidas\u201d y solicitara al Consejo Econ\u00f3mico y Social la redacci\u00f3n de un proyecto de Convenci\u00f3n.<a href=\"#_ftn15\" name=\"_ftnref15\"><u><sup>[15]<\/sup><\/u><\/a><\/p>\n<p>Finalmente, en 1948 el concepto de Lemkin sirvi\u00f3 como basamento para lograr la definici\u00f3n dada en el art\u00edculo 2 de la Convenci\u00f3n para la Prevenci\u00f3n y Sanci\u00f3n del delito de Genocidio, adoptada el 9 de diciembre de ese a\u00f1o por la Asamblea General, y cuyo mismo esp\u00edritu luego recogieron los estatutos de los Tribunales Penales Internacionales establecidos a\u00f1os m\u00e1s adelante y Tribunales h\u00edbridos cuando estos han sido competentes sobre genocidio.<\/p>\n<p>\u00abS\u00f3lo el hombre tiene ley. La ley debe ser construida\u00bb (Rosenthal, 1988)<a href=\"#_ftn16\" name=\"_ftnref16\"><u><sup>[16]<\/sup><\/u><\/a>. Y para garantizar que este proceso de construcci\u00f3n conduzca al bien y no al mal, dijo Lemkin (1945) \u201cel derecho internacional debe ser un instrumento para el progreso y la justicia, subordinado a los principios b\u00e1sicos de la conciencia y la responsabilidad humanas\u201d<a href=\"#_ftn17\" name=\"_ftnref17\"><u><sup>[17]<\/sup><\/u><\/a>.<\/p>\n<p>El castigo del crimen de genocidio es un asunto de preocupaci\u00f3n internacional y la labor del TPIR reflej\u00f3 el creciente reconocimiento de la dimensi\u00f3n internacional de la justicia penal. A 23 a\u00f1os del fallo Akayesu, la sentencia mantiene viva la memoria de las miles de v\u00edctimas y por la fuerza de su razonamiento ha servido (y servir\u00e1) como gu\u00eda para los tribunales penales internacionales que le sucedieron. La decisi\u00f3n abri\u00f3 las puertas para perseguir y sancionar a los responsables de cr\u00edmenes de genocidio, reafirmando que la persona humana como sujeto del derecho internacional puede comprometer su responsabilidad penal individual. Hasta el d\u00eda de hoy, env\u00eda un mensaje inequ\u00edvoco no solo en Ruanda sino tambi\u00e9n en otras partes del mundo, de que incluso los funcionarios estatales que alguna vez fueron influyentes, no son inmunes al alcance de la justicia penal internacional.<\/p>\n<p><span style=\"font-size: 10pt;\"><strong>Referencias:<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><sup>[1]<\/sup><\/a>\u00a0TPIR, Chamber I, Decision of 2 September 1998 The Prosecutor v. Jean-Paul Akayesu, Case ICTR-96-4-T.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref2\" name=\"_ftn2\"><sup>[2]<\/sup><\/a>\u00a0<em>Ibid.<\/em><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref3\" name=\"_ftn3\"><sup>[3]<\/sup><\/a>\u00a0TPIR, Comunicado de prensa, Declaraci\u00f3n de la jueza Louise Arbour Fiscal del Tribunal Penal Internacional para Ruanda,CC \/ PIU \/ 342-E La Haya, 4 de septiembre de 1998.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref4\" name=\"_ftn4\"><sup>[4]<\/sup><\/a>\u00a0 TPIR, Chamber I, Decision of 2 September 1998 The Prosecutor v. Jean-Paul Akayesu, Case ICTR-96-4-T<em>.<\/em><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref5\" name=\"_ftn5\"><sup>[5]<\/sup><\/a>\u00a0<em>Ibid<\/em><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref6\" name=\"_ftn6\"><sup>[6]<\/sup><\/a><em>\u00a0Ibid<\/em><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref7\" name=\"_ftn7\"><sup>[7]<\/sup><\/a>\u00a0Naciones Unidas, Cobertura de reuniones y comunicados de prensa, Comunicado de prensa, AFR \/ 93 L \/ 2894, Nueva York, 31 de agosto de 1998.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref8\" name=\"_ftn8\"><sup>[8]<\/sup><\/a>\u00a0Eshet, D., et al. The Making History Series, Totally Unofficial: Raphael Lemkin and The Genocide Convention, Facing History and Ourselves Foundation, Brown University,\u00a0 2007. p. 17<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref9\" name=\"_ftn9\"><sup>[9]<\/sup><\/a>\u00a0Winston Churchill, Never Give In! The Best of Winston Churchill\u2019s Speeches, New York, Hyperion, 2003, pp. 299-300<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref10\" name=\"_ftn10\"><sup>[10]<\/sup><\/a>\u00a0Lemkin, R., Totally Unofficial Man: The Autobiography of Raphael Lemkin, in Pioneers of Genocide Studies, ed. Steven L. Jacobs and Samuel Totten, New Brunswick, Transaction Books, 2002, p. 382.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref11\" name=\"_ftn11\"><sup>[11]<\/sup><\/a>\u00a0Lemkin, R., \u201cThe New Word and the New Idea\u201d Raphael Lemkin Papers, New York Public Library Rare Books and Manuscript Division.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref12\" name=\"_ftn12\"><sup>[12]<\/sup><\/a>\u00a0Lemkin, R., Axis Rule in Occupied Europe: Laws of Occupation, Analysis of Government, Proposals for Redress, Washington DC, Carnegie Endowment for International Peace, 1944, p. 79.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref13\" name=\"_ftn13\"><sup>[13]<\/sup><\/a>\u00a0Eshet, D., et al. The Making History Series, Totally Unofficial: Raphael Lemkin and The Genocide Convention, Facing History and Ourselves Foundation, Brown University,\u00a0 2007. p. 30.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref14\" name=\"_ftn14\"><sup>[14]<\/sup><\/a>\u00a0<em>Ibid.<\/em><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref15\" name=\"_ftn15\"><sup>[15]<\/sup><\/a>\u00a0Gonzalez Stier, D. Genocidio: los grupos protegidos y su tratamiento en los casos Akayesu (del TPIR) y Krstic (del TPIY),\u00a0 [En l\u00ednea], elDial.com Contenidos Juridicos, Doctrina DC24D6. Disponible en <a href=\"https:\/\/www.eldial.com\/nuevo\/nuevo_diseno\/v2\/doctrina1.asp?id=10496&amp;base=50&amp;indice=doctrina\">https:\/\/www.eldial.com\/nuevo\/nuevo_diseno\/v2\/doctrina1.asp?id=10496&amp;base=50&amp;indice=doctrina<\/a><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref16\" name=\"_ftn16\"><sup>[16]<\/sup><\/a>\u00a0Rosenthal, A. \u201cA Man Called Lemkin,\u201d New York Times, Octubre 18, 1988.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"#_ftnref17\" name=\"_ftn17\"><sup>[17]<\/sup><\/a>\u00a0Lemkin R., \u201cThe Legal Case against Hitler,\u201d The Nation, Febrero 24, 1945, p. 205.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><em><strong>Victoria Issin<\/strong><\/em><\/span><br \/>\n<span style=\"font-size: 12pt;\">Integrante<\/span><br \/>\n<span style=\"font-size: 12pt;\">Departamento de Derecho Internacional<\/span><br \/>\n<span style=\"font-size: 12pt;\">IRI &#8211; UNLP<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cOnly man has law. Law must be built.\u201d A Man Called Lemkin\u00a0 (Rosenthal, 1988) Entre abril y julio de 1994 por lo menos 500.000 personas de la poblaci\u00f3n tutsi y hutu moderada fueron masacradas brutalmente en Ruanda, uno de los per\u00edodos de exterminio masivo m\u00e1s intensos de la historia de la humanidad. El Consejo de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":16658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[34],"tags":[516,515,517,1137,518],"class_list":["post-19547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones-iri","tag-23-anos","tag-fallo-akayesu","tag-genocidio","tag-opderint","tag-tpir","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",600,160,false],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",375,100,false],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",720,192,false],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2020\/10\/opinionesIRI-FEAT.png",750,200,false]},"uagb_author_info":{"display_name":"Candela","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/candela\/"},"uagb_comment_info":0,"uagb_excerpt":"\u201cOnly man has law. Law must be built.\u201d A Man Called Lemkin\u00a0 (Rosenthal, 1988) Entre abril y julio de 1994 por lo menos 500.000 personas de la poblaci\u00f3n tutsi y hutu moderada fueron masacradas brutalmente en Ruanda, uno de los per\u00edodos de exterminio masivo m\u00e1s intensos de la historia de la humanidad. El Consejo de&hellip;","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/19547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=19547"}],"version-history":[{"count":2,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/19547\/revisions"}],"predecessor-version":[{"id":19549,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/19547\/revisions\/19549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/16658"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=19547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=19547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=19547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}