{"id":24910,"date":"2022-09-30T10:29:55","date_gmt":"2022-09-30T10:29:55","guid":{"rendered":"http:\/\/www.iri.edu.ar\/?p=24910"},"modified":"2022-09-29T19:35:05","modified_gmt":"2022-09-29T19:35:05","slug":"a2022-asia-cechino-articulo-riddick","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2022\/09\/30\/a2022-asia-cechino-articulo-riddick\/","title":{"rendered":"A2022 Asia Cechino Articulo Riddick"},"content":{"rendered":"<div class=\"departamento\">Departamento de Asia y el Pac\u00edfico<br \/>\nCentro de Estudios Chinos<\/div>\n<p class=\"secciones\">Art\u00edculos<\/p>\n<p class=\"Titulo1\">Xinjiang: estado de situaci\u00f3n en el\u00a0oeste <a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/\">*<\/a><\/p>\n<div class=\"autor\">Diego Riddick<\/div>\n<div class=\"texto\">1.664.900 kil\u00f3metros de monta\u00f1as, desiertos y estepas, as\u00ed como oasis y cuencas, albergan casi 26 millones de almas de la Regi\u00f3n Aut\u00f3noma que comprende un sexto del territorio total de la Rep\u00fablica Popular China. Frontera del noroeste, limita con pa\u00edses que presentan diferentes oportunidades y desaf\u00edos, a los que se complementan los mismos que posee Xinjiang. Es en atenci\u00f3n a los primeros, y para hacer frente a los segundos, que el gobierno central desarrolla una amplia estrategia, con pol\u00edticas al interior y exterior. Son estas dos las dimensiones que analizaremos brevemente en las presentes l\u00edneas.<\/p>\n<p class=\"Titulo2\">Contexto: Hilos del pasado que se extienden al presente<\/p>\n<p>La hoy\u00a0<strong><em>Regi\u00f3n Aut\u00f3noma Uigur de Xinjiang (XUAR)<\/em><\/strong>\u00a0ha sufrido todo tipo de convulsiones a lo largo de la historia, incluyendo: un imperio turco en el Siglo VI, un Kanato gobernado por una casa real\u00a0<em>Uygur<\/em>\u00a0en el Siglo IX y la subyugaci\u00f3n en el Siglo XVIII a la China Imperial. La posterior ca\u00edda del imperio abri\u00f3 una vez m\u00e1s la puerta a a\u00f1os de creciente inestabilidad, con la presencia de tropas chinas del<em>\u00a0Kuomintang<\/em>; una ef\u00edmera independencia con la Primera y Segunda Rep\u00fablica del Turkest\u00e1n Oriental (1933-1934 y 1944-1950, respectivamente); y con la Uni\u00f3n Sovi\u00e9tica ejerciendo una marcada influencia hasta el eventual avance de las fuerzas de la Rep\u00fablica Popular.<\/p>\n<p>Los cambios a nivel local tambi\u00e9n deben ser analizados a la luz de diversos contextos regionales: la influencia en la zona a trav\u00e9s de la dinast\u00eda Han, la articulaci\u00f3n de la Ruta de la Seda y el contacto con la Persia de los reyes Aquem\u00e9nides. Durante el per\u00edodo que conocemos como el Medioevo, asistimos a la aparici\u00f3n de n\u00f3madas turcos y la creaci\u00f3n del primer Kanato en el Siglo VI, al cual sigue la presencia de los \u00e1rabes durante el Siglo VIII, con la posterior llegada de los primeros uigures en el alba de las grandes invasiones mongolas. El control chino, restablecido durante el Siglo XVII, se ver\u00e1 afectado ante el debilitamiento imperial que dejar\u00e1 tanto a Xinjiang como al T\u00edbet como peones del Gran Juego, la competencia geopol\u00edtica entre los imperios brit\u00e1nico y ruso durante el siglo XIX.<\/p>\n<p>Al per\u00edodo posterior a la ca\u00edda de la China Imperial y hasta la instauraci\u00f3n de la Rep\u00fablica Popular, Xinjiang orbitar\u00e1 alternativamente entre Mosc\u00fa y Nanjing\/Chongqing, encontrando amplios m\u00e1rgenes de autonom\u00eda.<\/p>\n<p>Estos recorridos resultan de importancia clave para entender la particularidad de Xinjiang, ligado cultural y \u00e9tnicamente con el Asia Central pero en lo espiritual, mirando a La Meca. Dichos factores se conjugan en un escenario por dem\u00e1s complejo, para el cual el gobierno chino despliega su estrategia.<\/p>\n<p class=\"Titulo2\">Dimensi\u00f3n interna: fortalecer la Comunidad de Destino Compartido, mayor estabilidad social y seguridad a largo plazo<\/p>\n<p>Resulta imperativo para Beijing continuar con la integraci\u00f3n hacia el resto de China, que se ha movido a trav\u00e9s de ejes econ\u00f3micos y de seguridad. En el caso del primero, se destaca el crecimiento en econom\u00eda e infraestructura y la creciente inmigraci\u00f3n. XUAR es rica en materias primas y recursos energ\u00e9ticos: algod\u00f3n, lana, frutas, minerales, petr\u00f3leo, gas natural y carb\u00f3n. Las energ\u00edas renovables juegan un rol cada vez m\u00e1s activo en su econom\u00eda, representando casi un 20% del PBI en el 2020.<\/p>\n<p>Si bien mantiene fuertes lazos comerciales con los pa\u00edses vecinos, encontr\u00e1ndose todos entre sus 10 socios econ\u00f3micos principales y generando ganancias por bienes exportables de m\u00e1s de 20.000 millones de d\u00f3lares en 2020, Xinjiang ha ido incrementando su volumen de inversi\u00f3n extranjera directa y su status como nexo de intercambio<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn1\">[1]<\/a>. Es en el marco de esta expansi\u00f3n econ\u00f3mica que asistimos a un crecimiento del 3,4% en el 2020, incluso en un contexto fuertemente ligado al Covid-19.<\/p>\n<p>El gobierno central ha estado especialmente activo en este desarrollo: el apuntalamiento de XUAR a trav\u00e9s de diversas pol\u00edticas que incluyen la creaci\u00f3n del centro log\u00edstico de trenes en\u00a0<em>Urumqi<\/em>\u00a0(capital de Xinjiang) en 2016 y el subsecuente paso del expreso China-Europa; la vinculaci\u00f3n con la Regi\u00f3n Administrativa Especial de Hong Kong (la cual encabeza la lista de origen de inversi\u00f3n extranjera directa en XUAR); as\u00ed como la apertura de diversas zonas tecnol\u00f3gicas, industriales y de comercio en el marco de la Iniciativa \u2018\u2018Go West\u2019\u2019. El desarrollo de hub log\u00edstico de la Regi\u00f3n Aut\u00f3noma es continuo, como evidencia la aprobaci\u00f3n en diciembre pasado de la apertura de una nueva Zona Piloto en Tacheng<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn2\">[2]<\/a>.<\/p>\n<p>Respecto de la inmigraci\u00f3n, iniciada de manera progresiva en las \u00faltimas dos d\u00e9cadas, ha logrado equiparar progresivamente las poblaciones de la etnia Uigur con la Han, mayoritaria a nivel nacional. Seg\u00fan datos del \u00faltimo censo, de los 25.85 millones de habitantes de Xinjiang, los Uigures y los Han comprenden el 44,96% y el 42,24% de la poblaci\u00f3n, respectivamente<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn3\">[3]<\/a>. Demograf\u00eda aparte, estas migraciones favorecieron el traslado de trabajadores calificados, instrumentales en las industrias en desarrollo.<\/p>\n<p>En el eje de la seguridad, se asiste a constantes tensiones originadas por las caracter\u00edsticas propias de Xinjiang y el accionar de grupos partidarios de la secesi\u00f3n, as\u00ed como los roces desatados entre grupos \u00e9tnicos, a ra\u00edz de la inmigraci\u00f3n promovida por el gobierno central. En algunos casos, llevando a episodios particularmente violentos: 1) revueltas en\u00a0<em>Urumqi<\/em>, en julio del 2009; 2) ataque con bombas en\u00a0<em>Aksu<\/em>, con 376 v\u00edctimas, en agosto el 2010; 3) ataque en\u00a0<em>Hotan<\/em>, con 18 v\u00edctimas, en julio de 2011; 4) ataque con armas blancas en una estaci\u00f3n de tren en\u00a0<em>Kunnming<\/em>, con 31 muertos y 141 heridos, en marzo del 2014; 5) en una calle comercial de\u00a0<em>Urumqi<\/em>, ataques con explosivos asesinaron a 43 personas e hirieron a otras 90.<\/p>\n<p>La combinaci\u00f3n de tensiones \u00e9tnicas, secesi\u00f3n y extremismo religioso aline\u00f3 a China con la lucha internacional contra el terrorismo post-2001, as\u00ed como tambi\u00e9n motiv\u00f3 la creciente intervenci\u00f3n para contener cualquier amenaza, en la cual no se ha escatimado en medidas peculiares (aumentos de presupuesto en seguridad destinados a pagos de mayores recompensas por informaci\u00f3n relacionada a actividades terroristas<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn4\">[4]<\/a>), ni pol\u00e9micas, como los Campos de Reeducaci\u00f3n, d\u00f3nde un n\u00famero no establecido de ciudadanos de la etnia uigur se encuentran alojados.<\/p>\n<p>El abordaje del problema desde diferentes variables resulta clave en la comprensi\u00f3n de c\u00f3mo ve el problema la c\u00fapula del Partido Comunista. A lo largo de los \u00faltimos 15 a\u00f1os se han publicado una serie de Libros Blancos de Xinjiang, que dan testimonio de c\u00f3mo Beijing estructura su visi\u00f3n de la situaci\u00f3n y las l\u00edneas fundamentales que gu\u00edan sus pol\u00edticas en esta dimensi\u00f3n interna:<\/p>\n<p><strong>\u2013 Historia y Desarrollo de Xinjiang<\/strong><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn5\">[5]<\/a>\u00a0<strong>(2003)<\/strong>: ofrece una visi\u00f3n general de la historia de Xinjiang, su vinculaci\u00f3n y existencia con otros pueblos, as\u00ed como los desarrollos llevados a cabo por la RPCh.<\/p>\n<p>\u2013\u00a0<strong>Desarrollo y progreso en Xinjiang<\/strong><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn6\">[6]<\/a>\u00a0<strong>(2009)<\/strong>: detalla los avances econ\u00f3micos en la regi\u00f3n y la preservaci\u00f3n de la diversidad \u00e9tnica. Enfatiza la importancia de la seguridad nacional y de la estabilidad para el crecimiento de XUAR.<\/p>\n<p><strong>\u2013 Historia y desarrollo del Cuerpo de Producci\u00f3n y Construcci\u00f3n de Xinjiang<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn7\">[7]<\/a>(2014)<\/strong>: ofrece una visi\u00f3n general del mismo y su funci\u00f3n en el desarrollo de XUAR, no s\u00f3lo desde lo econ\u00f3mico sino tambi\u00e9n desde lo pol\u00edtico.<\/p>\n<p><strong>\u2013 Igualdad y Unidad \u00c9tnica en Xinjiang<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn8\">[8]<\/a>(2015)<\/strong>: se centra en la unidad \u00e9tnica de la regi\u00f3n, y se\u00f1ala tambi\u00e9n tres fuerzas a nivel internacional que influyen en la violencia local: separatismo \u00e9tnico, extremismo religioso y terrorismo.<\/p>\n<p><strong>\u2013 Libertad religiosa en Xinjiang<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn9\">[9]<\/a>(2016)<\/strong>: desarrolla el conflicto religioso en XUAR, pero hace foco en las pol\u00edticas del gobierno para combatir el extremismo.<\/p>\n<p>\u2013\u00a0<strong>Historia cultural y desarrollo en Xinjiang<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn10\">[10]<\/a>(2018)<\/strong>: destaca la coexistencia multicultural en China en general y Xinjiang en particular.<\/p>\n<p>\u2013\u00a0<strong>Lucha contra el terrorismo, el extremismo y la protecci\u00f3n de los DDHH en Xinjiang<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn11\">[11]<\/a>(Marzo 2019)<\/strong>: vincula el separatismo con el extremismo, remarcando la necesidad de combatir al segundo adhiri\u00e9ndose a los preceptos de la ley y aplicando enfoques preventivos.<\/p>\n<p>\u2013\u00a0<strong>Asuntos hist\u00f3ricos relacionados con Xinjiang<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn12\">[12]<\/a>\u00a0(Julio 2019):<\/strong>\u00a0enfatiza los v\u00ednculos de Xinjiang con el resto de China, como parte indivisible de su territorio. Desarrolla adem\u00e1s la naturaleza multi\u00e9tnica de la regi\u00f3n y el pa\u00eds, haciendo precisiones sobre el islam y los antiguos uigures.<\/p>\n<p><strong>\u2013 Educaci\u00f3n y entrenamiento vocacional en Xinjiang<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn13\">[13]<\/a>(Agosto 2019)<\/strong>: este se centra en el progreso de los campos de reeducaci\u00f3n en el combate del extremismo.<\/p>\n<p>\u2013\u00a0<strong>Empleo y Derechos Laborales en Xinjiang\u00a0(2020):<\/strong>\u00a0realiza una revisi\u00f3n respecto del progreso econ\u00f3mico de la regi\u00f3n, el crecimiento del empleo y de la poblaci\u00f3n urbana.<\/p>\n<p class=\"Titulo2\">Dimensi\u00f3n externa: Cooperaci\u00f3n regional y no intervenci\u00f3n<\/p>\n<p>La conducci\u00f3n de la pol\u00edtica general hacia XUAR no est\u00e1 exenta de cr\u00edticas, las cuales han encontrado lugar en recientes disputas geopol\u00edticas merced al crecimiento de China. Beijing, poco receptivo al cuestionamiento en p\u00fablico, se encuentra adem\u00e1s en la necesidad de reiterar su condena a la no-intervenci\u00f3n en los asuntos internos de los pa\u00edses cuando la situaci\u00f3n de los uigures es tra\u00edda a discusi\u00f3n no s\u00f3lo por asociaciones que agrupan a miembros de esa minor\u00eda a lo largo del globo, sino a trav\u00e9s de otros actores como Australia y Estados Unidos.<\/p>\n<p>La disputa comercial con el \u00faltimo ha tra\u00eddo aparejada la\u00a0<strong>Uyghur Human Rights Policy Act<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn14\">[14]<\/a><\/strong>. Independientemente de sus efectos reales, puso en guardia a la dirigencia del Partido Comunista durante la administraci\u00f3n de Donald Trump; dicha situaci\u00f3n contin\u00faa con la llegada de Joe Biden a la Casa Blanca, a ra\u00edz de las altisonantes declaraciones del Secretario de Estado norteamericano durante la cumbre de alto nivel en Anchorage en marzo pasado. Washington tiene un margen de maniobra muy limitado en Xinjiang, tanto por la distancia geogr\u00e1fica como por el recuerdo de la fallida pol\u00edtica a la otra zona bajo soberan\u00eda china en conflicto: Hong Kong. Al d\u00eda de hoy y tras la redacci\u00f3n de diversas actas y \u00f3rdenes ejecutivas, la Regi\u00f3n Administrativa Especial se encuentra \u2018\u2018normalizada\u2019\u2019 tras la sanci\u00f3n y aplicaci\u00f3n de la Ley de Seguridad Nacional.<\/p>\n<p>En el plano regional m\u00e1s cercano es donde Beijing coloca sus mayores esfuerzos en evitar cualquier tipo de infiltraci\u00f3n de elementos terroristas hacia la Regi\u00f3n Aut\u00f3noma. En este esquema juega un rol fundamental la alianza estrat\u00e9gica con Pakist\u00e1n, pa\u00eds con el cual coopera frente a India respecto de las zonas disputadas en Kashmir y comparte importantes lazos econ\u00f3micos (cuyo caso paradigm\u00e1tico es el Corredor Econ\u00f3mico China-Pakist\u00e1n) adem\u00e1s de frontera con XUAR. El apoyo del gobierno pakistan\u00ed a las pol\u00edticas de China no debe tomarse a la ligera<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn15\">[15]<\/a><em>.<\/em>\u00a0China evitar\u00e1 convertir la lucha contra la secesi\u00f3n en un motivo de disputa con la comunidad musulmana a nivel internacional.<\/p>\n<p>El reciente cambio en la situaci\u00f3n pol\u00edtica en Afganist\u00e1n resulta de inter\u00e9s para este an\u00e1lisis. Frente a la posibilidad de un cambio de gobierno en favor del Talib\u00e1n, a principios de agosto China ya hab\u00eda comenzado a reunirse con los bandos en disputa buscando acuerdos comunes independientemente del resultado de los combates<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn16\">[16]<\/a>. Estos acuerdos contemplan rechazar cualquier colaboraci\u00f3n con los grupos secesionistas al interior de Xinjiang. Vemos as\u00ed que este pa\u00eds es de enorme importancia para Beijing no s\u00f3lo por las posibilidades de intercambio de recursos (que Afganist\u00e1n posee en abundancia) o su ubicaci\u00f3n geogr\u00e1fica, sino fundamentalmente por su colaboraci\u00f3n en el combate del extremismo local.<\/p>\n<p>Finalizando, China continuar\u00e1 profundizando su cooperaci\u00f3n con sus vecinos en el oeste, de cara a fortalecer sus flujos comerciales y de comunicaci\u00f3n en el marco de la Iniciativa la Franja y la Ruta, pero tambi\u00e9n en el contexto del combate de fuerzas extremistas dentro de XUAR. Este cometido es inconfundible al presenciar las recientes maniobras militares \u2018\u2018Misi\u00f3n de Paz 2021\u2019\u2019, de las cuales participan los Estados miembros de la Organizaci\u00f3n de Cooperaci\u00f3n de Shangh\u00e1i del 20 al 24 de septiembre<a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn17\">[17]<\/a><em>.\u00a0<\/em>El eje de estas maniobras gira en torno al combate de los tres males: terrorismo, separatismo y extremismo. Un concepto a imagen y semejanza del Libro Blanco \u2018\u2018Igualdad y Unidad \u00c9tnica en Xinjiang\u2019\u2019.<\/p>\n<\/div>\n<p class=\"Titulo3\">Notas<\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn1a\">[1]<\/a>\u00a0Ver:\u00a0<a href=\"https:\/\/www.china-briefing.com\/news\/investing-in-xinjiang-economy-industry-trade-and-investment-profile\/\">https:\/\/www.china-briefing.com\/news\/investing-in-xinjiang-economy-industry-trade-and-investment-profile\/<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn2a\">[2]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/www.xinhuanet.com\/english\/2020-12\/17\/c_139597545.htm\">http:\/\/www.xinhuanet.com\/english\/2020-12\/17\/c_139597545.htm<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn3a\">[3]<\/a>\u00a0Datos \u00faltimo censo de China, extra\u00eddo de Xinhua:\u00a0<a href=\"http:\/\/www.xinhuanet.com\/english\/2021-06\/14\/c_1310006836.htm\">http:\/\/www.xinhuanet.com\/english\/2021-06\/14\/c_1310006836.htm<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn4a\">[4]<\/a>\u00a0Ver:\u00a0<a href=\"https:\/\/news.cgtn.com\/news\/3d63544f7a596a4d\/share_p.html?t=1487810469145\">https:\/\/news.cgtn.com\/news\/3d63544f7a596a4d\/share_p.html?t=1487810469145<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn5\">[5]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/en.people.cn\/200305\/26\/eng20030526_117240.shtml\">http:\/\/en.people.cn\/200305\/26\/eng20030526_117240.shtml<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn6a\">[6]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/www.china.org.cn\/government\/whitepaper\/node_7077515.htm\">http:\/\/www.china.org.cn\/government\/whitepaper\/node_7077515.htm<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn7a\">[7]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/english.www.gov.cn\/archive\/white_paper\/2014\/10\/05\/content_281474992384669.htm\">http:\/\/english.www.gov.cn\/archive\/white_paper\/2014\/10\/05\/content_281474992384669.htm<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn8a\">[8]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/english.www.gov.cn\/archive\/white_paper\/2015\/09\/24\/content_281475197200182.htm\">http:\/\/english.www.gov.cn\/archive\/white_paper\/2015\/09\/24\/content_281475197200182.htm<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn9a\">[9]<\/a>\u00a0Ver:\u00a0http:\/\/english.www.gov.cn\/archive\/white_paper\/2016\/06\/02\/content_281475363031504.htm<\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn10a\">[10]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/english.www.gov.cn\/archive\/white_paper\/2018\/11\/15\/content_281476391524846.htm\">http:\/\/english.www.gov.cn\/archive\/white_paper\/2018\/11\/15\/content_281476391524846.htm<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn11a\">[11]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/english.www.gov.cn\/archive\/white_paper\/2019\/03\/18\/content_281476567813306.htm\">http:\/\/english.www.gov.cn\/archive\/white_paper\/2019\/03\/18\/content_281476567813306.htm<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn12a\">[12]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/english.www.gov.cn\/archive\/whitepaper\/201907\/21\/content_WS5d33fed5c6d00d362f668a0a.html\">http:\/\/english.www.gov.cn\/archive\/whitepaper\/201907\/21\/content_WS5d33fed5c6d00d362f668a0a.html<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn13a\">[13]<\/a>\u00a0Ver:\u00a0<a href=\"http:\/\/english.www.gov.cn\/archive\/whitepaper\/201908\/17\/content_WS5d57573cc6d0c6695ff7ed6c.html\">http:\/\/english.www.gov.cn\/archive\/whitepaper\/201908\/17\/content_WS5d57573cc6d0c6695ff7ed6c.html<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn14a\">[14]<\/a>\u00a0Ver:\u00a0<a href=\"https:\/\/www.congress.gov\/bill\/116th-congress\/senate-bill\/3744\">https:\/\/www.congress.gov\/bill\/116th-congress\/senate-bill\/3744<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn15a\">[15]<\/a>\u00a0Ver:\u00a0<a href=\"https:\/\/www.aljazeera.com\/news\/2021\/7\/2\/pakistan-imran-khan-china-uighurs\">https:\/\/www.aljazeera.com\/news\/2021\/7\/2\/pakistan-imran-khan-china-uighurs<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn16a\">[16]<\/a>\u00a0Extra\u00eddo de entrevista a Sebasti\u00e1n Schulz:<a href=\"https:\/\/mundo.sputniknews.com\/20210807\/cual-sera-el-rol-de-china-en-la-pacificacion-de-afganistan-1114858582.html\">\u00a0https:\/\/mundo.sputniknews.com\/20210807\/cual-sera-el-rol-de-china-en-la-pacificacion-de-afganistan-1114858582.html<\/a><\/p>\n<p><a href=\"https:\/\/cechinounlp.wordpress.com\/2021\/09\/24\/xinjiang-estado-de-situacion-en-el-oeste\/#_ftn17a\">[17]<\/a>\u00a0M\u00e1s precisiones en entrevista a Sebasti\u00e1n Schulz:\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=lPHRBFMZ7wo\">https:\/\/www.youtube.com\/watch?v=lPHRBFMZ7wo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Departamento de Asia y el Pac\u00edfico Centro de Estudios Chinos Art\u00edculos Xinjiang: estado de situaci\u00f3n en el\u00a0oeste * Diego Riddick 1.664.900 kil\u00f3metros de monta\u00f1as, desiertos y estepas, as\u00ed como oasis y cuencas, albergan casi 26 millones de almas de la Regi\u00f3n Aut\u00f3noma que comprende un sexto del territorio total de la Rep\u00fablica Popular China. Frontera [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":24661,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[793],"tags":[858,856,857],"class_list":["post-24910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anuario2022","tag-comunidad-de-destino-compartido","tag-xinjiang","tag-xuar","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",600,160,false],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",375,100,false],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",720,192,false],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false]},"uagb_author_info":{"display_name":"Juana Alvarez Eiras","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/juana-alvarez-eiras\/"},"uagb_comment_info":0,"uagb_excerpt":"Departamento de Asia y el Pac\u00edfico Centro de Estudios Chinos Art\u00edculos Xinjiang: estado de situaci\u00f3n en el\u00a0oeste * Diego Riddick 1.664.900 kil\u00f3metros de monta\u00f1as, desiertos y estepas, as\u00ed como oasis y cuencas, albergan casi 26 millones de almas de la Regi\u00f3n Aut\u00f3noma que comprende un sexto del territorio total de la Rep\u00fablica Popular China. Frontera&hellip;","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/24910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=24910"}],"version-history":[{"count":4,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/24910\/revisions"}],"predecessor-version":[{"id":25414,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/24910\/revisions\/25414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/24661"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=24910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=24910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=24910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}