{"id":25281,"date":"2022-09-30T09:40:20","date_gmt":"2022-09-30T09:40:20","guid":{"rendered":"http:\/\/www.iri.edu.ar\/?p=25281"},"modified":"2022-09-30T09:36:51","modified_gmt":"2022-09-30T09:36:51","slug":"a2022-seguridad-articulo-wajsman","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2022\/09\/30\/a2022-seguridad-articulo-wajsman\/","title":{"rendered":"A2022 Seguridad Art\u00edculo Wajsman"},"content":{"rendered":"<div class=\"departamento\">Departamento de Seguridad Internacional y Defensa<\/div>\n<p class=\"secciones\">Art\u00edculos<\/p>\n<p class=\"Titulo1\">Ciberguerra entre Israel e Ir\u00e1n: desde Stuxnet hasta los ciberataques actuales<\/p>\n<div class=\"autor\">Gustavo Wajsman<a href=\"#_ftn1\" name=\"_ftnref1\"><sup><strong>[1]<\/strong><\/sup><\/a><\/div>\n<p class=\"Titulo2\">Resumen.<\/p>\n<div class=\"texto\">\n<p>El presente trabajo tiene como fin dar cuenta del primer Ciber ataque estatal con una Ciber arma presuntamente llevado a cabo por Israel y Estados Unidos aunque ejecutado por una unidad especial del Mossad, el Kidon, contra la central nuclear iran\u00ed en la ciudad de Natanz. Dicho ataque cibern\u00e9tico tuvo la intenci\u00f3n de retrasar los planes nucleares de Ir\u00e1n que incidir\u00edan en el poder y status quo de la regi\u00f3n detentado por Israel como potencia regional y principal aliado de los Estados Unidos de Norteam\u00e9rica. Si bien hay varios actores externos involucrados, nosotros solo abordaremos la postura israel\u00ed fundamentada en una visi\u00f3n neorrealista de las relaciones internacionales contempla el uso de ataques preventivos desde 1981 para salvaguardar la seguridad del estado. En este caso debuto el uso del quinto dominio a trav\u00e9s de la ciber arma STUXNET y ello ocasiono su consecuente repercusi\u00f3n en la doctrina de defensa iran\u00ed.<\/p>\n<p>Seg\u00fan nuestra visi\u00f3n esta guerra librada en el Ciberespacio, la cual fue complementada con operaciones de informaci\u00f3n, operaciones especiales y actividades especiales de inteligencia en las que participo el Mossad Israel\u00ed y la unidad 8200 de AMAN, la inteligencia militar de dicho pa\u00eds, fue perge\u00f1ada estrat\u00e9gicamente para usarse en conjunto con operaciones convencionales y no convencionales. En el caso tratado ello ocurri\u00f3 como consecuencia de la lecci\u00f3n aprendida en la guerra de Iom Kipur en 1973 y lo que ellos llaman \u201cEl concepto\u201d. . As\u00ed se dio el primer punta pie que dio origen a una nueva era ampliando la guerra al ciberespacio.<\/p>\n<p>Pero como toda fuerza de acci\u00f3n tiene otra fuerza de reacci\u00f3n, igual y opuesta, el exitoso uso de STUXNET a pesar de su negaci\u00f3n al principio y posterior reconocimiento por parte de altos funcionarios Iran\u00edes que retraso varios meses su programa nuclear, logro ganar algo de tiempo para usar otros medios alternativos como ser los diplom\u00e1ticos internacionales para detener el desarrollo nuclear del pa\u00eds persa pero como contrapartida , provoco que Ir\u00e1n desarrollara una poderosa unidad de ciberdefensa y comience usar el Ciberespacio como un dominio m\u00e1s de la guerra.<\/p>\n<p class=\"Titulo2\">Justificacion<\/p>\n<p>Desde un abordaje desde el realismo estructural trataremos el tema de STUXNET como la primer ciber arma dando comienzo a la ciberguerra, como un dominio m\u00e1s de la guerra, teniendo en cuenta la historia militar israel\u00ed, las relaciones internacionales, la seguridad internacional como campo especifico de las relaciones internacionales y la estrategia. Lo novedoso del presente trabajo es que no solo identifica a STUXNET como primer ciber arma sino que fue el producto final de una revisi\u00f3n en su doctrina militar luego del error estrat\u00e9gico militar cometido por Israel en 1973, durante la guerra de IOM KIPUR, el cual casi le cuesta una derrota militar y pol\u00edtica sin precedente desde la creaci\u00f3n del estado de Israel el 14 de mayo de 1948 que podr\u00eda haber acabado con el estado jud\u00edo.<\/p>\n<p>Nuestra visi\u00f3n ser\u00e1 concentrarnos brevemente en los cambios ocurridos desde dicha guerra y en la situaci\u00f3n de que a partir de entonces Israel no volvi\u00f3 a participar en una guerra estatal abierta. Lo que sigui\u00f3 en adelante para Israel fueron diferentes clases de conflictos asim\u00e9tricos incluyendo los conflictos h\u00edbridos y que como corolario culmino con el comienzo del uso del ciber espacio como campo de batalla complementario para asegurar el estatus quo de la regi\u00f3n y seguir manteniendo su superioridad militar .<\/p>\n<p>Si bien es cierto que desde 1973 Israel no se vio involucrado en una guerra convencional, los conflictos h\u00edbridos en los que se vio involucrado tuvieron que ver con actores subnacionales pero patrocinados por Ir\u00e1n.<\/p>\n<p>Dado que Ir\u00e1n financia y apoya a hezbollah y Hamas y ha manifestado su deseo de desaparecer al estado jud\u00edo de la faz de la tierra, Israel har\u00e1 todo lo posible para que Ir\u00e1n no consiga el arma nuclear y para retrasar sus avances en dicha materia hasta que se pueda resolver por otros medios a trav\u00e9s de la comunidad internacional.<\/p>\n<p class=\"Titulo2\">Planteamiento del problema<\/p>\n<p>De acuerdo a lo mencionado ut supra, el estado de Israel, se encuentra sumido en una visi\u00f3n de balance de poder regional descripto perfectamente por el realismo estructural de Kenneth Waltz en y en un sistema internacional an\u00e1rquico, debido a que no hay una autoridad central que lo ordene y por otro lado en dicho marco los estados dependen de s\u00ed mismo para sobrevivir. En esta visi\u00f3n neorrealista, las capacidades de los estados juegan un rol preponderante y el estado de Israel debe vigilar a Ir\u00e1n en este caso y accionar en consecuencia a sus desarrollos o intentos de desarrollos de capacidades militares para mantener la balanza a su favor.<\/p>\n<p>Con STUXNET se incorpora a la estrategia militar Israel\u00ed un nuevo dominio para la defensa del estado. Como los actores estatales son racionales y generan respuestas racionales, Ir\u00e1n percibi\u00f3 luego de esta inesperada acci\u00f3n por parte de Israel, la necesidad de contar con una ciberbrigada tanto defensiva como ofensiva de ahora en m\u00e1s.<\/p>\n<p class=\"Titulo2\">Introduccion<\/p>\n<p>Como se mencion\u00f3 previamente, durante el desarrollo del presente trabajo, el cual aclaramos que no pretende ser exhaustivo sino tan solo el hilo de Ariadna para una mayor profundizaci\u00f3n futura, trataremos de dar respuesta a la pregunta acerca de si \u00bfEl estado de Israel uso la primer ciber arma, STUXNET, como apoyo a las operaciones convencionales y de inteligencia para mantener su status quo con la intenci\u00f3n de retrasar los planes nucleares de Ir\u00e1n?<\/p>\n<p>Nuestra hip\u00f3tesis es que el uso de STUXNET efectivamente tuvo como finalidad retrasar el programa nuclear iran\u00ed y cumpli\u00f3 su cometido con el objetivo de mantener su superioridad militar regional y asegurar la integridad de su territorio y la vida de sus ciudadanos y habitantes del estado de Israel. Se utiliz\u00f3 este nuevo dominio de la guerra primero para impedir un desbalance de poder regional y por otro lado no recurrir a un conflicto b\u00e9lico abierto tradicional, lo cual hubiese costado muchos m\u00e1s recursos, apoyo internacional por parte de los Estados Unidos y Arabia Saud\u00ed y otros actores , y bajas humanas y materiales incalculables.<\/p>\n<p>Dicho de otra manera Israel pretendi\u00f3 no ir a una guerra abierta ni volver a los cl\u00e1sicos bombardeos a\u00e9reos que uso contra otros pa\u00edses en casos similares, y sobre todo teniendo en cuenta que la planta nuclear de Natanz es una instalaci\u00f3n de dif\u00edcil acceso para el ataque con misiles y demasiado riesgoso para una incursi\u00f3n de fuerzas especiales Israel\u00edes o del MOSSAD. Debido a ello decidi\u00f3 estrat\u00e9gicamente usar el quinto dominio para afectar de manera significativa las capacidades de las centrifugadoras de ura\u00f1o, sin posibilidad de una atribuci\u00f3n determinante de su autor\u00eda. En el ciberespacio no existen las declaraciones de guerra. De esta manera mantuvo el statu quo hasta el d\u00eda de hoy de acuerdo a la doctrina Begin de ataques preventivos.<\/p>\n<p>El objetivo general que pretende humildemente este trabajo, es analizar si STUXNET ha logrado su fin de retrasar el programa nuclear Iran\u00ed y mantener el statu quo regional de poder y si a partir de entonces ha continuado con su pol\u00edtica de ciberdefensa hasta la actualidad de acuerdo a la doctrina Begin e identificar la respuesta iran\u00ed en el quinto dominio.<\/p>\n<p>Para cumplir con este objetivo general nos proponemos presentar un contexto hist\u00f3rico, que permita entender el problema planteado desde la guerra de IOM KIPUR hasta el uso de STUXNET por parte de Israel y su continuidad de su estrategia de ciberdefensa y uso de Ciber armas.<\/p>\n<p>Luego de ello explicar las caracter\u00edsticas de STUXNET como ciber arma y por ultimo describir las consecuencias del uso de la misma.<\/p>\n<p>Previamente haremos una descripci\u00f3n del marco te\u00f3rico elegido que en nuestro caso es el neorrealismo o realismo estructural para sostener nuestra hip\u00f3tesis y tambi\u00e9n describiremos brevemente la metodolog\u00eda utilizada.<\/p>\n<p class=\"Titulo2\">Marco teorico<\/p>\n<p>Todo trabajo acad\u00e9mico cient\u00edfico tiene que contar con un marco te\u00f3rico de una ciencia o disciplina que lo sostenga y sirve como paradigma para explicar la hip\u00f3tesis que se plantea y su demostraci\u00f3n o negaci\u00f3n de la misma.<\/p>\n<p>En nuestro caso hemos seleccionado el neorrealismo o realismo estructural y en particular las ideas de Kenneth Waltz, padre del neorrealismo. Como la palabra misma neorrealismo denota, si hay un neorrealismo es porque existi\u00f3 un realismo cl\u00e1sico previamente.<\/p>\n<p>Para ello daremos cuenta de todos los puntos de convergencia que existen en el realismo cl\u00e1sico en general en sus diversas vertientes para luego explicar el aporte del neorrealismo a las relaciones internacionales y su aplicaci\u00f3n a nuestro caso de estudio.<\/p>\n<p>La visi\u00f3n del realismo comprende:<\/p>\n<ul>\n<li>El actor central de las relaciones internacionales es el estado.<\/li>\n<li>El sistema internacional es an\u00e1rquico y conflictivo.<\/li>\n<li>Lo que mueve a los estados es el poder y la seguridad<\/li>\n<li>Los estados son racionales<\/li>\n<\/ul>\n<p>Para el neorrealismo de Kenneth Waltz, el mundo internacional es un sistema compuesto por una estructura de unidades que interact\u00faan entre s\u00ed. La estructura permite analizar al sistema como un todo. (SODUPE, 2004:84)<\/p>\n<p>El realismo tiene una visi\u00f3n de pesimismo antropol\u00f3gico. Ve al hombre como un ser ego\u00edsta motivado por sus propios intereses y deseosos de poder. Es debido a ello que los hombres se organizan en estados y cada estado busca su poder en funci\u00f3n de su inter\u00e9s nacional.<\/p>\n<p>Por supuesto que ven el sistema internacional como an\u00e1rquico porque no existe una autoridad central. Debido a ello los estados solo pueden confiar en s\u00ed mismos y su preocupaci\u00f3n principal es mantener un margen apropiado de seguridad. Para lograrlo, los estados recurren al uso del equilibrio de poder y de la disuasi\u00f3n.<\/p>\n<p>El primer exponente que hist\u00f3ricamente se asocia al realismo es Tucidides y su obra: la historia de la guerra del Peloponeso.<\/p>\n<p>Tambi\u00e9n se encuentra entre sus padres fundadores a Maquiavelo quien ya profundiza en la naturaleza imperfecta del hombre y a Hobbes, quien es considerado otro de sus grandes exponentes que refiere que la naturaleza del estado es an\u00e1rquica y que donde la norma es \u201c<em>mantener sus armas en guardia y apuntando, y sus ojos fijos en el otro\u201d (MINGST, 2004: 126) <\/em><\/p>\n<p>Por otro lado consideramos que uno de los mayores referentes que aplico el realismo a la pol\u00edtica exterior fue El exponente pol\u00edtico m\u00e1s influyente de la teor\u00eda realista es Henri Kissinger.<\/p>\n<p>Para concluir este apartado debemos tratar de responder a dos preguntas:<\/p>\n<ol>\n<li>\u00bfPara qu\u00e9 quieren poder los estados?<\/li>\n<li>\u00bfCu\u00e1nto poder quieren los estados?<\/li>\n<\/ol>\n<p>La respuesta al primer interrogante es por el principio ordenador an\u00e1rquico de autoayuda. Los estados solo dependen de s\u00ed mismo y de sus capacidades.<\/p>\n<p>La respuesta a la segunda pregunta es: los estados solo quieren sobrevivir y para ello necesitan seguridad. Adquirir poder es la mejor manera de adquirir seguridad. Evitar que otros estados se hagan m\u00e1s poderosos es una premisa central.<\/p>\n<p>Seg\u00fan John Mearsheimer los estados desarrollan capacidades militares para defenderse de otros estados. El objetivo principal de los estados es su supervivencia. Por otro lado el mayor peligro es que los estados nunca podr\u00e1n conocer la intenci\u00f3n de los dem\u00e1s. Por lo tanto el estado como un actor racional siempre buscara maximizar su poder para sobrevivir (MEARSHIMER, 2006:73-74)<\/p>\n<p class=\"Titulo1\">Contexto historico<\/p>\n<p class=\"Titulo2\">Fundacion del estado de israel y sus tres guerras<\/p>\n<p>El estado de Israel fue fundado el 14 de mayo de 1948. Al siguiente d\u00eda tuvo que librar su primera guerra: la guerra por la independencia conocida como IOM HAZMAUT. A pesar de su incipiente ej\u00e9rcito, logro una incre\u00edble victoria militar y se hizo con m\u00e1s territorio en todos sus frentes. A diferencia de otros pa\u00edses del mundo, este joven pa\u00eds contaba desde temprano con diversos servicios de inteligencia que lo orientaban y ayudaban a lograr la independencia. El primero de ellos se llam\u00f3 SHAI, el cual tuvo diversas intervenciones y actividades pre independentista. Luego fue disuelto y se cre\u00f3 el SHIN BETH y el AMAN (LA INTELIGENCIA MILITAR ISRAELI) en 1948. Previamente en 1936 se cre\u00f3 la proto estrella de la inteligencia Israel: EL MOSSAD el cual opero hasta la creaci\u00f3n del estado el cual en 1951 seria refundado bajo las directivas de Ben Gurion como el coraz\u00f3n de la inteligencia israel\u00ed.<\/p>\n<p>Por ultimo en 1960 se cre\u00f3 una unidad de inteligencia separada llamada LEKEM, la cual se dedicar\u00eda \u00fanicamente a inteligencia cient\u00edfico-tecnol\u00f3gica. En 1985 se disolvi\u00f3 y sus funciones pasaron al ministerio de defensa y al ministerio de ciencia y tecnolog\u00eda.(NEJANKY, 2020: 20-21)<\/p>\n<p>Israel adem\u00e1s tuvo que soportar la guerra de los seis d\u00edas en 1967 en la cual volvi\u00f3 a humillar a los ej\u00e9rcitos \u00e1rabes agresores lo que le dio la sensaci\u00f3n de superioridad militar indiscutible y su tal\u00f3n de Aquiles: el concepto.<\/p>\n<p>La tercer guerra que tuvo que afrontar fue en 1973 conocida como la guerra de IOM KIPUR en donde esa falsa sensaci\u00f3n de seguridad que se conoce en Israel como \u201cel concepto\u201d dejo al estado jud\u00edo en las puertas del caos y la sorpresa estrat\u00e9gica que casi le cuesta una derrota total.<\/p>\n<p>Esta falsa sensaci\u00f3n de seguridad conocida como \u201cEl concepto\u201d estaba fundada en la confianza excesiva en los servicios de inteligencia israel\u00edes, y sobre todo de sus fuerzas de defensa de la capacidad de reacci\u00f3n con que contaban las fuerzas de defensa de Israel y por \u00faltimo la capacidad de movilizar 600000 soldados en horas a sus puestos de combate debido a un sistema estrat\u00e9gico de movilizaci\u00f3n y a su poca profundidad estrat\u00e9gica.<\/p>\n<p>A pesar de ello el director del MOSSAD advirti\u00f3 que la guerra con Egipto y Siria era inminente pero sin embargo el sesgo de \u201cEl concepto\u201d fue m\u00e1s fuerte y llevo a no escuchar al General Zamir y la lamentable guerra estallo. Adem\u00e1s cabe agregar que tambi\u00e9n existi\u00f3 un excelente uso de las operaciones de informaci\u00f3n por parte de los egipcios que filtraron por distintos medios que no atacar\u00edan Israel por que no podr\u00edan ganar jam\u00e1s esa guerra.(NEJANKY, 2020)<\/p>\n<p>Con respecto a las operaciones de informaci\u00f3n, podemos afirmar que no son algo nuevo en la historia militar a pesar de que su doctrina si lo es y se la relaciona con el ciberespacio. Sin ir m\u00e1s lejos An\u00edbal las utilizo para enga\u00f1ar a los romanos en la batalla de Canae.<\/p>\n<p>Afirmaba el actual comandante del comando estrat\u00e9gico de los Estados Unidos, General John Hyten, que no hay algo tal como guerra espacial y cibern\u00e9tica solo hay guerras. Pero cambios recientes en la doctrina militar Americana le est\u00e1n dando mayor importancia a las operaciones de informaci\u00f3n dentro de los conflictos. Este cambio ocurri\u00f3 luego de que el pent\u00e1gono percibiera como el enemigo hace uso de las mismas y que tanto dentro del campo de batalla como fuera le permiten alcanzar logros t\u00e1cticos y estrat\u00e9gicos.(VERTULI-LOUDON, 2018:xiii)<\/p>\n<p>\u201cla dificultad para distinguir entre el enga\u00f1o deliberado y la revelaci\u00f3n involuntaria de secretos, de diferenciar se\u00f1ales y ruidos, conduce en ocasiones a la necesidad de tratar a la informaci\u00f3n de manera similar, pues todo es ruido hasta que los hechos ocurren\u201d .(NEJANKY, 2020: 63)<\/p>\n<p>Los Israel\u00edes aprendieron la lecci\u00f3n y desde 1981 con la doctrina Begin y a trav\u00e9s de ataques preventivos que algunos autores incluso identifican como preentivos, debido a que consideran que todo estado tiene derecho a actuar aun cuando la amenaza aun sea potencial, no permitir\u00e1n jam\u00e1s que ning\u00fan enemigo de Israel ponga en jaque al estado nuevamente ni pueda afectar sus capacidades militares y de disuasi\u00f3n estrat\u00e9gica que posee para poder tener seguridad para su territorio y ciudadanos.<\/p>\n<p>Para poder entender mejor el conflicto que mantiene Israel con Ir\u00e1n, vamos a analizar brevemente como ha sido su relaci\u00f3n hist\u00f3rica.<\/p>\n<p>Para ello y al solo efecto de comprender mejor sus antecedentes, dividiremos su an\u00e1lisis en dos periodos:<\/p>\n<ol>\n<li>D, durante el periodo del Shah Reza Pahlavi, un aliado de occidente y en especial de Estados Unidos, en el cual Israel incluso cooperaba con Ir\u00e1n y en el cual los estados unidos le transfiri\u00f3 tecnolog\u00eda nuclear para usos pac\u00edficos sobre todo de energ\u00eda.<\/li>\n<li>Un segundo periodo en donde el Sha abuso de la confianza y trato de tener un desarrollo nuclear con fines militares para lo cual se le retiro todo el apoyo y luego de la revoluci\u00f3n del ayatollah Khomeini en adelante que se volvi\u00f3 a la idea de tener el arma nuclear.<\/li>\n<\/ol>\n<p class=\"Titulo2\">Periodos de las relaciones de occidente con iran<\/p>\n<p class=\"Titulo3\">Primer periodo<\/p>\n<p>En el primer periodo que comienza durante la segunda guerra mundial y termina en 1979 y se caracteriza porque existe una colaboraci\u00f3n e inter\u00e9s en Ir\u00e1n por parte de Estados Unidos y Gran Breta\u00f1a. Luego de la guerra tambi\u00e9n se interesa por el pa\u00eds persa la URSS compitiendo por concesiones petroleras.<\/p>\n<p>Desde su creaci\u00f3n en 1948, el estado de Israel causo gran conmoci\u00f3n en medio oriente. Aliado de estados unidos, occidental, anticomunista y contrario a los intereses de los pa\u00edses \u00e1rabes de la regi\u00f3n. Pero ir\u00e1n hay que recordar que no es un pa\u00eds \u00e1rabe sino persa porque no se hable \u00e1rabe sino Persa o Farsi. Israel luego de sus tres guerras pudo comenzar a identificar a sus enemigos en la regi\u00f3n y a establecer cu\u00e1les eran sus prioridades y amenazas a su seguridad nacional. Por otro lado en 1968 ir\u00e1n firma el Tratado de no proliferaci\u00f3n nuclear. Estados unidos provee de combustible nuclear con fines pac\u00edficos durante 10 a\u00f1os. Pero el Shah ten\u00eda otras intenciones con el programa nuclear. En 1979 Khomeini se hace del poder en Ir\u00e1n y funda un estado teocr\u00e1tico contrario a occidente a diferencia del Shah y empieza a apoyar a grupos de izquierda como Hezbollah.(GOMEZ, 2017:7)<\/p>\n<p class=\"Titulo3\">Segundo periodo<\/p>\n<p>Como mencionamos ut supra este segundo periodo comienza con la toma del poder del ayatola Khomeini en 1971 y la fundaci\u00f3n del califato que tiene como caracter\u00edstica la impronta religiosa que tomar\u00eda el pa\u00eds de aqu\u00ed en adelante.<\/p>\n<p>Este es un periodo muy conflictivo, se crean varias organizaciones terroristas sobre todo para disputarle la soberan\u00eda a Israel e Ir\u00e1n las apoya con log\u00edstica, armamentos, entrenamiento y financiaci\u00f3n. El caso de Hezbollah en L\u00edbano es un caso paradigm\u00e1tico porque crea un estado dentro de otro estado, participa en pol\u00edtica y tambi\u00e9n tiene un ala que lleva a cabo operaciones terroristas en conjunto con Ir\u00e1n. Luego Ir\u00e1n tuvo una larga guerra con Irak en la cual sali\u00f3 victorioso este \u00faltimo. Y de esta manera el ayatola se convenci\u00f3 de que necesitaban retomar el programa nuclear militar para tener disuasi\u00f3n. Como Estados Unidos ya no colaboraba en el programa, Ir\u00e1n busco nuevos socios como Pakist\u00e1n y China para la transferencia de tecnolog\u00eda nuclear. China quien se hab\u00eda comprometido a venderles un reactor nuclear desisti\u00f3 como resultado de las presiones que ejerci\u00f3 estados unidos pero sin embargo esto no acabo con el programa nuclear Iran\u00ed. Israel ve con preocupaci\u00f3n a Ir\u00e1n y a su programa nuclear teniendo en cuenta adem\u00e1s de su cercan\u00eda, su patrocinio al grupo libanes Hezbollah y luego a Hamas y la posibilidad de que le entregue alg\u00fan tipo de arma nuclear t\u00e1ctica. Esto empeora en 2001 cuando Ir\u00e1n comienza con su construcci\u00f3n subterr\u00e1nea en la ciudad de Natanz de una central nuclear para enriquecimiento de uranio. Comienzan las negociaciones internacionales para que ir\u00e1n detenga su programa nuclear pero para Israel esto no es suficiente. Si Ir\u00e1n consiguiera el arma nuclear adem\u00e1s de una amenaza real al estado jud\u00edo, implicar\u00eda un desbalance de poder regional que Israel no estaba dispuesto a aceptar. La decisi\u00f3n final de Israel de actuar preventivamente es tomada finalmente cuando el presidente de Ir\u00e1n anuncia que est\u00e1 dispuesto a construir 10 centrales nucleares nuevas. (GOMEZ, 2017:14)<\/p>\n<p class=\"Titulo3\">Stuxnet<\/p>\n<p>STUXNET no es solo la primer ciber arma de la historia sino es un hito que marca un antes y un despu\u00e9s en la historia de la guerra. En el S XX las guerras se llevaban a cabo en enfrentamientos directos de sus fuerzas armadas. Con su ej\u00e9rcito, fuerza a\u00e9rea y armada enfrentaban cada conflicto b\u00e9lico que ocurr\u00eda. La historia cambio un poco durante la guerra fr\u00eda. Luego de finalizada la segunda guerra mundial, los dos superpotencias ganadoras decidieron batirse a duelo por el dominio mundial. Pero exist\u00eda un problema. No se pod\u00edan enfrentar directamente porque ambos contaban con misiles nucleares y as\u00ed se establece la doctrina de la mutua destrucci\u00f3n asegurada. Entonces la guerra se dar\u00eda en la cabeza y en los corazones de los pa\u00edses alineados ideol\u00f3gicamente a uno u otro bando y el enfrentamiento entre estos ir\u00eda demarcando quien ser\u00eda el verdadero hegemon mundial.<\/p>\n<p>En 1991 se produce la ruptura del sistema bipolar con la implosi\u00f3n de la Uni\u00f3n de Rep\u00fablicas Socialistas Sovi\u00e9ticas (URSS) que se encontraba exhausta por el esfuerzo que signific\u00f3 la carrera armament\u00edstica denominada iniciativa de defensa estrat\u00e9gica por un lado y, por el otro lado al haber fracasado el modelo propuesto por el comunismo el cual, prima facie, no pudo mejorar la vida de sus connacionales. Estados Unidos de Am\u00e9rica surgi\u00f3 como \u00fanica potencia dominante al desaparecer el imperio sovi\u00e9tico (Ozaran, 2006). Con el final de la Guerra Fr\u00eda tambi\u00e9n comenzaba a delinearse lo que en relaciones internacionales es denominado nuevo orden mundial. Este denota cambios sustanciales con respecto al orden vigente durante la Guerra Fr\u00eda en especial en cuanto a \u201clas reglas de juego y a la distribuci\u00f3n de poder\u201d (Bartolom\u00e9, 2006, p., 76) Ozaran (2006 p., 20) opina que este nuevo orden mundial \u201cno surgi\u00f3 por la globalizaci\u00f3n, la ca\u00edda del muro de Berl\u00edn o la desintegraci\u00f3n de la ex Uni\u00f3n Sovi\u00e9tica sino que la suma de todos estos hechos fueron preparando el camino\u201d.<\/p>\n<p>Por otro lado hay que tener en cuenta como bien afirma Bartolom\u00e9 (2006, p., 78) \u201cnunca antes existi\u00f3 tanta democracia como en los inicios de la post Guerra Fr\u00eda. Esto auguraba para los neo internacionalistas liberales un sistema internacional de baja conflictividad\u201d.<\/p>\n<p>El 11-S lo cambi\u00f3 todo, con \u00e9l se esfum\u00f3 definitivamente la idea que sosten\u00edan los neo internacionalistas liberales acerca de la baja conflictividad que deparaba el nuevo orden mundial. Se tuvo en cuenta la baja conflictividad interestatal pero no la de otro tipo de conflictos, ya sean transnacionales o intraestatales.<\/p>\n<p>El siglo XXI incorporo un nuevo ambiente operacional a la guerra: el ciberespacio. Los conceptos de teatros de operaciones como espacios, duraci\u00f3n de la campa\u00f1a como tiempo y poder de combate como medios empiezan a perder algo de sentido y los estados comienzan a pensar que las ciber armas tiene la capacidad de alterar la forma tradicional de hacer la guerra. Para poder estar a la altura de las circunstancias hace falta tener una estrategia de ciberdefensa, capacitar recursos humanos, desarrollar armas cibern\u00e9ticas y ver la forma de adecuar todo esto al derecho interno e internacional(STEL,2005)<\/p>\n<p>Seg\u00fan Koybko la revoluci\u00f3n digital cambio los modos de vida social, pol\u00edtica y econ\u00f3mica y el ciberespacio pas\u00f3 a ser otro teatro de guerra. Por otro lado hace m\u00e1s de 2000 a\u00f1os Sun Tzu entendi\u00f3 que era mejor la guerra por medios indirectos(2019:21)<\/p>\n<p>Steven Metz ha manifestado que ha manifestado que la idea de asimetr\u00eda hac\u00eda referencia a alg\u00fan tipo de diferencia para tener alg\u00fan tipo de ventaja sobre el adversario. Por lo general pretenden generar un impacto psicol\u00f3gico, que obste la iniciativa, libertad de acci\u00f3n o deseos del enemigo. (Bartolom\u00e9, 2006)<\/p>\n<p>Las operaciones de informaci\u00f3n buscan da\u00f1ar, destruir modificar la informaci\u00f3n contenida en las redes o sistemas de informaci\u00f3n para cambiar las percepciones de la poblaci\u00f3n local e incluso del personal militar. (STEL,2005)<\/p>\n<p>Por otro lado seg\u00fan Alvin Toffler el conocimiento es \u201cel recurso central de la destructividad as\u00ed como lo es de la productividad\u201d la forma en que hacemos la guerra siempre es la misma de la que hacemos la riqueza. Tambi\u00e9n afirma Toffler que la informaci\u00f3n se est\u00e1 convirtiendo en el recurso principal de la guerra.(VERTULI-LOUDON, 2018:9-10)<\/p>\n<p>Ya son muchos los autores que afirman que la ciberguerra es la guerra por excelencia en el S XXI. Esto no quiere decir que la guerra convencional vaya a desaparecer. Es una guerra m\u00e1s propicia, barata y sin sangre. Lo \u00fanico que se necesita es contar con la infraestructura y los recursos humanos pertinentes que son mucho m\u00e1s econ\u00f3micos que los recursos convencionales y un solo ciber soldado puede apagar una ciudad entera, dejarla sin transporte o envenenar las aguas. Por otro lado esto da lugar a conceptos como el de ciberguerra que es llevada a cabo por estados contra otros estados dirigida a da\u00f1ar gravemente las capacidades del enemigo, para sustraerle informaci\u00f3n clasificada, sabotear sus infraestructuras cr\u00edticas. La guerra cibern\u00e9tica se caracteriza por su asimetr\u00eda, complejidad, objetivos limitados, etc.(MADERO, 2012:125)<\/p>\n<p>Podemos decir que un cibera taque es una acci\u00f3n realizada en el ciberespacio para penetrar, causar da\u00f1o, afectar, destruir sistemas inform\u00e1ticos, computadoras o dispositivos controladas por ellas. Para ello se valen de malware o programas maliciosos como virus o troyanos. Podemos decir que existen tres principales clases de cibera taques: los que perturban tomando el control de infraestructuras cr\u00edticas como el SCADA y su intenci\u00f3n es causar un da\u00f1o f\u00edsico. Cibera taques no intrusivos como los de DDoS y por \u00faltimo los intrusivos usados con el fin de conseguir informaci\u00f3n a trav\u00e9s de malware info-stealer que se usan para actividades de ciberespionaje. En el caso de Israel est\u00e1 dentro de la \u00f3rbita del MOSSAD, a trav\u00e9s de su unidad especial Kidon, y la unidad 8200 de AMAM de las FDI. Normalmente combinan los ataques ciber con operaciones convencionales y no convencionales sobre todo de fuerza a\u00e9rea bombardeando blancos espec\u00edficos, sabotajes por detonaci\u00f3n de explosivos, sumado a otras operaciones especiales de inteligencia como asesinatos selectivos para retrasar el programa nuclear Iran\u00ed (ROCA, 2013:8)<\/p>\n<p>En el a\u00f1o 2010 es detectada la ciber arma STUXNET por la empresa de seguridad inform\u00e1tica Bielorrusa VirusBlokAda. La particularidad de este gusano es que aprovecha la vulnerabilidad de MS10-4416 del sistema operativo Windows CC, que funcionan con los sistema del tipo SCADA, de la empresa Siemens y tiene la particularidad de atacar infraestructuras criticas como oleoductos, plataformas de petr\u00f3leo, centrales nucleares, el\u00e9ctricas, etc. y permite sabotearlos. Este virus troyano no se introduce a trav\u00e9s de internet sino est\u00e1 dise\u00f1ado para hacerlo a trav\u00e9s de una memoria USB. Una vez que es introducido el USB en una de las computadoras, se oculta en el Rootkit firmando con certificados previamente robados a los fabricantes del hardware. Despu\u00e9s de ello se mantiene oculto y camuflado hasta que su director decide activarlo. De ah\u00ed en m\u00e1s se multiplica a si mismo e infecta todas las computadoras de la intranet permitiendo a su autor robar informaci\u00f3n o sabotear el sistema ocultando los cambios. T\u00e9cnicamente usa para propagarse el archivo autorun.inf y aprovecha una vieja y conocida vulnerabilidad LNK del d\u00eda cero que hace que con solo ver los archivos en Windows, se ejecutan autom\u00e1ticamente y a trav\u00e9s de recursos de red compartidos se propaga. Lo m\u00e1s destacable de STUXNET, que es considerada la mejor ciber arma hasta ese momento inventada es que se trata del primer rootkit que se prepar\u00f3 para atacar el sistema SCADA. El resultado lo conocemos:20 % de las centrifugadoras destruidas en la planta de Natanz.(SANCHEZ MADERO, 2012:129-130)<\/p>\n<p>Como bien es sabido en ciberdefensa el problema de la atribuci\u00f3n es dif\u00edcil de lograr. Por declaraciones posteriores de altos funcionarios Israel\u00edes y norteamericanos, STUXNET habr\u00eda sido un desarrollo conjunto pero ejecutado por el MOSSAD a trav\u00e9s de una operaci\u00f3n de HUMINT que consisti\u00f3 en dejar abandonados varios pen drives llamativos en el estacionamiento de la planta nuclear de Natanz para que alguno o varios de sus empleados los conecten a un puerto USB e infecten el equipo.<\/p>\n<p>Este tipo de ciber armas es conocida como fire and forget( disparar y olvidar) lo estrat\u00e9gico de STUXNET es que pudo atacar y reprogramar el equipo blanco. Este ataque afecto a los niveles f\u00edsicos, l\u00f3gicos, de informaci\u00f3n, etc. Este tipo de refinamiento en los conocimientos apunta a que solo un estado o conjunto de ellos estaban en capacidad de desarrollarlo. Tanto el NY Times como un experto en seguridad inform\u00e1tica de Alemania apuntan a Israel y Estados Unidos e incluso van m\u00e1s lejos afirmando que pudieron utilizar sus propias centrales nucleares para probar el arma cibern\u00e9tica. Por otro lado el mism\u00edsimo SNOWDEN afirmo que STUXNET fue desarrollado en conjunto por Israel y Estados Unidos. Si bien en el momento del ataque Ir\u00e1n desminti\u00f3 da\u00f1os, m\u00e1s adelante el presidente Ahmadinejad lo admiti\u00f3 pero minimizando su verdadero alcance. <em>\u201c Stuxnet evidencia que este tipo de armamento es real y tiene la capacidad de afectar estructuras criticas del estado\u201d<\/em> .(GOMEZ, 2017:18-20)<\/p>\n<p class=\"Titulo3\">Consecuencias de stuxnet<\/p>\n<p>Como bien nos ilumina el maestro de la diplomacia internacional, Henry Kissinger, antes de la ciber era se pod\u00eda hablar de distinciones entre periodos de paz y de guerra. Los servicios de inteligencia exist\u00edan para evaluar y en algunos casos intervenir en el desarrollo de capacidades de otros estados. Un actor en solitario contando tan solo con algunos conocimientos espec\u00edficos y un ordenar puede acceder al ciberespacio y destruir infraestrtura critica desde un cuasi anonimato.( KISSINGER, 2016:345)<\/p>\n<p>Ir\u00e1n comprendi\u00f3 que hab\u00eda sido sorprendido por lo que Nassim Taleb denomino \u201cCisne Negro\u201d que es un suceso que ocurre por sorpresa, que nadie vio venir o lo pudo prever y que tienen un gran impacto y repercusiones trascendentales.(SANTANDER.ES, 2021)<\/p>\n<p>Entonces el presidente Iran\u00ed comprendi\u00f3 que comenzaba una nueva era, con nuevas amenazas, en especial en el campo del ciberespacio y que hacia falta destinar recursos financieros, tecnol\u00f3gicos y humanos para librar guerras en el quinto dominio. Creo una unidad de ciberdefensa tanto pasiva como activa. Y desde entonces empezaron a intercambiar cibera taques con Israel hasta el d\u00eda de la fecha conjuntamente con operaciones especiales de inteligencia como sabotaje y asesinatos.<\/p>\n<p>Oficiales de alto rango de la CIA identificaron a Ir\u00e1n como responsable del ataque a la empresa Saud\u00ed Aramco utilizando el malware SHAMOON. Tambi\u00e9n lo se\u00f1alan como responsable de ciber ataques a entidades bancarias de Estados Unidos ese mismo a\u00f1o. (ROCA, 2013:42)<\/p>\n<p>Y entonces hizo su aparici\u00f3n FLAME: una nueva Ciberarma que supera a su antecesor STUXNET. Esto reafirma que las Ciberarmas son para Israel una parte importante de su estrategia en el ciberespacio en contra de Ir\u00e1n. Esta nueva ciber arma es un gusano de ciberespionaje que afecto a varios pa\u00edses de medio oriente. La empresa de seguridad inform\u00e1tica Kaspersky determino que fue utilizada para un sabotaje al sector petrolero iran\u00ed.<\/p>\n<p>Flame comparte muchas caracter\u00edsticas con STUXNET aunque el primero se considera el m\u00e1s complejo detectado hasta el momento. Esta herramienta de ataque b\u00e1sicamente da acceso a un backdoor, funciona como un troyano y logra infectar redes locales, unidades removibles a trav\u00e9s de comandos remotos. Adem\u00e1s en lugar de destruir como STUXNET, esp\u00eda de manera invisible. Tambi\u00e9n tiene funciones de ataque. Una vez infectada la maquina permite robar archivos, cambiar la configuraci\u00f3n remota, encender micr\u00f3fonos para grabar , interceptar la informaci\u00f3n ingresada por teclados, capturar pantallas y chats y tambi\u00e9n interferir comunicaciones telef\u00f3nicas por VoIP.(BEJARANO, 2012:1-4)<\/p>\n<p>En la actualidad existe o m\u00e1s bien contin\u00faa desde STUXNET una guerra soterrada entre Ir\u00e1n e Israel que combina el ciberespacio con operaciones encubiertas y especiales.<\/p>\n<p>Ir\u00e1n sufri\u00f3 doce misteriosos ataques entre junio y julio de 2020 consistente en incendios y explosiones. Esto ocurri\u00f3 luego de que un cibera taque por parte de Ir\u00e1n hacia Israel intentara da\u00f1ar a la poblaci\u00f3n civil envenenando su agua potable elevando los niveles de cloro. Esto elevo la ciberguerra entre ambos pa\u00edses llev\u00e1ndola a terrenos f\u00edsicos como advertencia.<\/p>\n<p>El 23 de abril de 2020 Israel detecto alteraciones en una planta de agua potable donde hackers cambiaron los niveles de cloro y de qu\u00edmicos del agua que podr\u00edan haber sido fatales. Israel determino que el ataque se produjo desde Ir\u00e1n utilizando servidores europeos y americanos. El director nacional de Ciber de Israel declaro en ese momento que se cruzaron todas las l\u00edneas rojas. La primer contra respuesta fue un cibera taque al puerto iran\u00ed de Sajid rajaee. El Washington post se lo atribuyo a Israel. La guerra en el quinto dominio es cada vez m\u00e1s com\u00fan entre estados, da\u00f1a sin ser divisado y evita escaladas militares.(INSEG.ES, 2020)<\/p>\n<p class=\"Titulo2\">Conclusiones<\/p>\n<p>Dice Henri Kissinger que \u201ccada \u00e9poca tiene su leiv motiv\u201d osea una cosmovisi\u00f3n en la cual basar nuestras ideas y creencias d\u00e1ndonos un paradigma para entender al mundo. \u201c en la \u00e9poca medieval era la religi\u00f3n, en los siglos xix y xx fue la ilustraci\u00f3n y su fe en la raz\u00f3n humana\u2026 en el s xxi es la ciencia y la tecnolog\u00eda\u2026 estas han permitido m\u00e1s avances que en cualquier otra \u00e9poca pero tambi\u00e9n han creado armas capaces de destruir a la humanidad\u2026\u201d( KISSINGER, 2016:331)<\/p>\n<p>Durante el desarrollo del presente trabajo final integrador logramos demostrar nuestra hip\u00f3tesis acerca de que STUXNET logro retrasar los planes nucleares iran\u00edes y que a partir de entonces Israel continuo con su doctrina de cibera taques para colaborar con el mantenimiento del status quo vigente regional sin llegar a un enfrentamiento en el mundo f\u00edsico o por lo menos acot\u00e1ndolos a ciertos sabotajes y alg\u00fan asesinato selectivo de alg\u00fan cient\u00edfico nuclear iran\u00ed.<\/p>\n<p>Est\u00e1 claro que Israel desde la doctrina Begin en adelante se ha manejado en un marco te\u00f3rico de las relaciones internacionales del neorrealismo dado que actu\u00f3 en un sistema internacional an\u00e1rquico donde cada estado solo busca poder frente a otros estados para asegurar su supervivencia que est\u00e1 directamente relacionada con sus capacidades militares. En este caso concreto Israel debilito las capacidades nucleares de Ir\u00e1n para no desbalancear el poder regional que encabeza. Como Kenneth Waltz Israel le da suma importancia a la estructura en donde interact\u00faan las unidades dentro del sistema internacional.<\/p>\n<p class=\"Titulo3\">Notas<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a>Maestrando en Relaciones Internacionales (USAL) y candidato al Doctorado de Estudios Internacionales (Universidad Di Tella); egresado de la EDENA y Diplomado en Seguridad Internacional y Defensa (Universidad de Belgrano); Maestrando en Derecho, LLM (Universidad de Londres); experto en Cibercrimen y Ciberseguridad (Universidad Siglo XXI) y Diplomado Universitario en Gesti\u00f3n de la Ciberdefensa (Escuela Superior de las Fuerzas Armadas).<\/p>\n<p class=\"Titulo2\">Referencias bibliogr\u00e1ficas<\/p>\n<p class=\"Titulo3\"><a name=\"_Toc57670592\"><\/a>Bibliograf\u00eda Te\u00f3rica<\/p>\n<p class=\"bibliografia\">Bartolom\u00e9, M. (2006). La seguridad internacional en el siglo XXI, M\u00e1s all\u00e1 de Westfalia y Clausewitz.Academia Nacional de estudios pol\u00edticos y estrat\u00e9gicos. Ministerio de Defensa, Chile.<\/p>\n<p class=\"bibliografia\">Bejerano, M. Jose(2012) en l\u00ednea:<a href=\"https:\/\/dialnet.unirioja.es\/descarga\/articulo\/7468740.pdf\">https:\/\/dialnet.unirioja.es\/descarga\/articulo\/7468740.pdf<\/a> flame: una nueva amenaza de ciberespionaje.<\/p>\n<p class=\"bibliografia\">Buzan, B. (1998). Security, A new Framework for Analysis. Lynne Rienner Publishers, Boulder- Colorado.<\/p>\n<p class=\"bibliografia\">Calle, F. y Merke, F. (2004). La Estrategia de Seguridad Nacional de EE.UU. en la Era Bipolar. Agenda Internacional A\u00f1o 1, N\u00b0 3, Diciembre 2004. Enero\/Febrero 2005.<\/p>\n<p class=\"bibliografia\">Cardona, D.; Duarte, I. y Jim\u00e9nez, N. (2004). La Estrategia de Seguridad Nacional de los Estados Unidos en la Administraci\u00f3n Bush: Una Lectura desde Am\u00e9rica Latina. CEPI, Universidad del Rosario, Bogot\u00e1.<\/p>\n<p class=\"bibliografia\">CIDOB. Anuario Internacional 2008, 2007, Claves para interpretar la pol\u00edtica exterior espa\u00f1ola y las relaciones internacionales en 2007, relaciones de la Uni\u00f3n Europea con la Federaci\u00f3n Rusa. Recuperado de <a href=\"http:\/\/www.cidob.org\/\">http:\/\/www.cidob.org<\/a>.<\/p>\n<p class=\"bibliografia\">Clarke, R. (2004). Contra todos los enemigos. Taurus. Buenos Aires.<\/p>\n<p class=\"bibliografia\">Gonz\u00e1lez, R. (2010). La Estrategia de Seguridad Nacional de los Estados Unidos. Publicado en el Consejo Argentino para las Relaciones Internacionales. Recuperado de <a href=\"http:\/\/www.cari.org.ar\/\">www.cari.org.ar<\/a>. .<\/p>\n<p class=\"bibliografia\">Jim\u00e9nez, B. F. (2011). Racionalidad pac\u00edfica. Una introducci\u00f3n a los Estudios para la paz. Dykinson, Madrid.<\/p>\n<p class=\"bibliografia\">Kepa, Sodupe(2003) \u201cLa teoria de las relaciones internacionales a comienzos del siglo xxi\u201d, Universidad del Pais Vazco.<\/p>\n<p class=\"bibliografia\">Korybco, Andrew(2019) \u201cGuerras hibridas. revoluciones de colores y guerra no convencional\u201d, Batalla de ideas<\/p>\n<p class=\"bibliografia\">Kissinger, Henry(2016) \u201cOrden mundial\u201d, Ed Debate, Bs As<\/p>\n<p class=\"bibliografia\">Lobell, S. E., Ripsman, N. M. y Taliaferro, J. (2009). Neoclassical Realism, The State And Foreign Policy. Recuperado de <a href=\"https:\/\/core.ac.uk\/download\/pdf\/233941226.pdf\">https:\/\/core.ac.uk\/download\/pdf\/233941226.pdf<\/a>.<\/p>\n<p class=\"bibliografia\">Llinas Gomez, Alejandro(2017) \u201cAn\u00e1lisis del ciberataque para la seguridad de los estados y su incidencia en la transformacion del status quo: stuxnet el virus informatico\u201d, Universidad del colegio mayor de nuestra Sra. Del Rosario, Bogota.<\/p>\n<p class=\"bibliografia\">Medero, Gema(2012) <a href=\"https:\/\/dialnet.unirioja.es\/servlet\/articulo?codigo=4331298\">https:\/\/dialnet.unirioja.es\/servlet\/articulo?codigo=4331298<\/a> <u><a href=\"https:\/\/dialnet.unirioja.es\/servlet\/articulo?codigo=4331298\">La ciberguerra: los casos de Stuxnet y Anonymous<\/a><\/u><\/p>\n<p class=\"bibliografia\">Mearsheimer, J. (2001). The Tragedy of Great Power Politics. W.W. Norton &amp; Company, E.E.U.U.<\/p>\n<p class=\"bibliografia\">Mijares, V. M. (2015). Realismo neocl\u00e1sico: \u00bfEl retorno de los estudios internacionales a la ciencia pol\u00edtica? Revista de Ciencia Pol\u00edtica \/ Volumen 35 \/ N\u00ba 3 \/ 2015 \/ 581 \u2013 603.<\/p>\n<p class=\"bibliografia\">Mingst, Karen(2006) \u201cFundamentos de las relaciones internacionales\u201d, CIDE<\/p>\n<p class=\"bibliografia\">Nejanky, Paul(2020) \u201cLas fallas de la inteligencia israeli. analisis de una sorpresa en la guerra de iom kipur\u201d.punto aparte.<\/p>\n<p class=\"bibliografia\">Rodr\u00edguez Moreno, A. (2013). Giorgio Agamben y los Derechos Humanos: Homo Sacer I, el poder soberano y la nuda vida. Recuperado de <a href=\"http:\/\/www.academia.edu\/2091837\/giorgio_agamben_los_derechos_humanos_homo_sacer_I\">www.academia.edu\/2091837\/giorgio_agamben_los_derechos_humanos_homo_sacer_I<\/a>.<\/p>\n<p class=\"bibliografia\">Roca Xavier(2013) <a href=\"https:\/\/dialnet.unirioja.es\/servlet\/articulo?codigo=7494996\">https:\/\/dialnet.unirioja.es\/servlet\/articulo?codigo=7494996<\/a> <u><a href=\"https:\/\/dialnet.unirioja.es\/servlet\/articulo?codigo=7494996\">ciberseguridad, contrainteligencia y operaciones encubiertas en el programa nuclear de ir\u00e1n: de la neutralizaci\u00f3n selectiva de objetivos al \u201ccuerpo ciber\u201d iran\u00ed<\/a><\/u><\/p>\n<p class=\"bibliografia\">Rubbi, L. (2018). Guerra asim\u00e9trica: La estrategia de defensa de la Rep\u00fablica Popular China en el per\u00edodo 2012 \u2013 2016. Tesis de maestr\u00eda. Universidad Torcuato Di Tella, Buenos Aires.<\/p>\n<p class=\"bibliografia\">Stel. Enrique(2005). \u00abGuerra cibernetica\u201d, Circulo Militar<\/p>\n<p class=\"bibliografia\">Valdez Ugalde, J. L. y Duarte, F. (2013). Del poder duro al poder inteligente. La nueva estrategia de seguridad de Barack Obama o de la sobrevivencia de la pol\u00edtica exterior de Estados Unidos. Norteam\u00e9rica, A\u00f1o 8, n\u00famero 2, julio-diciembre de 2013.<\/p>\n<p class=\"bibliografia\">Vertuli, Mark y Loudon, Bradly(2018) \u201cpercepciones son realidades\u201d, Circulo Militar<\/p>\n<p class=\"bibliografia\">Walt, S. M. (1985). Alliance Formation and the Balance of World Power. International Security, 9(4), 3-43.<\/p>\n<p class=\"bibliografia\">Waltz, K. N. (1979). Theory of international politics. Addison, Wesley.<\/p>\n<p class=\"bibliografia\">Zakar\u00eda, F. (2008). The Post-American World, Allen Lane, New York.<\/p>\n<p class=\"Titulo3\">Bibliograf\u00eda Metodol\u00f3gica<\/p>\n<p class=\"bibliografia\">Maxwell, J. (1996). Qualitative Research Design. An Interactive approach. Sage Publicatios. Recuperado de <a href=\"http:\/\/catedras.fsoc.uba.ar\/guemure\/bibliografia\/Maxwell1.pdf\">http:\/\/catedras.fsoc.uba.ar\/guemure\/bibliografia\/Maxwell1.pdf<\/a>.<\/p>\n<p class=\"bibliografia\">Taylor, S. y Bogdan, R. (1987). Introducci\u00f3n a los m\u00e9todos cualitativos de investigaci\u00f3n: La b\u00fasqueda de significados. Editorial Paid\u00f3s B\u00e1sica, Barcelona.<\/p>\n<p class=\"bibliografia\">Vasilachis, I. (2006). Estrategias de Investigaci\u00f3n Cualitativa. Gedisa, Barcelona.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Departamento de Seguridad Internacional y Defensa Art\u00edculos Ciberguerra entre Israel e Ir\u00e1n: desde Stuxnet hasta los ciberataques actuales Gustavo Wajsman[1] Resumen. El presente trabajo tiene como fin dar cuenta del primer Ciber ataque estatal con una Ciber arma presuntamente llevado a cabo por Israel y Estados Unidos aunque ejecutado por una unidad especial del Mossad, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":24661,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[793],"tags":[883,136,265],"class_list":["post-25281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anuario2022","tag-ciberguerra","tag-iran","tag-israel","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",600,160,false],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",375,100,false],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",720,192,false],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/09\/anuario2022FEAT.png",750,200,false]},"uagb_author_info":{"display_name":"Juana Alvarez Eiras","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/juana-alvarez-eiras\/"},"uagb_comment_info":0,"uagb_excerpt":"Departamento de Seguridad Internacional y Defensa Art\u00edculos Ciberguerra entre Israel e Ir\u00e1n: desde Stuxnet hasta los ciberataques actuales Gustavo Wajsman[1] Resumen. El presente trabajo tiene como fin dar cuenta del primer Ciber ataque estatal con una Ciber arma presuntamente llevado a cabo por Israel y Estados Unidos aunque ejecutado por una unidad especial del Mossad,&hellip;","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/25281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=25281"}],"version-history":[{"count":5,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/25281\/revisions"}],"predecessor-version":[{"id":25562,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/25281\/revisions\/25562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/24661"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=25281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=25281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=25281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}