{"id":26462,"date":"2023-03-08T12:35:23","date_gmt":"2023-03-08T12:35:23","guid":{"rendered":"http:\/\/www.iri.edu.ar\/?p=26462"},"modified":"2023-09-06T11:49:47","modified_gmt":"2023-09-06T14:49:47","slug":"8m-retos-para-las-mujeres-en-el-marco-de-la-preocupante-situacion-politica-en-peru","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2023\/03\/08\/8m-retos-para-las-mujeres-en-el-marco-de-la-preocupante-situacion-politica-en-peru\/","title":{"rendered":"8M: Retos para las mujeres en el marco de la preocupante situaci\u00f3n pol\u00edtica en Per\u00fa"},"content":{"rendered":"<table>\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><span style=\"color: #000080;\"><em>El Instituto de Relaciones Internacionales desea hacer llegar su reconocimiento a todas las Mujeres en el d\u00eda su conmemoraci\u00f3n, en el entendimiento de que no se trata de un d\u00eda de festejo sino de reflexi\u00f3n por las luchas dadas y por las luchas que ellas y las sociedades en su conjunto tendr\u00e1n que enfrentar. Por un mundo sin diferencia alguna basada en el g\u00e9nero y por la materializaci\u00f3n del permanente anhelo de una vigencia plena de los Derechos Humanos para todos sin ning\u00fan tipo de discriminaci\u00f3n.<\/em><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"texto\">\n<p>En el marco de una nueva <strong>conmemoraci\u00f3n del 8M \u201cD\u00eda Internacional de la Mujer\u201d<\/strong>, el Centro de Estudios en G\u00e9nero(s) y Relaciones Internacionales (CeGRI) mantiene su firme compromiso de abordar el g\u00e9nero desde una perspectiva cr\u00edtica, reflexiva y plural. Como grupo de investigaci\u00f3n, se coincide en que las desigualdades estructurales de g\u00e9nero se renuevan para su supervivencia en la sociedad y las instituciones cumplen un rol fundamental en ello, pues premian o castigan dichas conductas en cada periodo de tiempo. Por tal motivo, resulta importante relevar la situaci\u00f3n de las mujeres peruanas durante la ola de protestas que asolan el pa\u00eds.Desde diciembre de 2022, la situaci\u00f3n pol\u00edtica peruana se mantiene inestable e incierta. Con <strong>Dina Boluarte<\/strong> a la cabeza, sucesora constitucional del tristemente c\u00e9lebre expresidente <strong>Pedro Castillo<\/strong>, su breve gobierno se ha caracterizado por rasgos poco democr\u00e1ticos, que inciden perjudicialmente en la conflictiva relaci\u00f3n ciudadan\u00eda-instituciones p\u00fablicas. Esto ha provoc\u00f3 que las protestas ciudadanas que exigen su renuncia, la salida del Congreso, el adelanto de elecciones y una Asamblea Constituyente est\u00e9n m\u00e1s vigentes que nunca, especialmente en las provincias m\u00e1s pobres del pa\u00eds.Sin embargo, a cuatro d\u00edas del D\u00eda Internacional de la Mujer, el Ministerio de la Mujer y Poblaciones Vulnerables (MIMP) realiz\u00f3 un pronunciamiento [1] poco acertado en relaci\u00f3n a los tiempos pol\u00edticos que vivimos. El mensaje se dirigi\u00f3 a las cuidadoras de ni\u00f1os y adolescentes con la finalidad de proteger la integridad f\u00edsica y emocional de dichas poblaciones vulnerables en el marco del ejercicio de la protesta pac\u00edfica. En resumidas cuentas, el MIMP \u00a0pidi\u00f3 no llevar ni\u00f1xs y adolescentes a las movilizaciones, a pesar de ser la instituci\u00f3n encargada de velar por el bienestar de las mujeres y las infancias.<\/p>\n<p>Gracias a la prensa independiente y algunos medios nacionales e internacionales, se ha expuesto al ojo p\u00fablico los excesos de las fuerzas del orden peruanas, tales como lanzar bombas lacrim\u00f3genas a mujeres que ven\u00edan de provincia con sus beb\u00e9s cargados en llicllas [2] a ejercer un derecho plenamente reconocido por la Constituci\u00f3n de 1993 [3]. \u00bfAcaso el rol de cuidadoras restringe a las mujeres de ejercer derechos civiles y pol\u00edticos? \u00bfSon las madres cuidadoras las responsables de cualquier accidente que pueda ocurrir a sus hijos durante las protestas?<\/p>\n<p>Ciertamente, el debate no deber\u00eda estar centrado en la madre que protesta, sino en disminuir cualquier indicio de exceso de la fuerza durante las protestas que pueda poner en peligro a las mujeres y sus infantes. Es un gran problema asignar la responsabilidad a la mujer cuidadora sobre sus hijos en las movilizaciones, ya que exime a los organismos p\u00fablicos intervinientes de la obligaci\u00f3n que les corresponde durante las movilizaciones a nivel nacional. Ante ello, el gobierno peruano y sus instituciones tienen plena obligaci\u00f3n de velar por la seguridad de los manifestantes, sean adultos o infantes y adolescentes.<\/p>\n<p>El Ministerio de Interior (al mando de la Polic\u00eda Nacional del Per\u00fa), el Ministerio de Defensa (a cargo de los soldados replegados en las provincias que presentan mayor grado de conflictividad) y, por supuesto, el Ministerio de la Mujer y Poblaciones Vulnerables deben situar correctamente el problema y no delegarlo en la cuidadora. Hist\u00f3ricamente, las mujeres han asumido el rol de madres, evitando que puedan ejercer otro rol de vida y adjudicando toda la responsabilidad de las infancias sobre ellas. De modo que, los esfuerzos a nivel internacional han apuntado a compatibilizar diversos \u00e1mbitos de desarrollo de la mujer. El gobierno peruano no puede desconocer aquello.<\/p>\n<p>Finalmente, resulta preciso recordar a mujeres que han cumplido un rol activo durante el periodo de inestabilidad pol\u00edtica. Solo para mencionar un ejemplo destacable de solidaridad y empat\u00eda, la cantante <strong>Yarita Lizeth<\/strong> ofreci\u00f3 el bus de su grupo musical para que los manifestantes en Juliaca (Puno) pudieran unirse a la gran protesta denominada \u201cToma de Lima\u201d del mes de enero [4]. No obstante, , la Fiscal\u00eda ha abierto, recientemente, un caso para investigarla por dicha colaboraci\u00f3n [5], lo cual ha dejado un nuevo disgusto en la poblaci\u00f3n peruana acerca de c\u00f3mo funcionan las instituciones que los representan.<\/p>\n<\/div>\n<p><strong><em>Mayra Alejandra Hinostroza Cute<\/em><br \/>\n<\/strong>Integrante<strong><br \/>\n<\/strong>Centro de Estudios en G\u00e9nero(s) y Relaciones Internacionales (CeGRI)<br \/>\nIRI-UNLP<\/p>\n<p><span style=\"font-size: 10pt;\"><strong>Notas<\/strong><\/span><br \/>\n<span style=\"font-size: 10pt;\">[1] Pronunciamiento del Ministerio de la Mujer y Poblaciones Vulnerables. <em>04 de marzo de 2023<\/em>. Fuente: <a href=\"https:\/\/twitter.com\/MimpPeru\/status\/1632063867940380672\">MIMP Twitter<\/a><\/span><br \/>\n<span style=\"font-size: 10pt;\">[2] El poder m\u00e1gico de la Lliclla. <em>03 de agosto de 2020<\/em>. <a href=\"https:\/\/www.canalipe.tv\/noticias\/padres\/el-poder-magico-de-lliclla\">Canal IPE<\/a><\/span><br \/>\n<span style=\"font-size: 10pt;\">[3] Investigar\u00e1n a polic\u00edas que lanzaron gas lacrim\u00f3geno a ni\u00f1os y mujeres aymaras. 04 de marzo de 2023. <a href=\"https:\/\/elbuho.pe\/2023\/03\/investigaran-a-policias-que-lanzaron-gas-lacrimogeno-a-ninos-y-mujeres-aymaras-video\/\">El B\u00faho<\/a><\/span><br \/>\n<span style=\"font-size: 10pt;\">[4]YaritaLizeth apoy\u00f3 con su bus a manifestantes que viajan de Juliaca a Lima. <em>17 de enero de 2023<\/em>. <a href=\"https:\/\/larepublica.pe\/espectaculos\/2023\/01\/17\/yarita-lizeth-apoyara-con-su-bus-para-el-traslado-de-manifestantes-que-viajan-de-juliaca-a-lima-protestas-en-puno-lrsd\">La Rep\u00fablica<\/a><\/span><br \/>\n<span style=\"font-size: 10pt;\">[5] Fiscal\u00eda pone en la mira a cantante YaritaLizeth por apoyar a los manifestantes que vinieron a la \u201cToma de Lima\u201d. <em>03 de marzo de 2023<\/em>. <a href=\"https:\/\/limagris.com\/fiscalia-pone-en-la-mira-a-cantante-yarita-lizeth-por-apoyar-a-los-manifestantes-que-vinieron-a-la-toma-de-lima\/\">Lima Gris<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto de Relaciones Internacionales desea hacer llegar su reconocimiento a todas las Mujeres en el d\u00eda su conmemoraci\u00f3n, en el entendimiento de que no se trata de un d\u00eda de festejo sino de reflexi\u00f3n por las luchas dadas y por las luchas que ellas y las sociedades en su conjunto tendr\u00e1n que enfrentar. Por [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":21671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[34],"tags":[430,374,941,1147,439,253],"class_list":["post-26462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones-iri","tag-8m","tag-genero","tag-inestabilidad-politica","tag-opcegri","tag-peru","tag-violencia","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",600,160,false],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",375,100,false],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",720,192,false],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false]},"uagb_author_info":{"display_name":"Candela","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/candela\/"},"uagb_comment_info":0,"uagb_excerpt":"El Instituto de Relaciones Internacionales desea hacer llegar su reconocimiento a todas las Mujeres en el d\u00eda su conmemoraci\u00f3n, en el entendimiento de que no se trata de un d\u00eda de festejo sino de reflexi\u00f3n por las luchas dadas y por las luchas que ellas y las sociedades en su conjunto tendr\u00e1n que enfrentar. Por&hellip;","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/26462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=26462"}],"version-history":[{"count":10,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/26462\/revisions"}],"predecessor-version":[{"id":30056,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/26462\/revisions\/30056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/21671"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=26462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=26462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=26462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}