{"id":31191,"date":"2023-09-22T15:47:30","date_gmt":"2023-09-22T18:47:30","guid":{"rendered":"https:\/\/www.iri.edu.ar\/?p=31191"},"modified":"2024-08-09T14:35:47","modified_gmt":"2024-08-09T17:35:47","slug":"31191","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2023\/09\/22\/31191\/","title":{"rendered":"Apuntes sobre la compleja maquinaria de la pol\u00edtica exterior china por Gustavo Ng"},"content":{"rendered":"<p class=\"departamento\">Departamento de Asia y el Pac\u00edfico<br \/>\nCentro de Estudios Chinos<\/p>\n<h6><a name=\"_Toc146111567\"><\/a><a name=\"_Toc146022701\"><\/a><a name=\"_Toc146017645\"><\/a>Art\u00edculos<\/h6>\n<h1><a name=\"_Toc146111568\"><\/a><a name=\"_Toc146017646\"><\/a>Apuntes sobre la compleja maquinaria de la pol\u00edtica exterior china<\/h1>\n<p><strong><em>Gustavo Ng<a href=\"#_ftn1\" name=\"_ftnref1\"><sup>[1]<\/sup><\/a><\/em><\/strong><\/p>\n<p>China siempre conserva algo del pasado, de modo que su presente est\u00e1 recargado de fragmentos de los siglos de dinast\u00edas, rutas comerciales, inventos destinados a hacer revoluciones, guerras y paz. En cada momento, esa m\u00e1quina del presente que funciona con piezas de todos los tiempos, adquiere una forma diferente. Cada forma rescata determinadas piezas, les asigna diferentes funciones y valores; algunas piezas son descartadas, otras que estaban guardadas son repuestas, y la metamorfosis tiene diferentes ritmos, direcciones diversas, motivaciones particulares, acomod\u00e1ndose a las condiciones externas e internas.<\/p>\n<p>Un ejemplo de esta compleja estrategia son las posiciones que tiene China frente a los dem\u00e1s pa\u00edses. En cada etapa hist\u00f3rica, ha armado una pol\u00edtica exterior con determinadas posiciones, algunas antiguas, cultivadas con los siglos, y otras innovadoras. A continuaci\u00f3n revisaremos algunas de las posiciones que componen la pol\u00edtica exterior actual del pa\u00eds asi\u00e1tico.<\/p>\n<h2>Un pa\u00eds que a\u00fan no ha alcanzado el desarrollo de otros<\/h2>\n<p>El canciller Wang Yi aclar\u00f3 en un evento organizado por el Centro de Pol\u00edtica Europea en 2019 que China se ubica por debajo del puesto 80 en el \u00cdndice de Desarrollo Humano y est\u00e1 rezagada en comparaci\u00f3n a los pa\u00edses desarrollados en materia de ciencia, tecnolog\u00eda y educaci\u00f3n.<\/p>\n<p>Tambi\u00e9n advirti\u00f3 que el desarrollo desequilibrado e inadecuado sigue siendo un enorme desaf\u00edo para China, y a\u00fan queda por terminar el proceso de industrializaci\u00f3n.<\/p>\n<h2>El pa\u00eds m\u00e1s grande en la historia de la Humanidad<\/h2>\n<p>Una colaboraci\u00f3n en Wikipedia sobre los imperios en la historia presenta a China con una regularidad que, sumadas las apariciones, impacta como la naci\u00f3n (entre las actuales) que mayor poder tuvo. En la lista de los imperios que controlaron mayor superficie, est\u00e1n los imperios Xiong, Tibetano y Mongol, las dinast\u00edas Qing, Ming, Shang, Sui, Jin, Liao, Zhao, Wei, Wu, Han del Este y del Oeste, Song, Tang, Qin y Yuan, el Estado de Xianbei, los kanatos Uigur y Chagatai y otros que forman parte de la China de hoy. La dinast\u00eda Xia ya era imperio en el a\u00f1o 1800 a.C.<\/p>\n<p>Entre los diez imperios m\u00e1s poblados, ocho pertenecen total o parcialmente a la China de hoy: la dinast\u00eda Qing, que concentra el 37% de la poblaci\u00f3n mundial en el siglo XIX, la Song del Norte (33% en el siglo XII), Han del Oeste (32%, en el primer siglo de la era cristiana), el imperio Mongol (31% en el siglo XIII), las dinast\u00edas Jin, Ming, Qin (24% en el 220 a.C.) y la Tang.<\/p>\n<h2>Acepta las reglas del juego que otros han creado<\/h2>\n<p>Sin abandonar el socialismo, China comenz\u00f3 a fines de la d\u00e9cada de 1970 su proceso de Reforma y Apertura, que signific\u00f3 entrar a participar en el juego econ\u00f3mico mundial, que ten\u00eda la forma del neoliberalismo. Entre las materializaciones de esta participaci\u00f3n estuvo el ingreso de China a la Organizaci\u00f3n Mundial del Comercio en diciembre de 2001. Aunque muchos otros miembros se han ido quejando de que China ha transgredido, relativizado o violado normas, los reclamos pertenecen a las negociaciones por las que transcurre el comercio planetario, y son constantes entre todos los miembros. Ante una situaci\u00f3n concreta, el a\u00f1o pasado Gao Feng, portavoz del Ministerio de Comercio, reiter\u00f3 por en\u00e9sima vez que \u201cel Gobierno chino siempre ha respetado las normas de la OMC y ha gestionado su comercio exterior de acuerdo con ellas\u201d, en respuesta al reciente establecimiento por parte de la OMC de un panel para resolver disputas.<\/p>\n<h2>Principio de no injerencia en asuntos internos<\/h2>\n<p>China se atiene de modo inamovible al principio de no injerencia en los asuntos internos de otros pa\u00edses, no interfiriendo en nada en otros estados y no permitiendo la interferencia en sus asuntos (lo que en \u00faltima instancia genera conceptos que son principios universales a los que se les agregan peculiaridades chinas, como \u201csocialismo con peculiaridades china\u201d o \u201cvalores asi\u00e1ticos\u201d por derechos humanos).<\/p>\n<p>A fines del a\u00f1o pasado, poco despu\u00e9s de que se llevara a cabo la \u00abCumbre de las Democracias\u00bb convocada por el presidente norteamericano, Joe Biden, el Gobierno chino public\u00f3 el libro blanco (suerte de visi\u00f3n oficial y gu\u00eda para funcionarios y miembros del Partido Comunista Chino) \u201cChina: una democracia que funciona\u201d.<\/p>\n<h2>Por su propio peso, acaba imponiendo reglas<\/h2>\n<p>En Am\u00e9rica Latina tenemos casos como el de la central hidroel\u00e9ctrica de Belo Monte, en el Amazonas brasile\u00f1o, construida por la empresa china State Grid, que ha sido objeto de una investigaci\u00f3n por parte de la Comisi\u00f3n Interamericana de Derechos Humanos, acusada de da\u00f1os ambientales y violaci\u00f3n de los derechos de los ind\u00edgenas. Li Ming, del Departamento de Cooperaci\u00f3n Internacional de State Grid nos asegur\u00f3 que en este momento la empresa \u201cbusca mantener una actitud abierta a todos los \u00e1mbitos de la sociedad brasile\u00f1a\u201d.<\/p>\n<p>Por su parte, el profesor asociado del Centro de Estudios sobre Am\u00e9rica Latina de la Universidad de Ciencia y Tecnolog\u00eda del Sudoeste,\u00a0 Zhongzhou Cui, ha explicado que \u201cChina no contaba con pol\u00edticas y leyes bien establecidas para tratar las cuestiones medioambientales hasta hace poco\u201d, y a\u00f1adi\u00f3 que \u201cOccidente y los pa\u00edses latinoamericanos tienen expectativas demasiado altas para los inversores chinos a la hora de tratar las cuestiones medioambientales\u201d.<\/p>\n<p>En este sentido, indic\u00f3 que durante 35 a\u00f1os su pa\u00eds dio prioridad al desarrollo econ\u00f3mico sobre la protecci\u00f3n del medioambiente, por lo que \u201clos inversores chinos no ganaron suficiente experiencia para tratar los problemas medioambientales, ya que ten\u00edan una demanda muy alta de logros econ\u00f3micos por parte de los niveles superiores del gobierno\u201d.<\/p>\n<p>Otro caso similar es el de la represa Coca-Codo Sinclair en Ecuador, el mayor proyecto energ\u00e9tico del pa\u00eds, en el que el Banco de Exportaci\u00f3n e Importaci\u00f3n de China invirti\u00f3 2.240 millones de d\u00f3lares y la obra estuvo a cargo de SinoHydro. La construcci\u00f3n recibi\u00f3 denuncias de corrupci\u00f3n, sobrecostos y un accidente en el que murieron 14 trabajadores.<\/p>\n<h2>Cooperaci\u00f3n horizontal<\/h2>\n<p>Abundan los proyectos de cooperaci\u00f3n con pa\u00edses como Rusia (ventas rusas de hidrocarburos, por exportaciones chinas de productos industrializados) o Alemania, pa\u00eds con el que hace dos meses firm\u00f3 diez proyectos en el Di\u00e1logo Jiangsu-Alemania 2022, que involucran medicina, veh\u00edculos el\u00e9ctricos inteligentes, fabricaci\u00f3n de equipos y nuevos materiales.<\/p>\n<h2>Iniciativas<\/h2>\n<p>Entre la cooperaci\u00f3n horizontal y las posiciones en las que hace valer su peso, China ofrece iniciativas, invitando a proyectos conjuntos.<\/p>\n<p>La madre de las propuestas es la Iniciativa de la Franja y la Ruta, BRI, que en un primer momento fue presentada como un plan de China para la conexi\u00f3n log\u00edstica con los pa\u00edses vecinos para ir transform\u00e1ndose en una convocatoria abierta a las ideas y condiciones de los participantes. Fue convirti\u00e9ndose en algo amplio, con un cariz filos\u00f3fico de \u201cempecemos a construir un mundo multilateral\u201d. Tan amplia, la iniciativa puede ser materializada de cualquier modo concertado, y dar lugar a una multiplicidad de mecanismos.<\/p>\n<h2>Amabilidad para una Comunidad de Destino Compartido<\/h2>\n<p>Es maciza la determinaci\u00f3n de China de amabilidad y b\u00fasqueda de coincidencias para una relaci\u00f3n fruct\u00edfera con todos los pa\u00edses de la Tierra.<\/p>\n<p>Se espera que el XX Congreso Nacional del Partido Comunista Chino (PCCh) que tendr\u00e1 lugar en las pr\u00f3ximas semanas, consagre por tercer t\u00e9rmino consecutivo a Xi Jinping como secretario general, lo que anticipar\u00e1 su tercer per\u00edodo como presidente de la Naci\u00f3n desde el 2023. En este sentido, el congreso tambi\u00e9n servir\u00e1 como reafirmaci\u00f3n e impulso de la proyecci\u00f3n del jefe de Estado chino como l\u00edder mundial, lo que se corresponde con el lugar que ocupa China en el mundo. Xi Jinping se presenta en todo el orbe con su propuesta de una Comunidad de Destino Compartido. Lo dijo con estas palabras en la Reuni\u00f3n Conmemorativa con Motivo del 50\u00ba Aniversario de la restauraci\u00f3n de China en la ONU: \u201cHay que impulsar mancomunadamente la construcci\u00f3n de una comunidad de destino com\u00fan de la humanidad, para construir conjuntamente un mundo que goce de una paz duradera, de una seguridad universal y de la prosperidad com\u00fan, y que sea abierto, inclusivo, limpio y hermoso. Los seres humanos deben unirse para superar codo con codo los momentos dif\u00edciles, y convivir de forma armoniosa.<\/p>\n<p>Fomentar la construcci\u00f3n de una comunidad de destino com\u00fan de la humanidad no es sustituir un sistema por otro, ni reemplazar una civilizaci\u00f3n con otra, sino que significa la vinculaci\u00f3n de los intereses, la compartici\u00f3n de los derechos y la asunci\u00f3n conjunta de las responsabilidades por parte de los pa\u00edses con distintos sistemas sociales, diferentes ideolog\u00edas, historias y culturas dis\u00edmiles, y niveles de desarrollo no iguales, en los asuntos internacionales, formando de esta manera el mayor divisor com\u00fan con respecto a la construcci\u00f3n conjunta de un buen mundo\u201d.<\/p>\n<h2>El Pa\u00eds del Centro<\/h2>\n<p>China tambi\u00e9n se planta como el Pa\u00eds del Centro, de fuerza centr\u00edpeta. Si los dem\u00e1s quieren relacionarse con China, China analizar\u00e1 la propuesta.<\/p>\n<p>Esta pieza parece haber sido cuidadosamente desactivada desde el comienzo del proceso de Apertura y Reforma y cualquier idea de desacoplamiento de China es sistem\u00e1ticamente negada por los funcionarios del Gobierno. Sin embargo, el a\u00f1o pasado el primer ministro Li Keqiang, debi\u00f3 asegurar que nadie \u201cquiere ni puede cerrar la puerta\u201d.<\/p>\n<p>El reflejo de no seguir promoviendo el amiguismo internacional es claramente alimentado por la hostilidad norteamericana. Los insultos y bravuconadas de Donald Trump, sostenidas por Joe Biden, son sentidos como una traici\u00f3n a la buena disposici\u00f3n hacia los Estados Unidos, que incluy\u00f3 la admiraci\u00f3n de la poblaci\u00f3n china.<\/p>\n<p>Ya en 1991, Wang Huning, asesor ideol\u00f3gico del presidente Xi Jinping y miembro del Politbur\u00f3, escribi\u00f3 \u201cAm\u00e9rica contra Am\u00e9rica\u201d, obra de la que se destaca su poder predictivo de la actual crisis del pa\u00eds que busca con insistencia provocar alg\u00fan tipo de conflicto con China. Estos d\u00edas el diario chino Global Times inform\u00f3 de \u201cun delegado al Congreso Popular de la Naci\u00f3n\u201d (a quien no identifica) sugiri\u00f3 que las escuelas dejen de ense\u00f1ar ingl\u00e9s para \u201cofrecerle a los chicos m\u00e1s cultura tradicional china en un momento cr\u00edtico de la formaci\u00f3n de su visi\u00f3n del mundo, y para incrementar su orgullo cultural en una edad temprana\u201d.<\/p>\n<h2>Defensa confrontativa<\/h2>\n<p>Una parte de la diplomacia china responde con firmeza, sin rehuir la confrontaci\u00f3n ni temer el conflicto.<\/p>\n<p>Se trata de una tesitura relativamente reciente, protagonizada por diplom\u00e1ticos de la nueva generaci\u00f3n, que han decidido no quedarse callados ante las ofensas gratuitas por parte de los Estados Unidos y sus aliados. Portavoces de la Canciller\u00eda como Zhao Lijian y Hua Chunyin usan redes sociales occidentales no s\u00f3lo para contener y repeler la lluvia de campa\u00f1as contrarias a China, sino para denunciar las contradicciones y los atropellos del gobierno norteamericano contra otros pa\u00edses y contra su propia poblaci\u00f3n.<\/p>\n<p>Todas estas posiciones arman un sistema que es la plataforma de la pol\u00edtica exterior china. El pensamiento occidental, que tiende al primitivismo de la l\u00f3gica que excluye \u2014si es A no es B\u2014, es un modo poco \u00fatil para comprender la intrincada maquinaria diplom\u00e1tica china.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><sup>[1]<\/sup><\/a> Integrante del Centro de Estudios Chinos (IRI-UNLP).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Gustavo Ng<\/p>\n","protected":false},"author":5,"featured_media":29328,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"anuario","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[1041,1075],"class_list":["post-31191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-a2023","tag-a2023cechinoart","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT-600x200.png",600,200,true],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT-375x200.png",375,200,true],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT-720x200.png",720,200,true],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2023\/08\/a2023FEAT.png",750,200,false]},"uagb_author_info":{"display_name":"Juana Alvarez Eiras","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/juana-alvarez-eiras\/"},"uagb_comment_info":0,"uagb_excerpt":"por Gustavo Ng","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/31191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=31191"}],"version-history":[{"count":3,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/31191\/revisions"}],"predecessor-version":[{"id":36738,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/31191\/revisions\/36738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/29328"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=31191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=31191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=31191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}