{"id":33750,"date":"2023-12-27T10:27:30","date_gmt":"2023-12-27T13:27:30","guid":{"rendered":"https:\/\/www.iri.edu.ar\/?p=33750"},"modified":"2024-09-03T13:00:23","modified_gmt":"2024-09-03T16:00:23","slug":"algunas-reflexiones-sobre-la-vigesima-octava-conferencia-de-las-partes-de-la-convencion-marco-de-las-naciones-unidas-sobre-cambio-climatico","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2023\/12\/27\/algunas-reflexiones-sobre-la-vigesima-octava-conferencia-de-las-partes-de-la-convencion-marco-de-las-naciones-unidas-sobre-cambio-climatico\/","title":{"rendered":"Algunas reflexiones sobre la Vig\u00e9sima Octava Conferencia de las Partes de la Convenci\u00f3n Marco de las Naciones Unidas sobre Cambio Clim\u00e1tico"},"content":{"rendered":"<p>La Vig\u00e9sima Octava Conferencia de las Partes (COP28) de la Convenci\u00f3n Marco de las Naciones Unidas sobre Cambio Clim\u00e1tico (CMNUCC) se desarroll\u00f3 desde el 30 de noviembre hasta el 13 de diciembre en Dubai, Emiratos \u00c1rabes Unidos (EAU).<\/p>\n<p>En esta COP se concret\u00f3 un paquete de decisiones y declaraciones conocido como el Consenso de los Emiratos \u00c1rabes Unidos, siendo sus principales resultados: la operacionalizaci\u00f3n del Fondo para P\u00e9rdidas y Da\u00f1os acordado en la COP27, el cierre del primer ciclo del Balance Mundial (GST); la adopci\u00f3n de un marco para la Meta Global de Adaptaci\u00f3n (GGA), as\u00ed como un programa de trabajo sobre Transici\u00f3n Justa.<\/p>\n<p>Tambi\u00e9n se adoptaron algunas declaraciones como el Compromiso Global de Energ\u00edas Renovables y Eficiencia Energ\u00e9tica; la Declaraci\u00f3n sobre agricultura sostenible, sistemas alimentarios resilientes y acci\u00f3n clim\u00e1tica; la Declaraci\u00f3n sobre Clima y Salud; la Declaraci\u00f3n de los L\u00edderes de los EAU sobre un Marco Global de Financiaci\u00f3n Clim\u00e1tica; entre otras.<\/p>\n<p>En esta oportunidad me referir\u00e9 a dos procesos y temas de agenda de las negociaciones clim\u00e1ticas que culminaron en la COP28: la adopci\u00f3n de un marco para la GGA y la finalizaci\u00f3n del primer ciclo del GST, que resultan de suma relevancia para el camino a seguir en t\u00e9rminos de acci\u00f3n clim\u00e1tica global.<\/p>\n<p>La Meta Global de Adaptaci\u00f3n nace con el Acuerdo de Par\u00eds (AP). En su art\u00edculo 2.b, establece que el AP tiene por objeto \u201caumentar la capacidad de adaptaci\u00f3n a los efectos adversos del cambio clim\u00e1tico y promover la resiliencia al clima y un desarrollo con bajas emisiones de gases de efecto invernadero, de un modo que no comprometa la producci\u00f3n de alimentos\u201d. A su vez, el art. 7.1, fija el objetivo mundial relativo a la adaptaci\u00f3n, con sus tres componentes: \u201caumentar la capacidad de adaptaci\u00f3n, fortalecer la resiliencia y reducir la vulnerabilidad al cambio clim\u00e1tico con miras a contribuir al desarrollo sostenible y lograr una respuesta de adaptaci\u00f3n adecuada en el contexto del objetivo referente a la temperatura que se menciona en el art\u00edculo 2\u201d.<\/p>\n<p>En este sentido, uno de los grandes desaf\u00edos sigue siendo encontrar una manera adecuada de medir el progreso global de los esfuerzos en adaptaci\u00f3n a la luz de las circunstancias nacionales y las diferentes capacidades de los Estados. Esta tarea, iniciada en 2016 con la adopci\u00f3n del AP, esperaba ser resuelta este a\u00f1o, pero qued\u00f3 inconclusa.<\/p>\n<p>Un primer obst\u00e1culo tiene que ver con la misma esencia de lo que implica pensar e implementar la adaptaci\u00f3n, es decir, es una dimensi\u00f3n del cambio clim\u00e1tico que depende de m\u00faltiples factores, algunos de ellos a escala local y sobre la cual no existe una m\u00e9trica universal, como s\u00ed sucede en el caso de la mitigaci\u00f3n, cuya base para la acci\u00f3n clim\u00e1tica se estructura en torno a las emisiones de gases de efecto invernadero (GEIs). Por otro lado, la vulnerabilidad tambi\u00e9n constituye un aspecto diferencial entre los Estados, as\u00ed como los recursos y capacidades que ellos poseen para hacer frente al cambio clim\u00e1tico. En consecuencia, se complejiza la definici\u00f3n de un \u00fanico indicador para cuantificar el progreso de los esfuerzos de adaptaci\u00f3n a nivel global<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Adem\u00e1s de que es necesario un di\u00e1logo entre escalas y entre m\u00faltiples indicadores para alcanzar una dimensi\u00f3n real de la adaptaci\u00f3n.<\/p>\n<p>Una herramienta clave fue la adopci\u00f3n del Programa de Trabajo Bienal de Glasgow-Sharm El Sheikh sobre el Objetivo Mundial de Adaptaci\u00f3n (GlaSS) cuyo objetivo consist\u00eda en mejorar el entendimiento, conceptualizar y en \u00faltima instancia alcanzar la meta del Acuerdo de Par\u00eds sobre la GGA. En la COP27 Argentina, en nombre de ABU (grupo de negociaci\u00f3n que nuclea a Argentina, Brasil y Uruguay), propuso la elaboraci\u00f3n de un marco para la GGA, el cual luego de los ocho talleres t\u00e9cnicos del GlaSS, adquiri\u00f3 una estructurada mejorada. A esta propuesta se sum\u00f3 posteriormente AILAC y, luego, el G77 m\u00e1s China<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>.<\/p>\n<p>En las negociaciones de la COP28, el borrador de la propuesta que deb\u00eda adoptarse al interior del G77 m\u00e1s China, estaba conformado por una serie de apartados como: prop\u00f3sito; principios; <em>overarching layer<\/em>; dimensiones, temas, consideraciones transversales, fuentes y <em>targets<\/em>; indicadores; medios de implementaci\u00f3n; <em>enablers; further work<\/em>; v\u00ednculo con el GST; cooperaci\u00f3n internacional y rol de las partes interesadas y; provisiones presupuestarias.<\/p>\n<p>Durante los trece d\u00edas de negociaciones no fue posible acordar un borrador de texto de decisi\u00f3n lo suficientemente s\u00f3lido en cuanto a <em>targets<\/em>, ya que solo se incluyeron aquellos asociados al ciclo iterativo de pol\u00edtica de adaptaci\u00f3n y no a los temas como agua, agricultura, salud, biodiversidad y ecosistemas, entre otros. Asimismo, los principios que forman parte de la arquitectura clim\u00e1tica desde 1992 como el de las responsabilidades comunes pero diferenciadas (CBDR) no aparece en la decisi\u00f3n final de la GGA. La elaboraci\u00f3n de los indicadores no pudo terminarse durante los dos a\u00f1os de duraci\u00f3n del GlaSS, dando lugar a la adopci\u00f3n de una decisi\u00f3n en esta COP para la creaci\u00f3n de un programa de trabajo que se hiciera cargo de esta tarea.<\/p>\n<p>En general, las discusiones estuvieron mayormente centradas en cuestiones procedimentales atinentes a las negociaciones <em>per se<\/em> en detrimento de las cuestiones sustantivas del borrador de la decisi\u00f3n. Particularmente, la falta de una posici\u00f3n com\u00fan del G77 m\u00e1s China frente a lo que deb\u00eda contener el marco y el lenguaje de \u00e9ste, dificult\u00f3 el proceso negociador durante la fase de Alto Nivel. Si bien esta COP result\u00f3 en una decisi\u00f3n sobre la GGA, bajo el nombre de Marco de los Emiratos para la Resiliencia Clim\u00e1tica Global, la misma estuvo por debajo de las expectativas y de lo que realmente se requiere para alcanzar los objetivos del AP.<\/p>\n<p>Otro de los procesos m\u00e1s relevantes para esta COP fue el cierre del primer ciclo del Balance Mundial, el cual est\u00e1 establecido en el AP en su art\u00edculo 14, siendo el a\u00f1o 2019 el punto de partida del proceso del GST a partir de la decisi\u00f3n 19\/CMA.1. Esta decisi\u00f3n establece que el Balance tiene como principal objetivo la evaluaci\u00f3n del progreso colectivo para mejorar la ambici\u00f3n clim\u00e1tica global, que deber\u00e1 realizarse de manera facilitadora cada cinco a\u00f1os y que cada ciclo tiene una duraci\u00f3n de dos a\u00f1os. A su vez, consta de tres fases: recopilaci\u00f3n de la informaci\u00f3n, evaluaci\u00f3n t\u00e9cnica y examen de los productos.<\/p>\n<p>Es importante que el ciclo del GST est\u00e9 alineado con el ciclo de informes del IPCC \u2013 que es una de sus principales fuentes de informaci\u00f3n- y con el ciclo de presentaciones de las Contribuciones Determinadas Nacionalmente (NDCs), para garantizar un mayor compromiso clim\u00e1tico de cada uno de los Estados. Este Balance se realiza teniendo en cuenta Mitigaci\u00f3n, Adaptaci\u00f3n y Medios de Implementaci\u00f3n \u2013 que incluye financiamiento, transferencia de tecnolog\u00eda y construcci\u00f3n de capacidades-.<\/p>\n<p>En estos a\u00f1os de trabajo sobre el GST pudieron concretarse las diferentes fases, dando como resultado una decisi\u00f3n final en esta COP. Un t\u00f3pico que se negoci\u00f3 en paralelo al GST fue la adopci\u00f3n de la GGA, ante lo cual se dificult\u00f3 tener claridad sobre este \u00faltimo t\u00f3pico en el texto final de la decisi\u00f3n del GST. Durante las negociaciones en Dubai, las Partes y los grupos de negociaci\u00f3n presentaron sus posiciones y aportes para mejorar el texto borrador. Sin embargo, algunos debates no cerrados volv\u00edan a resurgir, como la necesidad de equiparar adaptaci\u00f3n con mitigaci\u00f3n en t\u00e9rminos de financiamiento y acci\u00f3n clim\u00e1tica; por otro lado, las circunstancias nacionales de cada uno de los Estados y las posiciones tradicionales de los grupos sobre ciertas cuestiones transversales como g\u00e9nero o derechos humanos. Una gran dificultad estuvo relacionada a la falta de claridad en el trabajo de los Co-Facilitadores, quienes no pudieron integrar las diversas posiciones y miradas de las Partes y los grupos. Esto fue un reclamo constante de las Partes y Grupos durante los plenarios de esta COP.<\/p>\n<p>Aunque la decisi\u00f3n final del GST incluye secciones relativas a mitigaci\u00f3n, adaptaci\u00f3n, medios de implementaci\u00f3n, medidas de respuesta, p\u00e9rdidas y da\u00f1os, cooperaci\u00f3n internacional, entre otras; a\u00fan resta avanzar en el consenso sobre aspectos fundamentales si se quiere cumplir con el Acuerdo de Par\u00eds. En este sentido, otra cuesti\u00f3n que no alcanz\u00f3 las expectativas fue la inclusi\u00f3n de una cl\u00e1usula de <em>phase out<\/em>, es decir, de eliminaci\u00f3n total de los combustibles f\u00f3siles. Lo que se pudo incorporar fue la eliminaci\u00f3n gradual de los mismos, que no es consistente con lo que se requiere para alcanzar los escenarios m\u00e1s benignos propuestos por el IPCC.<\/p>\n<p>La COP28 nos present\u00f3 una serie de desaf\u00edos de los cuales salimos airosos en cierta medida. El primer d\u00eda de negociaci\u00f3n se adopt\u00f3 la decisi\u00f3n que operacionalizaba el Fondo espec\u00edfico para P\u00e9rdidas y Da\u00f1os. Tambi\u00e9n se hizo eco de una serie de declaraciones muy relevantes y decisiones que eran necesarias para continuar con el proceso negociador y el fortalecimiento de la arquitectura clim\u00e1tica. No obstante, la ambici\u00f3n y la calidad de los acuerdos que se esperaban no estuvieron a la altura de la urgencia que nos presenta el cambio clim\u00e1tico. La ventana de oportunidad se est\u00e1 cerrando con rapidez, y la calidad de los compromisos de cada uno de los gobiernos del mundo se dirigen en sentido opuesto.<\/p>\n<p style=\"text-align: right;\"><strong><em>Susana Beatriz Zazzarini<\/em><\/strong><br \/>\nDepartamento de Ambiente y Desarrollo<br \/>\nIRI-UNLP<\/p>\n<h6>Referencias<\/h6>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> En Argentina 1.5 se puede consultar toda una serie de informes t\u00e9cnicos y de pol\u00edtica sobre la Meta Global de Adaptaci\u00f3n: <a href=\"https:\/\/arg1punto5.com\/\">https:\/\/arg1punto5.com\/<\/a><\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Ver Informe T\u00e9cnico N\u00b02 de Argentina 1.5 en <a href=\"https:\/\/arg1punto5.com\/index.php\/2023\/07\/28\/el-marco-del-objetivo-mundial-de-adaptacion-como-modo-de-evaluar-el-progreso-y-de-promover-accion-y-apoyo-a-largo-plazo\/\">https:\/\/arg1punto5.com\/index.php\/2023\/07\/28\/el-marco-del-objetivo-mundial-de-adaptacion-como-modo-de-evaluar-el-progreso-y-de-promover-accion-y-apoyo-a-largo-plazo\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Susana Beatriz Zazzarini<\/p>\n","protected":false},"author":15,"featured_media":21671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[34],"tags":[1478,1155],"class_list":["post-33750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones-iri","tag-a2024opmedamb","tag-opmedam","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",600,160,false],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",375,100,false],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",720,192,false],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/02\/opinionesIRI-FEAT-750x200.png",750,200,false]},"uagb_author_info":{"display_name":"Noeli Scarpelli","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/noeli\/"},"uagb_comment_info":0,"uagb_excerpt":"por Susana Beatriz Zazzarini","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/33750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=33750"}],"version-history":[{"count":2,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/33750\/revisions"}],"predecessor-version":[{"id":36867,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/33750\/revisions\/36867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/21671"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=33750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=33750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=33750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}