{"id":41564,"date":"2025-08-21T14:22:07","date_gmt":"2025-08-21T17:22:07","guid":{"rendered":"https:\/\/www.iri.edu.ar\/?p=41564"},"modified":"2025-09-25T11:42:04","modified_gmt":"2025-09-25T14:42:04","slug":"la-beca-nasser-una-iniciativa-egipcia-para-el-liderazgo-internacional","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2025\/08\/21\/la-beca-nasser-una-iniciativa-egipcia-para-el-liderazgo-internacional\/","title":{"rendered":"La Beca Nasser: una iniciativa egipcia para el liderazgo internacional"},"content":{"rendered":"<p class=\"departamento\">Departamento de Medio Oriente<\/p>\n<h6>Art\u00edculos<\/h6>\n<h1>La Beca Nasser: una iniciativa egipcia para el liderazgo internacional<\/h1>\n<p class=\"autor\">Mar\u00eda Cecilia Civallero<a href=\"#_ftn1\" name=\"_ftnref1\"><sup><strong>[1]<\/strong><\/sup><\/a><\/p>\n<h2>1- Introducci\u00f3n<\/h2>\n<p>Este escrito se propone observar el despliegue de una pol\u00edtica p\u00fablica de la Rep\u00fablica \u00c1rabe de Egipto destinada a la promoci\u00f3n de la diplomacia juvenil y la profundizaci\u00f3n de las relaciones con los pa\u00edses del Sur Global. Se trata de la Beca Nasser para el Liderazgo Internacional, un programa que, durante el mes de mayo del a\u00f1o 2025, reuni\u00f3 a m\u00e1s de 160 j\u00f3venes provenientes de 84 pa\u00edses. A su vez, se destaca que, en su quinta edici\u00f3n, fue convocada bajo el lema \u201cEgipto y las Naciones Unidas: 80 a\u00f1os de representaci\u00f3n de los problemas del Sur Global\u201d, recibiendo el apoyo de esta organizaci\u00f3n internacional y el patrocinio del presidente egipcio, Abdel Fattah El-Sisi (Nasser, 2025).<\/p>\n<p>De esta forma, el objetivo es describir la ejecuci\u00f3n de esta iniciativa y comenzar a analizar de qu\u00e9 forma esta pretende contribuir a la proyecci\u00f3n regional e internacional de Egipto. Para esto, se propone observar el programa efectivamente impartido a lo largo de la beca (formado por actividades y conferencias), y las comunicaciones oficiales esbozadas por sus organizadores: el Ministerio de Juventud y Deportes, a cargo del Dr. Ashraf Sobhi, y el Foro Internacional Nasser (Nasser, 2025). La beca Nasser constituye una de las iniciativas del Foro Internacional Nasser, siendo esta una plataforma que tiene por fin apoyar y empoderar a la juventud y que fue fundada por un antrop\u00f3logo egipcio llamado Hassan Ghazaly.<\/p>\n<p>Consideramos que observar las caracter\u00edsticas de la beca en su quinta edici\u00f3n nos permite aproximarnos tanto a la imagen que las autoridades organizadoras desean proyectar sobre el Egipto actual, como a los valores que el pa\u00eds del Nilo decide promover en el escenario internacional. A su vez, creemos que no solo se trata del Ministerio de Juventud y Deportes: el gran involucramiento de diversas agencias y carteras de gobierno demuestran el aval e inter\u00e9s que la beca ha sabido concitar ante el Gobierno nacional.<\/p>\n<p>De esta forma, el programa de la beca revela los v\u00ednculos, agendas y acceso a informaci\u00f3n y espacios f\u00edsicos (accesos vedados para el com\u00fan de los egipcios, tal como era destacado por los participantes nativos) que posee el Ministerio organizador. As\u00ed lo indica la exposici\u00f3n brindada el tercer d\u00eda del programa por el primer ministro egipcio, Dr. Mostafa Madbouly, la visita al Centro de Correcci\u00f3n y Rehabilitaci\u00f3n en la ciudad 10 de Ramad\u00e1n o al Instituto de Estudios de Inteligencia, Ciencia y Seguridad (Intelligence Science and Security Studies Institute &#8211; ISSSI).<\/p>\n<h2>2- Caracter\u00edsticas y fundamentos del programa<\/h2>\n<p>Los antecedentes, objetivos y valores de la beca Nasser est\u00e1n expuestos de forma accesible en su p\u00e1gina web. La intenci\u00f3n, en el presente apartado, es acercar esa informaci\u00f3n disponible, poni\u00e9ndola en relaci\u00f3n con las actividades y contenidos efectivamente desplegados en su quinta edici\u00f3n en el corriente a\u00f1o.<\/p>\n<h3>Objetivos<\/h3>\n<p>Resumidamente, lo que busca esta iniciativa es capacitar a la juventud, ofreci\u00e9ndole \u201cdiversas formas de apoyo y formaci\u00f3n\u201d, con el fin de mejorar su capacidad de liderazgo. De esta forma, intenta \u201ccontribuir con los esfuerzos internacionales para el desarrollo\u201d, aprovechando \u201cla energ\u00eda y las ideas de los j\u00f3venes para lograr un desarrollo sostenible en sus comunidades\u201d. En este punto, esta iniciativa se asume como parte de los acuerdos y experiencias que persiguen estos mismos objetivos, tales como: \u201clas Resoluciones de las Naciones Unidas sobre la Juventud, la Visi\u00f3n 2030 de Egipto, la Agenda 2063 para \u00c1frica, el Marco de Cooperaci\u00f3n de las Naciones Unidas para el Desarrollo Sostenible, la asociaci\u00f3n Sur-Sur, la Carta Africana de la Juventud y los principios del Movimiento de Pa\u00edses No Alineados\u201d (en adelante, MPNA). A su vez, el programa busca centrarse \u201cen la transferencia de la experiencia egipcia de desarrollo\u201d a trav\u00e9s del establecimiento de instituciones y la construcci\u00f3n del \u201ccar\u00e1cter nacional\u201d (Nasser Forum, 2025).<\/p>\n<h3>Antecedentes<\/h3>\n<p>Con respecto a su trayectoria, se destaca que la beca se lanz\u00f3 en el a\u00f1o 2019, bajo los auspicios de la Oficina del Primer Ministro, estando destinada solamente a j\u00f3venes del continente africano. En aquel momento, Egipto ejerc\u00eda la presidencia de la Uni\u00f3n Africana e intentaba, con esta iniciativa, \u201ctransferir de forma tangible la experiencia egipcia en materia de desarrollo en el contexto de la activaci\u00f3n del concepto de cooperaci\u00f3n e integraci\u00f3n africanas, en el que Egipto desempe\u00f1a un papel destacado\u201d (Nasser Forum, 2025). Inmediatamente despu\u00e9s de esta primera edici\u00f3n, la beca recibi\u00f3 el patrocinio del presidente Abdel Fattah El-Sisi y ampli\u00f3 su convocatoria a j\u00f3venes de los continentes de Asia, Australia, Am\u00e9rica Latina y Europa, adem\u00e1s del continente africano. Esto ha permitido la participaci\u00f3n de una mayor cantidad de j\u00f3venes, en 2021, 2022 y 2023, ediciones que adoptaron lemas vinculados con la cooperaci\u00f3n sur-sur y el Movimiento y Organizaci\u00f3n de J\u00f3venes no Alineados<a href=\"#_ftn2\" name=\"_ftnref2\"><sup>[2]<\/sup><\/a>.<\/p>\n<h3>Mecanismos de evaluaci\u00f3n y selecci\u00f3n de los becarios<\/h3>\n<p>En cuanto a los mecanismos de evaluaci\u00f3n y selecci\u00f3n de los becarios, los criterios adoptados por sus organizadores pretenden ajustarse a los principios de justicia, equidad, transparencia e igualdad de oportunidades. As\u00ed, lo que se busca es reunir a un grupo de j\u00f3venes destacados y responsables en espacios de toma de decisiones en campos diversos, tanto del sector p\u00fablico como privado. Aunque esto no se aleja de las caracter\u00edsticas que suelen asumir programas de este estilo, en el caso de la beca Nasser, se expone que los principios de selecci\u00f3n deben estar alineados con la Visi\u00f3n 2030 de Egipto, los Objetivos de Desarrollo Sostenible (ODS) y las agendas continentales, regionales y globales con las que la Rep\u00fablica \u00c1rabe de Egipto est\u00e1 comprometida.<\/p>\n<p>Este sistema de selecci\u00f3n de participantes de 18 a 40 a\u00f1os, \u201cj\u00f3venes de \u00e9lite y l\u00edderes\u201d, pretende adem\u00e1s promover la innovaci\u00f3n en el liderazgo a trav\u00e9s de la igualdad de g\u00e9nero (asignando un 50% de participaci\u00f3n a cada uno), la inclusi\u00f3n (previendo un 5% para personas con discapacidad) y criterios clave vinculados a: la experiencia internacional de los aspirantes, la diversidad geogr\u00e1fica, su compromiso con \u201clos problemas del Sur Global\u201d y con proyectos con impacto social positivo, y la comprensi\u00f3n y apoyo del solicitante a cuestiones como \u201cel desarrollo sostenible, la mitigaci\u00f3n de la pobreza, la educaci\u00f3n inclusiva, la justicia clim\u00e1tica y la reducci\u00f3n de las desigualdades sociales y econ\u00f3micas\u201d(Nasser Forum, 2025).<\/p>\n<h3>El lema de la 5ta cohorte<\/h3>\n<p>Sumado a esto, cabe hacer una menci\u00f3n al lema escogido para la quinta cohorte: \u201cEgipto y las Naciones Unidas: 80 a\u00f1os de representaci\u00f3n de los problemas del Sur Global\u201d. De esta forma, las autoridades egipcias homenajean a esta organizaci\u00f3n por el 80 aniversario de su creaci\u00f3n y, a partir de all\u00ed, planifican un programa centrado en el rol de las Naciones Unidas y de Egipto en el \u00e1mbito multilateral. Antes de observar cu\u00e1les fueron las tem\u00e1ticas abordadas en las conferencias y los expositores, resulta interesante mencionar c\u00f3mo es descrito el v\u00ednculo entre Egipto y las Naciones Unidas en el sitio oficial de la beca: no solo se trata de un lazo de larga data, porque Egipto particip\u00f3 en su fundaci\u00f3n en 1945, sino que tambi\u00e9n este aniversario es relevante por el rol que este pa\u00eds construy\u00f3 \u201cdurante 80 a\u00f1os\u201d porque consideraba (y considera) que este \u00e1mbito multilateral le permite a los \u201cpa\u00edses en desarrollo\u201d defender sus \u201ccausas\u201d (Nasser Forum, 2025).<\/p>\n<p>Este entendimiento (y estrategia diplom\u00e1tica) deben pensarse a la par del rol que la naci\u00f3n del Nilo desempe\u00f1\u00f3 en relaci\u00f3n a los procesos independentistas de muchos pa\u00edses asi\u00e1ticos y africanos en las d\u00e9cadas de 1950 y 1960 (Civallero, 2021). Esto es ejemplificado en el sitio web haciendo alusi\u00f3n a que Egipto \u201cincluso lider\u00f3 intensos esfuerzos para apoyar a estos pa\u00edses dentro de la ONU antes de su independencia, enviando l\u00edderes nacionales desde El Cairo a Nueva York para presentar sus justas causas ante la Asamblea General\u201d reivindicando el principio de solidaridad entre ellos (Nasser Forum, 2025). A su vez, se afirma que a trav\u00e9s de ese esfuerzo Egipto ha logrado construir un Estado que \u201cequilibra el compromiso nacional con la apertura global, esforz\u00e1ndose por amplificar la voz del Sur Global y fortalecer la cooperaci\u00f3n entre sus miembros\u201d (Nasser Forum, 2025).<\/p>\n<p>As\u00ed, no solo la tem\u00e1tica de las Naciones Unidas estuvo presente gran parte del tiempo, sino que tambi\u00e9n funcionarios y representantes de esta organizaci\u00f3n intergubernamental conformaron los paneles de exposici\u00f3n y debate. Asimismo, estas alusiones al rol de Egipto en la ONU asumiendo la voz de los pa\u00edses ausentes o recientemente independizados, estuvo presente tambi\u00e9n en la conferencia brindada por el primer ministro y el canciller.<\/p>\n<h3>Participaci\u00f3n de Am\u00e9rica Latina<\/h3>\n<p>Otro aspecto a destacar de la edici\u00f3n 2025, tal como lo hicieron sus organizadores, fue el crecimiento de la participaci\u00f3n de becarios latinoamericanos. En un comunicado titulado \u201cParticipaci\u00f3n sin precedentes de Am\u00e9rica Latina\u201d (Nasser, 2025), se expone que esta ha alcanzado un \u201cr\u00e9cord hist\u00f3rico\u201d a partir de la postulaci\u00f3n de 42 hombres y mujeres oriundos de 14 pa\u00edses del continente, de los cuales superaron las pruebas representantes de 11 pa\u00edses (Nasser, 2025). A partir de esto, los organizadores afirman que esto se debe a \u201cla creciente importancia internacional de la beca\u201d y \u201cla confianza de la juventud latinoamericana en el papel fundamental de Egipto\u201d en el empoderamiento de los j\u00f3venes, en la promoci\u00f3n de la diplomacia juvenil y en la profundizaci\u00f3n de las asociaciones con los pa\u00edses del Sur Global. Adem\u00e1s, se se\u00f1ala que esta interacci\u00f3n con representantes de Am\u00e9rica Latina aporta una \u201cadici\u00f3n cualitativa a la beca\u201d, favoreciendo mayor \u201cdiversidad cultural y geogr\u00e1fica\u201d, y fortaleciendo la posici\u00f3n de Egipto como plataforma regional y global.<\/p>\n<h2>3- La agenda de la edici\u00f3n 2025<\/h2>\n<p>Con la intenci\u00f3n de organizar y simplificar la informaci\u00f3n sobre la agenda de la quinta edici\u00f3n de la beca Nasser, ser\u00e1n simplemente enumeradas las actividades realizadas, dividi\u00e9ndolas de la siguiente manera: a) actividades en sitios tur\u00edsticos; b) conferencias y workshops; c) visitas a sitios oficiales. De esta forma, se ofrece un panorama general para luego adentrarnos en el an\u00e1lisis de esta iniciativa haciendo foco en algunos momentos espec\u00edficos de esta agenda referidos a visitas a sitios oficiales.<\/p>\n<h3>a.\u00a0\u00a0\u00a0 Propuesta tur\u00edstica y cultural<\/h3>\n<p>Con respecto a la primera categor\u00eda, los sitios que la conformaron fueron: las Pir\u00e1mides de Giza, la Biblioteca de Alejandr\u00eda, la \u00d3pera de El Cairo, el Gran Museo Egipcio, el Complejo Religioso de El Cairo (formado por un templo jud\u00edo, iglesias coptas y mezquitas isl\u00e1micas), la Catedral de Abbassiya y una experiencia gastron\u00f3mica (un plato t\u00edpico llamado koshery) acompa\u00f1ada por un espect\u00e1culo art\u00edstico (danza t\u00edpica Mezmar y Tanoura). Estos sitios y destinos conforman un mapa fehaciente de la popularidad de Egipto como destino tur\u00edstico y la importancia que esto posee en la divulgaci\u00f3n de sus im\u00e1genes ancestrales y culturales.<\/p>\n<h3>b.\u00a0\u00a0 Conferencias y workshops<\/h3>\n<p>Con respecto al segundo \u00edtem, cabe se\u00f1alar que fueron organizadas en la sede de la beca, el Centro Ol\u00edmpico ubicado en el barrio de Maadi. A pesar de que en muchos casos las visitas a sitios oficiales tambi\u00e9n inclu\u00edan conferencias magistrales, y que en las brindadas en Maadi tambi\u00e9n asist\u00edan funcionarios p\u00fablicos de alto rango, se ha decidido diferenciarlas en este apartado por considerar que la visita le asigna un plus a la experiencia y que por eso se planific\u00f3 de esa manera, otorg\u00e1ndoles mayor relevancia. Por otro lado, cabe destacar que los expositores fueron, en todos los casos, personalidades destacadas con amplia trayectoria en su campo. Solo por mencionar algunos casos, se trat\u00f3 de ministros o ex ministros, embajadores, funcionarios de alto rango de organismos nacionales e internacionales, entre otros.<\/p>\n<p>As\u00ed, se transcriben a continuaci\u00f3n los t\u00edtulos de las conferencias brindadas:<\/p>\n<ul>\n<li>\u201cDeterminantes de la pol\u00edtica exterior egipcia en las Naciones Unidas\u201d<\/li>\n<li>\u201cPacto para el Futuro: Aspiraciones y ambiciones\u00bb<\/li>\n<li>\u201cEgipto y las Naciones Unidas: 80 a\u00f1os de fundaci\u00f3n y asociaci\u00f3n\u201d<\/li>\n<li>\u201cExperiencias del Di\u00e1logo Nacional\u201d<\/li>\n<li>\u201cEl rol de Egipto en las operaciones globales de <em>peacekeeping <\/em>y <em>peacebuilding<\/em>\u201d<\/li>\n<li>\u201cUmm Kulthum: 50 a\u00f1os de presencia y celebraci\u00f3n del legado de la legendaria Umm Kulthum\u201d<\/li>\n<li>\u201c70 a\u00f1os de la Conferencia de Bandung y la conformaci\u00f3n del Sur Global\u201d<\/li>\n<li>\u201cLa causa palestina\u201d<\/li>\n<li>\u201cLa imagen del Sur Global en el periodismo y en los medios de comunicaci\u00f3n internacionales\u201d<\/li>\n<li>\u201cJuventud y Diplomacia P\u00fablica: poder inteligente, eficacia e influencia\u201d<\/li>\n<li>\u201cIce-Breaking Workshop &amp; Networking\u201d (sesiones interactivas dise\u00f1adas para \u201cfomentar las conexiones, alentar el compromiso y crear un entorno c\u00f3modo para que los participantes se conozcan y establezcan relaciones profesionales\u201d).<\/li>\n<\/ul>\n<h3>c.\u00a0\u00a0\u00a0 Visitas a sitios oficiales<\/h3>\n<p>Con respecto a las visitas a sitios oficiales, y por cuestiones de espacio, estas ser\u00e1n enumeradas haci\u00e9ndose hincapi\u00e9 en algunas de ellas, consideradas las m\u00e1s relevantes. Al igual que fue destacado en el segundo \u00edtem, en la mayor\u00eda de los casos, los becarios fueron recibidos en dichos sitios por la autoridad de mayor rango, reflejando la importancia que estas carteras de gobierno u organismos p\u00fablicos le asignan a la beca.<\/p>\n<ul>\n<li><strong>Museo Gamal Abdel Nasser<\/strong>.<\/li>\n<\/ul>\n<p>El t\u00edtulo de la actividad fue \u201cGamal Abdel Nasser: presencia a pesar de la ausencia\u201d y las personalidades invitadas fueron: Adel El-Mahrouki en el rol de moderador (productor televisivo y periodista), Abdel Hakim Abdel Nasser (quinto hijo del ex presidente Gamal Abdel Nasser, ingeniero civil), Ahmed Khafagi (abogado y economista, diplom\u00e1tico de carrera especializado en tratados y acuerdos internacionales), Mohamed El Orabi (licenciado en Administraci\u00f3n de Empresas por la Universidad de El Cairo, exministro de Asuntos Exteriores, presidente del Consejo Egipcio de Asuntos Exteriores, entre muchos otros cargos parlamentarios y diplom\u00e1ticos), Mohamed Fayek (diplom\u00e1tico especializado en Derechos Humanos con amplia trayectoria en numerosos pa\u00edses; actualmente preside el Consejo Nacional de Derechos Humanos de Egipto y es vicepresidente del Comit\u00e9 Egipcio para la Solidaridad Afroasi\u00e1tica).<\/p>\n<p>En dichas exposiciones, existieron diversas alusiones al tipo de pol\u00edtica exterior que Egipto construy\u00f3 a lo largo de los a\u00f1os marcando el proceso del nasserismo como fundacional de muchas de sus facetas. En este marco, consideramos que un punto a destacar es la menci\u00f3n a la importancia asignada por Nasser a la pol\u00edtica exterior como un instrumento imprescindible para las naciones emergentes y, espec\u00edficamente, al v\u00ednculo con China que el l\u00edder egipcio construy\u00f3 en aquel momento. Sumado a esto, fue subrayado que \u201ctodos los africanos brindaban su apoyo para la independencia de los dem\u00e1s\u201d, y que Egipto lo hizo especialmente con aquellos que afrontaban la presencia colonial europea.<\/p>\n<ul>\n<li><strong>Nueva Capital Administrativa:<\/strong> encuentro con el primer ministro y el ministro de Relaciones Exteriores, Emigraci\u00f3n y Expatriados Egipcios.<\/li>\n<\/ul>\n<p>Esta actividad, titulada \u201cDeterminantes de la pol\u00edtica exterior egipcia en las Naciones Unidas\u201d, fue el evento de m\u00e1s alto nivel de la quinta cohorte y fue cubierto por la prensa (Ministerio de Juventud y Deportes, 2025). All\u00ed el primer ministro, Dr. Mostafa Madbouly, brind\u00f3 una conferencia y luego hizo lo mismo el canciller, Dr. Badr Abdelatty, quien adem\u00e1s respondi\u00f3 todas las preguntas existentes en la audiencia (formada \u00fanicamente por los becarios). Estas autoridades estuvieron acompa\u00f1adas por el ministro de Juventud y Deportes, Dr. Ashraf Sobhi, quien tambi\u00e9n brind\u00f3 unas palabras junto al canciller.<\/p>\n<p>Con respecto a las palabras proferidas por el primer ministro, <strong>Dr. Mostafa Madbouly<\/strong>, y considerando los objetivos de este escrito, se destacan las menciones realizadas sobre el rol mediador de Egipto y el apoyo que brinda para arribar a escenarios de paz en Libia, Sud\u00e1n o Gaza. Adem\u00e1s, afirm\u00f3 que Egipto posee 10 millones de refugiados en su territorio. Madbouly se\u00f1al\u00f3 que, a pesar de que Egipto transit\u00f3 2 \u201crevoluciones\u201d<a href=\"#_ftn3\" name=\"_ftnref3\"><sup>[3]<\/sup><\/a> recientemente, han transformado la inestabilidad y la inseguridad que caracteriz\u00f3 esos momentos y han conseguido bajar a la mitad el desempleo y mejorar la infraestructura y los servicios sociales y econ\u00f3micos. Caracterizado como el mentor de los mega proyectos arquitect\u00f3nicos, de infraestructura y de servicios sociales del Egipto actual, Madbouly se\u00f1al\u00f3 que la Nueva Capital Administrativa es un reflejo de que los egipcios contin\u00faan siendo \u201cgrandes constructores\u201d, vinculando estas iniciativas con el Egipto milenario. Mencionando escenarios conflictivos globales, afirm\u00f3 que el camino elegido por Egipto es el \u201cconstruir y desarrollar\u201d y no destruir.<\/p>\n<p>Por su parte, el canciller, <strong>Dr. Badr Abdelatty<\/strong>, comenz\u00f3 su alocuci\u00f3n indicando que nunca antes la Rep\u00fablica \u00c1rabe de Egipto estuvo rodeada de tantos escenarios cercanos que requieren atenci\u00f3n o que, por su nivel de conflictividad, constituyen desaf\u00edos o amenazas a su seguridad (nombrando a Yemen, Libia, Siria, Sud\u00e1n y Gaza). Adem\u00e1s, esto se da en un contexto global caracterizado por una alta fragmentaci\u00f3n y polarizaci\u00f3n en el cual las naciones m\u00e1s influyentes ejercen un doble est\u00e1ndar. Esta tendencia, por ejemplo, lleva a los pa\u00edses a no condenar la ocupaci\u00f3n israel\u00ed en los territorios palestinos, en los cuales, afirm\u00f3, se est\u00e1 llevando a cabo una violaci\u00f3n al Derecho Internacional Humanitario alarmante. Esta situaci\u00f3n, se\u00f1al\u00f3, s\u00f3lo favorece las condiciones para el fundamentalismo y no constituye verdadera soluci\u00f3n a este conflicto, el cual ser\u00e1 aplacado solo a trav\u00e9s del reconocimiento del derecho palestino a permanecer en su tierra.<\/p>\n<p>Ahora bien, frente a este diagn\u00f3stico y escenario internacional, Abdelatty afirma que la \u201csalida\u201d egipcia es la \u201cconsolidaci\u00f3n del sur global\u201d y la \u201csolidaridad como respuesta\u201d. As\u00ed, en sus palabras, \u201cla soluci\u00f3n es levantarse en nombre de la Carta de las Naciones Unidas y la ley internacional\u201d y defender las instancias multilaterales como la \u201c\u00fanica v\u00eda de protecci\u00f3n\u201d para los pa\u00edses del Tercer Mundo. Mencionando al G77, al MPNA y a los grupos asi\u00e1ticos y africanos en general, agreg\u00f3 referencias al G20 y a los BRICS como ejemplos de un \u201cimpulso democratizador\u201d. Este mismo impulso debiera ser, para \u00e9l, el que transforme espacios como el Consejo de Seguridad de la ONU, por ejemplo, revisando la cuesti\u00f3n del veto u otorg\u00e1ndole un asiento permanente a \u00c1frica. Sumado a esto, Abdelatty no solo hizo un llamado a transformar la ONU, tambi\u00e9n se refiri\u00f3 a la \u201carquitectura financiera internacional\u201d expresando que el Banco Mundial (BM) y Fondo Monetario Internacional (FMI) \u201cno representan al sur global, no son democr\u00e1ticos y no son sostenibles\u201d.<\/p>\n<ul>\n<li><strong>Senado egipcio<\/strong><\/li>\n<\/ul>\n<p>Esta C\u00e1mara Alta del Parlamento bicameral de Egipto fue restablecida en el a\u00f1o 2020, luego de las enmiendas realizadas a la Constituci\u00f3n Nacional. A diferencia de la C\u00e1mara Baja, el Senado es un \u00f3rgano consultivo que revisa y hace recomendaciones sobre legislaci\u00f3n, enmiendas constitucionales, planes nacionales y tratados internacionales. Aunque t\u00e9cnicamente el poder legislativo reside en la C\u00e1mara de Representantes, el Senado desempe\u00f1a un papel clave en la vida pol\u00edtica egipcia. As\u00ed fue resaltado en el marco de la beca, transmitiendo \u201cel apoyo a la gobernanza democr\u00e1tica y el di\u00e1logo pol\u00edtico\u201d que esta instituci\u00f3n realiza. Adem\u00e1s, se reconoce en este \u00f3rgano pol\u00edtico \u201cun legado de m\u00e1s de dos siglos\u201d, hall\u00e1ndose sus or\u00edgenes en las experiencias parlamentarias que destacan a Egipto como pa\u00eds precursor en este sentido, tanto en el continente africano como en la regi\u00f3n de Medio Oriente (el \u00abConsejo Superior\u00bb fundado por Mohamed Ali en 1824; la C\u00e1mara de Representantes, fundada durante el gobierno del jedive Ismail; la Asamblea Legislativa de principios de siglo XX; entre otras experiencias) (Nasser, 2025).<\/p>\n<ul>\n<li><strong>Base Naval de Alejandr\u00eda<\/strong><\/li>\n<\/ul>\n<p>Cabe destacar que, en dicha visita, los becarios visitaron el ENS Gamal Abdel Nasser, un buque de asalto anfibio clase Mistral de la Armada egipcia. Adquirido por Egipto en el a\u00f1o 2016, este buque fue construido por Francia y originalmente ten\u00eda como destino Rusia. Tiene una gran capacidad de transporte de helic\u00f3pteros, tropas y veh\u00edculos, y est\u00e1 equipado para misiones de combate, humanitarias y de mando (Precidency, 2017).<\/p>\n<ul>\n<li><strong>Academia de Polic\u00eda<\/strong><\/li>\n<\/ul>\n<p>Sobre esta actividad, consideramos dable destacar el rol asignado a Egipto como formador de oficiales de polic\u00eda de otros pa\u00edses, a quienes se les otorga la posibilidad de cursar posgrados en esta Academia. Adem\u00e1s, las actividades de cooperaci\u00f3n t\u00e9cnica que se realizan con pa\u00edses de todos los continentes, el intercambio con universidades, los profesores extranjeros invitados, y la formaci\u00f3n de especialistas con altos est\u00e1ndares en las materias requeridas por el Ministerio del Interior. Finalmente, destacamos la menci\u00f3n a que esta formaci\u00f3n se realiza en consonancia con la Estrategia Nacional de Derechos Humanos, lanzada por Egipto en enero de 2021<a href=\"#_ftn4\" name=\"_ftnref4\"><sup>[4]<\/sup><\/a>.<\/p>\n<ul>\n<li><strong>Centro de Correcci\u00f3n y Rehabilitaci\u00f3n en la ciudad 10 de Ramad\u00e1n<\/strong><\/li>\n<\/ul>\n<p>Establecidos por el Ministerio de Interior egipcio, estos Centros de Correcci\u00f3n y Rehabilitaci\u00f3n transforman el sistema y la cosmovisi\u00f3n a trav\u00e9s de las cuales el pa\u00eds abordaba la cuesti\u00f3n de las personas privadas de su libertad. En el caso del Centro visitado en el marco de la beca, los becarios fueron conducidos a observar las salas de dibujo, m\u00fasica y lectura, la guarder\u00eda para los hijos de las reclusas, el centro m\u00e9dico (el quir\u00f3fano, los consultorios y las salas de internaci\u00f3n), la cocina, las f\u00e1bricas textiles, la mezquita y la capilla cristiana, adem\u00e1s de observar desde lejos las canchas deportivas y los campos donde se realizan las actividades agropecuarias. En la p\u00e1gina web de la beca se expresa que esta iniciativa \u201crefleja el compromiso de Egipto con la implementaci\u00f3n de las normas internacionales de Derechos Humanos proporcionando alimentos saludables, rehabilitando a los reclusos mediante programas productivos, educativos y m\u00e9dicos, y ofreciendo atenci\u00f3n psicol\u00f3gica y social\u201d. As\u00ed, se afirma que esto \u201cno es meramente una instituci\u00f3n punitiva; es un modelo de civilizaci\u00f3n que reformula el concepto de las c\u00e1rceles en Egipto\u201d (Nasser, 2025).<\/p>\n<ul>\n<li><strong>Nuevo Canal de Suez<\/strong><\/li>\n<\/ul>\n<p>La jornada en Ismailia incluy\u00f3 navegar por dicho Canal, pudiendo observar la ampliaci\u00f3n que constituy\u00f3 la obra del \u201cNuevo Canal de Suez\u201d ampliando la cantidad de kil\u00f3metros con doble v\u00eda en el Nilo y sus afluentes. Adem\u00e1s, se realiz\u00f3 una visita a la Academia Mar\u00edtima de Formaci\u00f3n y Simulaci\u00f3n del Canal de Suez y al t\u00fanel construido recientemente que conecta Asia con \u00c1frica (New Suez Canal, 2025).<\/p>\n<ul>\n<li><strong>Instituto de Ciencias de la Inteligencia y Estudios de Seguridad<\/strong> (ISSSI por sus siglas en ingl\u00e9s)<\/li>\n<\/ul>\n<p>En su visita, los becarios de la quinta cohorte presenciaron una exposici\u00f3n del director a cargo de este Instituto, la cual comenz\u00f3 con una reflexi\u00f3n sobre los motivos por los cuales esta visita hab\u00eda sido incluida en el programa de la beca. En alusi\u00f3n a las tareas que lleva a cabo este Instituto, el director se\u00f1al\u00f3 que sus informes se realizan a pedido de Presidencia y de otras autoridades del Ej\u00e9rcito. De all\u00ed deriv\u00f3 en cu\u00e1l es la \u201cperspectiva egipcia\u201d y la metodolog\u00eda de trabajo, enfatizando en la idea de seguridad nacional. Adem\u00e1s, se\u00f1al\u00f3 cu\u00e1l es la conexi\u00f3n entre el Ej\u00e9rcito y la sociedad civil -indicando que este es un v\u00ednculo cotidiano y estrecho ya que en cada familia egipcia hay un ex o actual integrante de estas fuerzas- y entre el Ej\u00e9rcito y la gesti\u00f3n p\u00fablica en general.<\/p>\n<p>Finalmente, se refiri\u00f3 a la diversidad de los desaf\u00edos actuales, describiendo algunos de ellos como: el calentamiento global, la IA, el terrorismo, el crimen organizado, la inmigraci\u00f3n ilegal, los cyber ataques y los Estados fallidos. Con respecto al terrorismo, se describieron programas e iniciativas para la \u201creinserci\u00f3n\u201d de familias afectadas o vinculadas con este, indicando que la mejor manera de combatirlo es mejorando los servicios p\u00fablicos y las oportunidades para los habitantes. Cabe se\u00f1alar que esta fue una actividad colmada de medidas de seguridad y una conferencia muy enriquecedora y de tono provocativo gracias a las iron\u00edas sobre las tareas de inteligencia y an\u00e9cdotas personales del propio director.<\/p>\n<p>Adem\u00e1s, se visitaron los siguientes sitios oficiales, los cuales ser\u00e1n desarrollados en trabajos subsiguientes: la Academia Militar, el Museo de la Fuerza A\u00e9rea, el Instituto Al-Azhar (Observatorio de lucha contra el extremismo y encuentro con el Gran Sheikh) y la Sede de la Liga de los Estados \u00c1rabes (organizaci\u00f3n que este a\u00f1o cumple 80 a\u00f1os).<\/p>\n<h2>4- Conclusiones preliminares: el rol de Egipto en el Sur Global<\/h2>\n<p>En este apartado se intentar\u00e1 esbozar un an\u00e1lisis preliminar para comenzar a responder a la pregunta sobre c\u00f3mo aporta la beca Nasser a la proyecci\u00f3n regional e internacional de la Rep\u00fablica \u00c1rabe de Egipto. Sin pretender una respuesta acabada o exhaustiva, consideramos que las pr\u00e1cticas discursivas y visuales que caracterizan a esta iniciativa nos permiten observar la apuesta que el pa\u00eds del Nilo realiza para erigirse como referente en \u00c1frica y en el Sur Global, construyendo un liderazgo en base a su pertenencia geogr\u00e1fica y a su trayectoria hist\u00f3rica. En la medida en que esta estrategia es exitosa, cabe preguntarse \u00bfde qu\u00e9 manera lo realiza?<\/p>\n<p>Consideramos que es posible mencionar dos relatos o im\u00e1genes generales que se dirigen en este sentido: primero, que las relaciones exteriores y el contexto internacional es sustancial para Egipto y que existe una estrategia diplom\u00e1tica multilateral clara y sostenida en el tiempo; segundo, que Egipto es un pa\u00eds que, desde los levantamientos \u00e1rabes hasta hoy, se ha transformado considerable y positivamente.<\/p>\n<p>As\u00ed, con respecto a la primera observaci\u00f3n, y aunque el lema de la 5ta cohorte se centra en Naciones Unidas, la valoraci\u00f3n de la pertenencia a espacios como la Uni\u00f3n Africana, la Liga \u00c1rabe, el MPNA (en todas sus instancias), el G77, los BRICS, entre otros, es constante y forma parte de una propuesta egipcia de potenciar los espacios de representaci\u00f3n de los pa\u00edses del Tercer Mundo, considerados aquellos en donde se observan mayores posibilidades de unificar posiciones. A su vez, en el plano exterior, esta visi\u00f3n podr\u00eda vincularse con la importancia asignada al rol de <em>peacebuilding <\/em>y <em>peacekeeping <\/em>que Egipto ha desarrollado. As\u00ed lo demuestra la menci\u00f3n reiterada, en sucesivas oportunidades, de que el pa\u00eds del Nilo fue uno de los primeros en contribuir con las operaciones de paz de la ONU: esta primera participaci\u00f3n se concret\u00f3 en el Congo en el a\u00f1o 1960.<\/p>\n<p>Con respecto a la segunda observaci\u00f3n, referida a las transformaciones acaecidas en Egipto, es imposible no observar los megaproyectos inmobiliarios y de infraestructura (como la Nueva Capital Administrativa, el Nuevo Canal de Suez), las campa\u00f1as como Vida Digna<a href=\"#_ftn5\" name=\"_ftnref5\"><sup>[5]<\/sup><\/a> y Di\u00e1logo Nacional<a href=\"#_ftn6\" name=\"_ftnref6\"><sup>[6]<\/sup><\/a> o los programas como el Programa Nacional de Vivienda Social<a href=\"#_ftn7\" name=\"_ftnref7\"><sup>[7]<\/sup><\/a>, y no pensar en el calificativo \u201cfara\u00f3nico\u201d. A\u00fan m\u00e1s, considerando las p\u00e9rdidas econ\u00f3micas que Egipto viene sufriendo por la afectaci\u00f3n del tr\u00e1nsito en el Canal de Suez (Infobae, 21\/03\/2025) y que este pa\u00eds, junto con la Rep\u00fablica Argentina, son los dos con mayor endeudamiento con el FMI. Vinculado a esto, y al centralismo imperante, el rol y la inversi\u00f3n realizada en las fuerzas armadas y de seguridad, reflejan la importancia que el gobierno les otorga en nombre de la estabilidad del pa\u00eds y de su seguridad nacional, a\u00fan m\u00e1s en una regi\u00f3n plagada de desaf\u00edos.<\/p>\n<p>Sumado a esto, nuevamente Egipto apela a una trayectoria hist\u00f3rica que se destaca en \u00c1frica y Medio Oriente (Civallero, 2021). As\u00ed, a pesar de la indudable presencia del relato heroico de los acontecimientos del siglo XX, sobre todo el nasserismo, muchas de las instituciones visitadas reiteran como un valor su existencia previa y su trayectoria de m\u00e1s de un siglo. No solo el Senado, como ya se se\u00f1al\u00f3, tambi\u00e9n otras como el Ej\u00e9rcito o la Armada; incluso, en el caso de esta \u00faltima, citando como ejemplo que cuando Nasser lleg\u00f3 al poder la Armada cambi\u00f3 de nombre, pero continu\u00f3 con las mismas operaciones militares. Esto es importante si recordamos el rol que las Fuerzas Armadas poseen en Egipto, algo se\u00f1alado por el director del ISSSI.<\/p>\n<p>A su vez, cabe marcar tambi\u00e9n el fuerte mensaje referido al nuevo rol de los Derechos Humanos en Egipto<a href=\"#_ftn8\" name=\"_ftnref8\"><sup>[8]<\/sup><\/a>, algo que era demandado por la comunidad internacional y denunciado por organizaciones vinculadas a la tem\u00e1tica, sobre todo luego de los levantamientos de 2011. La alusi\u00f3n a la Estrategia Nacional de Derechos Humanos<a href=\"#_ftn9\" name=\"_ftnref9\"><sup>[9]<\/sup><\/a> en diversas conferencias y visitas da cuenta de esto. M\u00e1s a\u00fan, la visita al Centro de Rehabilitaci\u00f3n, en tanto nuevo modelo de c\u00e1rceles en el pa\u00eds, resulta llamativa en un programa dirigido a la diplomacia juvenil y refuerza las primeras conclusiones de este apartado referidas a la proyecci\u00f3n regional e internacional que la beca promueve.<\/p>\n<p>Finalmente, cabe hacer una menci\u00f3n al rol de la juventud, el universo al cual est\u00e1 destinada la beca. En las palabras de Hassan Ghazaly<a href=\"#_ftn10\" name=\"_ftnref10\"><sup>[10]<\/sup><\/a>, la beca Nasser contin\u00faa un camino iniciado por Egipto hace muchos a\u00f1os, de apoyo y transferencia de capacidades a los pa\u00edses de \u00c1frica y Medio Oriente a la par que aboga por un tipo de uni\u00f3n entre sus naciones. Por tal motivo, el nombre de la beca hace referencia al l\u00edder del panarabismo, y se ofrece como una plataforma de aprendizaje de aptitudes de liderazgo y como un entorno de <em>networking <\/em>entre personas de todos los rincones del globo. Consultado para este trabajo sobre el interrogante principal de este escrito, Ghazaly expres\u00f3 que la beca busca transferir a la juventud ciertos conocimientos y capacidades basados en los ideales y la experiencia egipcia. Esto robustece la proyecci\u00f3n de Egipto a la par que reaviva los ideales que vincularon a los pa\u00edses del Tercer Mundo contra el colonialismo y a favor de sus intereses comunes.<\/p>\n<h2>4- Bibliograf\u00eda<\/h2>\n<p>Civallero, C. (2021). Nacionalismo \u00e1rabe, tercermundismo y no alineamiento: construcciones identitarias y relaciones internacionales en el Egipto de Abdel Nasser. Tesis de maestr\u00eda. UNTREF.<\/p>\n<p>Infobae (21\/03\/2025). \u201cEl tr\u00e1fico en el Canal de Suez sigue en crisis tras la reanudaci\u00f3n de los ataques\u201d. Disponible en. <u><a href=\"https:\/\/www.infobae.com\/movant\/2025\/03\/21\/el-trafico-en-el-canal-de-suez-sigue-en-crisis-tras-la-reanudacion-de-los-ataques-\">https:\/\/www.infobae.com\/movant\/2025\/03\/21\/el-trafico-en-el-canal-de-suez-sigue-en-crisis-tras-la-reanudacion-de-los-ataques-<\/a><\/u><\/p>\n<p>Ministerio de Juventud y Deportes (2025). \u201cUnder the Patronage of President Abdel Fattah El-Sisi: Prime Minister Welcomes 150 Youth Leaders from 80 Countries during the Fifth Edition of the Nasser for International Leadership\u201d. Disponible en: <u><a href=\"https:\/\/www.emys.gov.eg\/news_en\/17410\/Under-the-Patronage-of-President-Abdel-Fattah-El-Sisi-Prime-Minister-Welcomes-150-Youth-Leaders-from-80-Countries-during-the-Fifth-Edition-of-the-Nasser-Fellowship-for-International-Leadership\">https:\/\/www.emys.gov.eg\/news_en\/17410\/Under-the-Patronage-of-President-Abdel-Fattah-El-Sisi-Prime-Minister-Welcomes-150-Youth-Leaders-from-80-Countries-during-the-Fifth-Edition-of-the-Nasser-Fellowship-for-International-Leadership<\/a><\/u><\/p>\n<p>Nasser Forum (2025). \u201cNasser Fellowship for International Leadership, Batch 5\u201d. Disponible en: <u><a href=\"https:\/\/nasserforum.com\/#collapse-5772\">https:\/\/nasserforum.com\/#collapse-5772<\/a><\/u><\/p>\n<p>Nasser Youth Movement (2025). \u201cIn Celebration of the High Dam\u2019s Anniversary&#8230; Nasser Fellowship for International Leadership Receives Patronage from President El-Sisi\u201d. Disponible en: <u><a href=\"https:\/\/www.nasseryouthmovement.net\/Nasser-Fellowship-Egypt\">https:\/\/www.nasseryouthmovement.net\/Nasser-Fellowship-Egypt<\/a><\/u><\/p>\n<p>________________________. \u201cThe Egyptian Senate\u201d. Disponible en: <u><a href=\"https:\/\/nasseryouthmovement.net\/The-Egyptian-Senate\">https:\/\/nasseryouthmovement.net\/The-Egyptian-Senate<\/a><\/u><\/p>\n<p>________________________. \u201cParticipaci\u00f3n sin precedentes de Am\u00e9rica Latina en la quinta edici\u00f3n de la Beca Nasser para el Liderazgo Internacional\u201d. Disponible en: <u><a href=\"https:\/\/www.nasseryouthmovement.net\/es\/Foro-Internacional-Nasser-America-Latina-Internacional\">https:\/\/www.nasseryouthmovement.net\/es\/Foro-Internacional-Nasser-America-Latina-Internacional<\/a><\/u><\/p>\n<p>________________________. \u201cForo-Internacional-Nasser-America-Latina-Internacional\u201d. Disponible en:<\/p>\n<p><u><a href=\"https:\/\/www.nasseryouthmovement.net\/Nasser-Fellowship-Egypt\">https:\/\/www.nasseryouthmovement.net\/Nasser-Fellowship-Egypt<\/a><\/u><\/p>\n<p>________________________. Rehabilitation Centers in 10th of Ramadan: An Integrated Egyptian Model for Human Justice and Modern Rehabilitation\u201d. Disponible en: <u><a href=\"https:\/\/nasseryouthmovement.net\/Rehabilitation-Center\">https:\/\/nasseryouthmovement.net\/Rehabilitation-Center<\/a><\/u><\/p>\n<p>New Suez Canal (2025). \u201cNew Suez Canal\u201d. Disponible en: <u><a href=\"https:\/\/www.suezcanal.gov.eg\/English\/About\/SuezCanal\/Pages\/NewSuezCanal.aspx\">https:\/\/www.suezcanal.gov.eg\/English\/About\/SuezCanal\/Pages\/NewSuezCanal.aspx<\/a><\/u><\/p>\n<p>Presidency (2017). \u201cENS Gamal Abdel Nasser (Mistral Class)\u201d. Disponible en: <u><a href=\"https:\/\/www.presidency.eg\/en\/%D8%A7%D9%84%D9%85%D8%B4%D8%A7%D8%B1%D9%8A%D8%B9-%D8%A7%D9%84%D9%82%D9%88%D9%85%D9%8A%D8%A9\/%D8%AD%D8%A7%D9%85%D9%84%D8%A9-%D8%A7%D9%84%D8%B7%D8%A7%D8%A6%D8%B1%D8%A7%D8%AA-%D9%85%D9%8A%D8%B3%D8%AA%D8%B1%D8%A7%D9%84-%D8%AC%D9%85%D8%A7%D9%84-%D8%B9%D8%A8%D8%AF-%D8%A7%D9%84%D9%86%D8%A7%D8%B5%D8%B1\/\">https:\/\/www.presidency.eg\/en\/%D8%A7%D9%84%D9%85%D8%B4%D8%A7%D8%B1%D9%8A%D8%B9-%D8%A7%D9%84%D9%82%D9%88%D9%85%D9%8A%D8%A9\/%D8%AD%D8%A7%D9%85%D9%84%D8%A9-%D8%A7%D9%84%D8%B7%D8%A7%D8%A6%D8%B1%D8%A7%D8%AA-%D9%85%D9%8A%D8%B3%D8%AA%D8%B1%D8%A7%D9%84-%D8%AC%D9%85%D8%A7%D9%84-%D8%B9%D8%A8%D8%AF-%D8%A7%D9%84%D9%86%D8%A7%D8%B5%D8%B1\/<\/a><\/u><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><sup>[1]<\/sup><\/a> Miembro del DEMO-IRI-UNLP. Egresada de la 5ta cohorte de la Beca Nasser para el liderazgo internacional. Correo electr\u00f3nico: <u><a href=\"mailto:ceciliaciva@gmail.com\">ceciliaciva@gmail.com<\/a><\/u><\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\"><sup>[2]<\/sup><\/a> La Organizaci\u00f3n de J\u00f3venes del Movimiento de los Pa\u00edses No Alineados (NAM) se estableci\u00f3 en la ciudad de Shusha el viernes 29 de julio de 2022. As\u00ed, la Declaraci\u00f3n de Shusha, Azerbaiy\u00e1n, dispuso el establecimiento de la Organizaci\u00f3n de la Juventud del Movimiento de los Pa\u00edses No Alineados. Disponible en: <u><a href=\"https:\/\/azertag.az\/es\/xeber\/la_cumbre_de_la_juventud_del_movimiento_de_pases_no_alineados_se_convierte_en_una_organizacion_juvenil-2233940\">https:\/\/azertag.az\/es\/xeber\/la_cumbre_de_la_juventud_del_movimiento_de_pases_no_alineados_se_convierte_en_una_organizacion_juvenil-2233940<\/a><\/u><\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\"><sup>[3]<\/sup><\/a> Aqu\u00ed el Primer Ministro se refiere a los acontecimientos acaecidos en el a\u00f1o 2011 y 2013 en Egipto, a ra\u00edz de la llamada \u201cPrimavera \u00c1rabe\u201d, y que condujeron a la ca\u00edda de Mubarak, la victoria de Morsi y, luego, la llegada al poder ed Abdelfatah El-Sisi.<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\"><sup>[4]<\/sup><\/a> La Estrategia Nacional de Derechos Humanos fue lanzada por Egipto en enero de 2021 para el quinquenio 2021-2026. Disponible en: <u><a href=\"https:\/\/nwm.unescwa.org\/resources\/216\">https:\/\/nwm.unescwa.org\/resources\/216<\/a><\/u><\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\"><sup>[5]<\/sup><\/a> El programa vida Digna est\u00e1 dirigido al desarrollo de comunidades locales y rurales, brindando oportunidades de empleo y mejora de la infraestructura de comunidades en el centro y sur de Egipto. Disponible en: <a href=\"https:\/\/www.sis.gov.eg\/Story\/44296\/Una-iniciativa-de-vida-digna?lang=es\">https:\/\/www.sis.gov.eg\/Story\/44296\/Una-iniciativa-de-vida-digna?lang=es<\/a><\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\"><sup>[6]<\/sup><\/a> La campa\u00f1a Di\u00e1logo Nacional se propone mejorar la situaci\u00f3n social y pol\u00edtica en Egipto, convocando a personalidades partidarias, acad\u00e9micas, de la sociedad civil, entre otras, para discutir los mayores problemas en estos campos. \u201cEgipto inicia el Di\u00e1logo Nacional para mejorar derechos y salir de la crisis\u201d, Swiss, 03\/05\/2023:<u><a href=\"https:\/\/www.swissinfo.ch\/spa\/egipto-inicia-el-di%C3%A1logo-nacional-para-mejorar-derechos-y-salir-de-la-crisis\/48483928\">https:\/\/www.swissinfo.ch\/spa\/egipto-inicia-el-di%C3%A1logo-nacional-para-mejorar-derechos-y-salir-de-la-crisis\/48483928<\/a><\/u><\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\"><sup>[7]<\/sup><\/a> El Programa Nacional de Vivienda Social tiene como objetivo proporcionar viviendas a 1 mill\u00f3n de hogares de bajos ingresos y, adem\u00e1s, realizar esto a trav\u00e9s de construcciones ecol\u00f3gicas. BM, 22\/09\/2022, disponible en: <u><a href=\"https:\/\/www.worldbank.org\/en\/news\/feature\/2022\/09\/21\/egypt-s-green-social-housing-supports-climate-efforts-and-improves-quality-of-life-for-citizens\">https:\/\/www.worldbank.org\/en\/news\/feature\/2022\/09\/21\/egypt-s-green-social-housing-supports-climate-efforts-and-improves-quality-of-life-for-citizens<\/a><\/u><\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\"><sup>[8]<\/sup><\/a> En enero del corriente, durante el 59\u00b0 per\u00edodo de sesiones del Consejo de Derechos Humanos de la ONU, se present\u00f3 el informe del Grupo de Trabajo sobre el Examen Peri\u00f3dico Universal (EPU) en Egipto. El Grupo de Trabajo del EPU est\u00e1 integrado por los 47 Estados miembros del Consejo de Derechos Humanos y Egipto fue uno de los 14 Estados examinados durante este per\u00edodo de sesiones. El informe destaca los avances concretados en esta materia y est\u00e1 disponible en: <u><a href=\"https:\/\/docs.un.org\/es\/A\/HRC\/59\/16\">https:\/\/docs.un.org\/es\/A\/HRC\/59\/16<\/a><\/u>.<\/p>\n<p><a href=\"#_ftnref9\" name=\"_ftn9\"><sup>[9]<\/sup><\/a> Estrategia Nacional de Derechos Humanos. Disponible en: <u><a href=\"https:\/\/nwm.unescwa.org\/sites\/default\/files\/2023-04\/national-human-rights-strategy-en.pdf\">https:\/\/nwm.unescwa.org\/sites\/default\/files\/2023-04\/national-human-rights-strategy-en.pdf<\/a><\/u><\/p>\n<p><a href=\"#_ftnref10\" name=\"_ftn10\"><sup>[10]<\/sup><\/a> Entrevista realizada por nosotros al antrop\u00f3logo Hassan Ghazaly, fundador del Foro Internacional Nasser y promotor de la Beca Nasser para el Liderazgo Internacional. Julio de 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Mar\u00eda Cecilia Civallero<\/p>\n","protected":false},"author":5,"featured_media":42708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"anuario","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[1768],"class_list":["post-41564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-a2025artdemo","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new-600x200.png",600,200,true],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new-375x200.png",375,200,true],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new-720x200.png",720,200,true],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2025\/09\/feat-anuario-2025-new.png",750,200,false]},"uagb_author_info":{"display_name":"Juana Alvarez Eiras","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/juana-alvarez-eiras\/"},"uagb_comment_info":0,"uagb_excerpt":"por Mar\u00eda Cecilia Civallero","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/41564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=41564"}],"version-history":[{"count":4,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/41564\/revisions"}],"predecessor-version":[{"id":42980,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/41564\/revisions\/42980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/42708"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=41564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=41564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=41564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}