{"id":44659,"date":"2026-03-13T10:43:01","date_gmt":"2026-03-13T13:43:01","guid":{"rendered":"https:\/\/www.iri.edu.ar\/?p=44659"},"modified":"2026-03-13T11:17:45","modified_gmt":"2026-03-13T14:17:45","slug":"la-conferencia-de-munich-en-el-marco-de-una-nueva-politica-internacional","status":"publish","type":"post","link":"https:\/\/www.iri.edu.ar\/index.php\/2026\/03\/13\/la-conferencia-de-munich-en-el-marco-de-una-nueva-politica-internacional\/","title":{"rendered":"La Conferencia de M\u00fanich en el marco de una nueva pol\u00edtica Internacional"},"content":{"rendered":"<h2><a name=\"_Toc224044048\"><\/a>*\u00a0 La Conferencia de M\u00fanich en el marco de una nueva pol\u00edtica Internacional<\/h2>\n<h3><a name=\"_Toc224044049\"><\/a>Julio Ram\u00f3n Lascano y Vedia<a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]<\/strong><\/a><\/h3>\n<p>La nueva pol\u00edtica internacional afincada en el realismo pol\u00edtico puro, se desarrolla en un marco de competitividad y beligerancia mundial creciente y sin contar con un multilateralismo que contenga los rumbos de la geopol\u00edtica mundial y las decisiones hegem\u00f3nicas del contempor\u00e1neo mundo: Ello no ha detenido la realizaci\u00f3n de la Conferencia de seguridad de M\u00fanich Alemania se realiza desde 1962.<\/p>\n<p>Esta Conferencia en 2026 se expuso p\u00fablicamente a trav\u00e9s de mensajes y posiciones de l\u00edderes y gobernantes de occidente que han hecho exageradas declaraciones. Los Estados<\/p>\n<p>Unidos y Europa se reunieron en M\u00fanich en un intento por recrear fortaleza en la alianza atl\u00e1ntica de posguerra. Aunque la beligerancia y confrontaci\u00f3n geopol\u00edtica mundial acontece m\u00e1s all\u00e1 de ese marco, y requiere de pensamientos, ideas y propuestas para nuevas problem\u00e1ticas de pol\u00edtica internacional, de seguridad y peligros nucleares latentes en el planeta.<\/p>\n<p>En un mundo cuyo contexto internacional est\u00e1 marcado por decisiones hegem\u00f3nicas de Estados Unidos y China, durante la misma conferencia, y con el objeto de hacer comprender los posicionamientos de la nueva pol\u00edtica internacional, se\u00f1al\u00f3 el Secretario de Estado de Estados Unidos Marco Rubio, en una clase de \u201crealismo puro\u201d, que \u201cel orden global debe subordinarse a los intereses nacionales\u201d. Rubio reivindica la historia compartida entre Estados Unidos y Europa, y adem\u00e1s defendi\u00f3 avanzar en una reforma del sistema internacional, aclarando que no se hace necesario desmantelar todo el sistema multilateral. Por ello para Estados Unidos se hace necesario pensar en una nueva pol\u00edtica internacional realista y en el relacionamiento con Europa pensar en una \u201calianza revitalizada\u201d. Esto seguramente incluir\u00e1 el papel de Rusia en la posguerra con Ucrania, donde Estados Unidos parece esperar pacientemente resultados diplom\u00e1ticos finales que permitan incluir esta tem\u00e1tica geopol\u00edtica, pol\u00edtica y econ\u00f3mica en la agenda de cuestiones pendientes a reformar en el relacionamiento con Europa y la nueva alianza atl\u00e1ntica<\/p>\n<p>A pesar de las presiones de Donald Trump sobre Groenlandia y su ret\u00f3rica confrontativa, que han dejado dudas profundas en los gobernantes y l\u00edderes de Europa , en un an\u00e1lisis rigurosos se puede aseverar que ello ha correspondido a la nueva pol\u00edtica exterior del hegem\u00f3n norteamericano que se apoya en concepciones y decisiones que apuntan a la transformaci\u00f3n y reforma del sistema internacional multilateral, la reforma del debilitado esquema de las Naciones Unidas, y la modificaci\u00f3n del complejo entramado pol\u00edtico jur\u00eddico y econ\u00f3mico de la Uni\u00f3n Europea, que seg\u00fan la visi\u00f3n realista vigente ha dejado a Europa m\u00e1s lejos de un sistema de relacionamiento pol\u00edtico diplom\u00e1tico y comercial \u00fatil, y en extrema cercan\u00eda con las inversiones y negociaciones que encara de manera paciente y creciente en todo el mundo la Rep\u00fablica Popular China.<\/p>\n<p>Los europeos se expresan en M\u00fanich de diversas maneras, y algunos, buscando soluciones al desaf\u00edo de rearmarse como una comunidad pol\u00edtica occidental l\u00f3gica y \u00fatil a una alianza atl\u00e1ntica, y otros buscando un mayor independentismo de la uni\u00f3n europea que lo haga aut\u00f3noma de las decisiones de Estados Unidos y de China a la vez. Esta \u00faltima posici\u00f3n aparece muy ingenua en el esquema geopol\u00edtico contempor\u00e1neo pero los pa\u00edses escandinavos y otros miembros de la Uni\u00f3n Europea as\u00ed parecen pretenderlo. Por Alemania Friedrich Merz se inclin\u00f3 claramente de buscar una mayor orden para enfrentar la actual crisis europea y mundial, por Francia Emmanuel Macron pidi\u00f3 una Europa \u201cgeopol\u00edtica\u201d con disuasi\u00f3n nuclear reforzada; mientras por Gran Breta\u00f1a Keir Starmer insisti\u00f3 en que los Estados Unidos es el aliado indispensable para la subsistencia misma de Europa y Occidente. Giorgia Meloni defiende el occidente desde el Imperio de Roma hasta la alianza con Estados Unidos contempor\u00e1nea. M\u00e1s all\u00e1 de estas posiciones expresadas durante la conferencia, surge a\u00fan un estado confusional reinante en la Uni\u00f3n Europea, a partir del abandono de la misma como interlocutor de los Estados Unidos en el planeta y la asunci\u00f3n de m\u00faltiples negocios diplom\u00e1ticos que la acercaron a China y la alejaron de Rusia; ingresando en m\u00faltiples interpretaciones de poca claridad sobre la voluntad pol\u00edtica de Europa en el nuevo esquema de la pol\u00edtica internacional contempor\u00e1nea.<\/p>\n<p>L\u00f3gicamente en la Conferencia de M\u00fanich, el escepticismo ha dominado los escenarios y discursos. Ello, aunque Washington ratific\u00f3 su paraguas nuclear en la Organizaci\u00f3n del Atl\u00e1ntico Norte OTAN, donde tienen un gran peso las negociaciones sobre Ucrania y Groenlandia. En la nueva pol\u00edtica internacional a la que asistimos con un marcado balance entre la geopol\u00edtica y las relaciones internacionales, de manera original, pero con absoluta l\u00f3gica aparece un protagonista de peso que parece comprender las necesidades de reformas del sistema que surgen de la existencia de esta nueva pol\u00edtica internacional sin reglas y en un mundo en guerras. Y que lo interpreta y se\u00f1ala as\u00ed en los foros diversos que participa, Se trata del candidato a Secretario General de las Naciones Unidas y actual Director de la Agencia de energ\u00eda at\u00f3mica de la ONU Dr. Rafael Grossi, diplom\u00e1tico argentino en funciones internacionales.<\/p>\n<h4>La cuesti\u00f3n energ\u00e9tica-nuclear en la conferencia de M\u00fanich<\/h4>\n<p>En el contexto de la nueva pol\u00edtica internacional sin reglas, esta conferencia de seguridad de M\u00fanich se desarrolla en un momento signado por la convergencia de crisis estrat\u00e9gicas, guerras abiertas, tensiones geopol\u00edticas sist\u00e9micas, transici\u00f3n energ\u00e9tica acelerada y creciente cuestionamiento de los reg\u00edmenes de control nuclear. En este marco, la dimensi\u00f3n energ\u00e9tica y nuclear adquiere una centralidad in\u00e9dita como factor cr\u00edtico de seguridad internacional.<\/p>\n<p>Desde el punto de vista de la seguridad y la defensa, las cuestiones de la energ\u00eda, la tecnolog\u00eda y los recursos estrat\u00e9gicos configuran el nuevo equilibrio de poder. La guerra en Ucrania, la inestabilidad en Medio Oriente y la rivalidad entre grandes potencias han demostrado que la infraestructura energ\u00e9tica es hoy tanto un activo econ\u00f3mico como un objetivo militar. Ataques a sistemas energ\u00e9ticos y las disputas por corredores de suministro y la vulnerabilidad de las centrales nucleares en zonas de conflicto han reposicionado la cuesti\u00f3n at\u00f3mica en el centro del debate estrat\u00e9gico.<\/p>\n<p>La voz de Rafael Grossi, director general del Organismo Internacional de Energ\u00eda At\u00f3mica (OIEA), se hace entonces relevante, pues se ha convertido en uno de los actores t\u00e9cnicos- pol\u00edticos m\u00e1s influyentes en la gobernanza nuclear. Grossi ha advertido en M\u00fanich que el sistema internacional de no proliferaci\u00f3n atraviesa un momento de fragilidad estructural. Si bien el r\u00e9gimen vigente sigue siendo un pilar de estabilidad, enfrenta cuestionamientos incluso de Estados hist\u00f3ricamente alineados con sus compromisos. Seg\u00fan su diagn\u00f3stico, la erosi\u00f3n de consensos refleja un mundo m\u00e1s competitivo, donde la disuasi\u00f3n vuelve a ganar terreno frente al desarme.<\/p>\n<p>El alto funcionario se\u00f1al\u00f3 que la l\u00f3gica de seguridad cooperativa posterior a la Guerra Fr\u00eda est\u00e1 siendo reemplazada por esquemas de autonom\u00eda estrat\u00e9gica regional, rearmamento y reconsideraci\u00f3n de capacidades nucleares. La visi\u00f3n del Director de la AIEA combina realismo estrat\u00e9gico con pragmatismo t\u00e9cnico; pues reconoce el derecho de los Estados al desarrollo nuclear con fines pac\u00edficos; pero insiste en la necesidad de verificaci\u00f3n robusta y transparencia para evitar desv\u00edos militares. Es un el delicado equilibrio a conseguir.\u00a0 El director de la AIEA afirma que el panorama nuclear iran\u00ed ha cambiado \u201cradicalmente\u201d tras la guerra de doce d\u00edas, lo que obliga a redise\u00f1ar cualquier acuerdo de control. Por ello los conflictos contempor\u00e1neos no solo generan riesgos de proliferaci\u00f3n, sino tambi\u00e9n de descontrol t\u00e9cnico, p\u00e9rdida de trazabilidad de materiales y vac\u00edos de supervisi\u00f3n internacional.<\/p>\n<p>Lo importante resulta en que la dimensi\u00f3n energ\u00e9tica del problema nuclear se manifiesta con claridad en los escenarios b\u00e9licos. En Europa oriental, los ataques a infraestructuras el\u00e9ctricas y los riesgos sobre centrales at\u00f3micas han elevado la preocupaci\u00f3n por accidentes radiol\u00f3gicos de escala transnacional. Autoridades ucranianas han advertido en M\u00fanich que los bombardeos contra redes energ\u00e9ticas incrementan los peligros para la seguridad nuclear de toda la regi\u00f3n. Se hace accidente la interdependencia entre energ\u00eda y seguridad: una central nuclear no es solo una planta de generaci\u00f3n, sino un nodo cr\u00edtico cuya afectaci\u00f3n puede desencadenar crisis humanitarias, ambientales y geopol\u00edticas.<\/p>\n<p>En el sistema internacional solo el organismo AIEA desempe\u00f1a un rol insustituible, al momento de hablar de las reformas del sistema internacional, y definir un punto de partida para modificar las decisiones hacia una geopol\u00edtica adecuada a la nueva pol\u00edtica internacional sin reglas pero en un mundo en guerra. As\u00ed el Director Rafael Grossi enfatiza precisamente esta paradoja contempor\u00e1nea: la humanidad necesita m\u00e1s energ\u00eda nuclear para descarbonizar, pero simult\u00e1neamente enfrenta mayores riesgos de proliferaci\u00f3n, sabotaje o uso militar. Gestionar esa tensi\u00f3n es el desaf\u00edo central de la gobernanza global.<\/p>\n<p>Esta posici\u00f3n manifestada en M\u00fanich es fundamental pues, est\u00e1 situada en la intersecci\u00f3n entre diplomacia, tecnolog\u00eda y seguridad; y expresa esa nueva complejidad de un mundo donde la estabilidad estrat\u00e9gica depender\u00e1 de la transici\u00f3n energ\u00e9tica y rivalidad geopol\u00edtica creciente.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Embajador de carrera (R). Profesor de Historia Argentina y de Pol\u00edtica Internacional de la Universidad Nacional de la Defensa UNDEF. Licenciatura de Defensa y Maestr\u00eda Defensa Nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Julio Ram\u00f3n Lascano y Vedia<\/p>\n","protected":false},"author":5,"featured_media":22934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"boseguridad","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[2000],"class_list":["post-44659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-boseguridad60art","entry","has-media"],"uagb_featured_image_src":{"full":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",750,200,false],"thumbnail":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT-150x150.png",150,150,true],"medium":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT-300x80.png",300,80,true],"medium_large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",750,200,false],"large":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",750,200,false],"1536x1536":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",750,200,false],"2048x2048":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",750,200,false],"ocean-thumb-m":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",600,160,false],"ocean-thumb-ml":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",750,200,false],"ocean-thumb-l":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",750,200,false],"sow-carousel-default":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT-272x182.png",272,182,true],"sow-blog-portfolio":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",375,100,false],"sow-blog-grid":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",720,192,false],"sow-blog-alternate":["https:\/\/www.iri.edu.ar\/wp-content\/uploads\/2022\/07\/boSeguridad-FEAT.png",750,200,false]},"uagb_author_info":{"display_name":"Juana Alvarez Eiras","author_link":"https:\/\/www.iri.edu.ar\/index.php\/author\/juana-alvarez-eiras\/"},"uagb_comment_info":0,"uagb_excerpt":"por Julio Ram\u00f3n Lascano y Vedia","_links":{"self":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/44659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=44659"}],"version-history":[{"count":1,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/44659\/revisions"}],"predecessor-version":[{"id":44660,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/44659\/revisions\/44660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/22934"}],"wp:attachment":[{"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=44659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=44659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iri.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=44659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}